{"id":22041,"date":"2012-12-12T19:05:22","date_gmt":"2012-12-12T23:05:22","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/un-cuerpo-alcalino-es-sinonimo-de-un-cuerpo-sano-cuatro-claves-para-combatir-la-acidez\/"},"modified":"2012-12-12T19:05:22","modified_gmt":"2012-12-12T23:05:22","slug":"un-cuerpo-alcalino-es-sinonimo-de-un-cuerpo-sano-cuatro-claves-para-combatir-la-acidez","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/un-cuerpo-alcalino-es-sinonimo-de-un-cuerpo-sano-cuatro-claves-para-combatir-la-acidez\/","title":{"rendered":"Un cuerpo alcalino es sin\u00f3nimo de un cuerpo sano: cuatro claves para combatir la acidez"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-22040\" style=\"float: left;\" alt=\"ALCALINO_BUENO_PA_LA_SALUD\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_ALCALINO_BUENO_PA_LA_SALUD.jpg\" width=\"620\" height=\"282\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_ALCALINO_BUENO_PA_LA_SALUD.jpg 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_ALCALINO_BUENO_PA_LA_SALUD-300x136.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/>EFE.- Buscamos tener un cuerpo sano, que es tanto como buscar un cuerpo alcalino. Porque una <strong>clave de nuestra salud est\u00e1 en el pH de la sangre<\/strong>, el \u00edndice que mide su acidez o alcalinidad en una escala del 0 al 14.<\/p>\n<p>  <!--more-->  <\/p>\n<ul>\n<li>Una clave de nuestra salud est\u00e1 en el pH de la sangre: de 0 a 14, el id\u00f3neo es 7,4.<\/li>\n<li>Ante el exceso de acidez, la sangre roba nutrientes del resto de \u00f3rganos.<\/li>\n<li>Eso causa cansancio, dolor de cabeza, problemas digestivos, desmineralizaci\u00f3n&#8230;<\/li>\n<li>Repasamos los alimentos \u00e1cidos (a evitar) y alcalinos (a procurar).<\/li>\n<\/ul>\n<p>El nivel id\u00f3neo es el 7,4. Pero la contaminaci\u00f3n ambiental, los malos h\u00e1bitos alimenticios o el estr\u00e9s <strong>acidifican el cuerpo y alteran este ph<\/strong>. Y la sangre reacciona: roba los nutrientes que necesita del resto de \u00f3rganos vitales para compensar el desequilibro. Pero eso tiene consecuencias: cansancio, dolores de cabeza, problemas digestivos, dismineralizaci\u00f3n de las u\u00f1as y el cabello, etc.<\/p>\n<p>Enrique Gonz\u00e1lez, director t\u00e9cnico de Bioenerg\u00eda Humana y nutricionista terap\u00e9utico, afirma que <strong>\u00abla sangre es el director\u00bb<\/strong>. Las oscilaciones del pH de la sangre son casi nulas (+\/- 0,04), y por tanto no se suele medir: \u00abLo que solemos medir son otros l\u00edquidos del cuerpo como la saliva y la orina. Si est\u00e1n \u00e1cidos es que est\u00e1n cediendo a la sangre, y si est\u00e1n alcalinos no\u00bb.<\/p>\n<p>Si mantenemos <strong>nuestro cuerpo en su estado natural, es decir, ligeramente alcalino<\/strong> (con el pH de la sangre por encima de 7), estar\u00e1 protegido frente a enfermedades. El nutricionista lo explica: \u00abNo va a tener que ceder ning\u00fan tipo de sustancia y va a propiciar un clima poco favorable para virus y bacterias\u00bb.<\/p>\n<p>En cambio, <strong>un cuerpo \u00e1cido es un cuerpo enfermo<\/strong> o propenso a la enfermedad porque la sangre, las c\u00e9lulas y los \u00f3rganos vitales viven en un entorno hostil y est\u00e1n en peligro. \u00abTenemos que trabajar para que nuestro cuerpo est\u00e9 alcalino y no \u00e1cido\u00bb, explica Enrique Gonz\u00e1lez.<\/p>\n<h2>Cuatro claves para tener un cuerpo \u00abalcalino\u00bb<\/h2>\n<p>Las <strong>claves para combatir la acidez<\/strong> son la alimentaci\u00f3n, el ejercicio f\u00edsico, la \u00abducha interior\u00bb y el equilibrio emocional.<\/p>\n<p><strong>Nutrici\u00f3n<\/strong><br \/>Lo ideal es compensar con m\u00e1s alimentos alcalinizantes \u2013ricos en potasio, magnesio y\/o calcio\u2013 para que el cuerpo no tenga que sufrir robando minerales para alcalinizar la sangre. De este modo lograremos equilibrar la cifra del ph. La recomendaci\u00f3n del experto es <strong>consumir menos alimentos acidificantes y m\u00e1s alimentos alcalinizantes<\/strong>.<\/p>\n<ul>\n<li><strong>Alimentos \u00e1cidos<\/strong>: caf\u00e9, alcohol, bebidas gaseosas, frituras, az\u00facar refinado, harina blanca, zumo de frutas envasado, chocolate, mermelada, leche, arroz, carne roja y frutas en general.<\/li>\n<li><strong>Alimentos alcalinos<\/strong>: patata, lechuga, pepino, coles de Bruselas, espinacas, algas, lim\u00f3n, bayas de Goji, aguacate, ajo, t\u00e9 verde, jengibre y almendras crudas.<\/li>\n<\/ul>\n<p><strong>Ejercicio f\u00edsico<\/strong><br \/>Un cuerpo sedentario realiza sus funciones con mucha m\u00e1s lentitud. Se aconseja hacer deporte adaptado a la edad y el nivel de preparaci\u00f3n de cada uno para \u00abmantener el cuerpo vivo\u00bb. As\u00ed <strong>se activa el metabolismo, se eliminan toxinas<\/strong> y el organismo funciona bien.<\/p>\n<p><strong>\u00abDucha interior\u00bb<\/strong><br \/>Depurar los residuos de nuestro cuerpo es imprescindible. \u00abLos <strong>t\u00f3xicos tambi\u00e9n nos acidifican<\/strong>, sobre todo si el organismo no limpia o no drena bien\u00bb, afirma el nutricionista. Por eso propone recurrir a algunas plantas que ayuden en la labor de limpieza. Hidratarse tambi\u00e9n es muy importante.<\/p>\n<p><strong>Equilibrio emocional<\/strong><br \/>Seg\u00fan la Organizaci\u00f3n Mundial de la Salud , la <strong>salud implica bienestar f\u00edsico y ps\u00edquico<\/strong>, as\u00ed como bienestar ambiental y social. El estr\u00e9s emocional provoca que ciertas hormonas nos tensionen y dejen residuos en el organismo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EFE.- Buscamos tener un cuerpo sano, que es tanto como buscar un cuerpo alcalino. Porque una clave de nuestra salud est\u00e1 en el pH de la sangre, el \u00edndice que mide su acidez o alcalinidad en una escala del 0 al 14.<\/p>\n","protected":false},"author":3,"featured_media":22040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-22041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22041"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22040"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}