{"id":22090,"date":"2012-12-13T19:51:09","date_gmt":"2012-12-13T23:51:09","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/vecinos-del-barrio-holguin-frente-a-base-aerea-de-pto-pta-protestan-por-situacion-con-edenorte\/"},"modified":"2012-12-13T19:51:09","modified_gmt":"2012-12-13T23:51:09","slug":"vecinos-del-barrio-holguin-frente-a-base-aerea-de-pto-pta-protestan-por-situacion-con-edenorte","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/vecinos-del-barrio-holguin-frente-a-base-aerea-de-pto-pta-protestan-por-situacion-con-edenorte\/","title":{"rendered":"Vecinos del Barrio Holgu\u00edn frente a Base A\u00e9rea de Pto. Pta. Protestan por situaci\u00f3n con EDENORTE"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-22089\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_edenorte5063.jpg\" width=\"150\" height=\"110\" alt=\"edenorte5063\" class=\"caption\" style=\"float: left;\" \/>Sos\u00faa:- Residentes en el barrio Holguin frente a la Base A\u00e9rea de aqu\u00ed salieron a las calles en protesta por la situaci\u00f3n que enfrentan con la Empresa Distribuidora de Energ\u00eda del Norte \u201cEDENORTE\u201d, en virtud de que la l\u00ednea que alimenta el principal transformador de energ\u00eda de la comunidad con frecuencia se rompe debido al mal estado que presenta.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>Manifestaron que referido cableado se rompe constantemente interrumpiendo el servicio, lo que representa un peligro mortal ya que cae sobre el zinc de las casas que conforman el barrio corriendo sus habitantes el peligro de morir electrocutados.<\/div>\n<div><\/div>\n<div>\n<p>Adujeron que cumplen con el pago del servicio regularmente, pero, que la Distribuidora de Energ\u00eda los irrespeta ya que el mal servicio y las constantes aver\u00edas por rupturas del cableado.<\/p>\n<p>Agregaron que han solicitado a ejecutivos de la empresa de energ\u00eda reubicar algunos postes del tendido el\u00e9ctrico que en la actualidad se encuentran dentro de algunas residencias del sector, as\u00ed como la sustituci\u00f3n del cableado, a lo que se le ha hecho omiso provocando la indignaci\u00f3n que les motiv\u00f3 a realizar la protesta.<\/p>\n<p><a href=\"http:\/\/www.sosuadigital.net\/index.php\/noticias-del-momento\/3069-vecinos-del-barrio-holguin-frente-a-base-aerea-de-pto-pta-protestan-por-situacion-con-edenorte\">fuente<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa:- Residentes en el barrio Holguin frente a la Base A\u00e9rea de aqu\u00ed salieron a las calles en protesta por la situaci\u00f3n que enfrentan con la Empresa Distribuidora de Energ\u00eda del Norte \u201cEDENORTE\u201d, en virtud de que la l\u00ednea que alimenta el principal transformador de energ\u00eda de la comunidad con frecuencia se rompe debido al mal estado que presenta.<\/p>\n","protected":false},"author":3,"featured_media":22089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-22090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22090"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22090\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22089"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}