{"id":22138,"date":"2012-12-15T16:08:15","date_gmt":"2012-12-15T20:08:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/sensato-quiere-salir-del-patio-al-mundo-de-la-moda\/"},"modified":"2012-12-15T16:08:15","modified_gmt":"2012-12-15T20:08:15","slug":"sensato-quiere-salir-del-patio-al-mundo-de-la-moda","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/sensato-quiere-salir-del-patio-al-mundo-de-la-moda\/","title":{"rendered":"Sensato quiere salir del patio al mundo de la moda&#8230;"},"content":{"rendered":"<div>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-22137\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_fe43debe365c3734b050f80797ad9725_L.jpg\" width=\"300\" height=\"278\" alt=\"fe43debe365c3734b050f80797ad9725_L\" class=\"caption\" style=\"float: left;\" \/>\u00abNo importa que tan grande sean los compromisos, siempre busco la manera de terminar el a\u00f1o, en mi pa\u00eds\u00bb, afirma al adelantar que tiene deseos de comer pasteles en RD<\/h4>\n<\/p><\/div>\n<p>  <!--more-->  <\/p>\n<div>\n<p>William Reyna naci\u00f3 en San Cristobal. Sin embargo, se cri\u00f3 en el Bronx, barrio neoyorquino al que se mud\u00f3 siendo un adolescente de 13 a\u00f1os.<\/p>\n<p>Con los a\u00f1os fue incursionando cada vez m\u00e1s en la m\u00fasica hasta que logr\u00f3 su boom con el sobrenombre de Sensato del Patio y su propuesta de m\u00fasica urbana.<\/p>\n<p>\u00abSiempre supe que este momento llegar\u00eda&nbsp; me faj\u00e9 y prepar\u00e9; eso y la formaci\u00f3n de mis padres impidi\u00f3 que la fama me afectara\u00bb, le dijo el int\u00e9rprete de \u00abJhonny, la gente est\u00e1 muy loca\u00bb a Dafne Guzm\u00e1n para su programa \u00abDe calle\u00bb, que se tranmite por Teleantillas.<\/p>\n<p>\u00abSoy de los que visualizan sus metas y trabajo para conseguirlas, el mejor ejemplo es el tatuaje que me hice con el logo del Latin Grammy cuando aun no hab\u00eda iniciado de manera profesional mi carrera en la m\u00fasica y mira: este a\u00f1o consegu\u00ed&nbsp; no una, sino dos nominaciones\u00bb, coment\u00f3 en medio de la conversaci\u00f3n el tambi\u00e9n productor urbano.<\/p>\n<p>En otro orden, luciendo una impecable y moderna pinta, el disc\u00edpulo de Pitbull se confes\u00f3 amante de los pasteles en hoja que prepara su mam\u00e1 y de la moda.<\/p>\n<p>\u00abDesde chiquitico cuando andaba por La Toma o el Santo Cerro, en San Cristobal, los carajitos me relajaban porque no me desmontaba mi fl\u00fa\u00bb, admitiendo as\u00ed que le gustan las marcas, por lo que no descarta incursionar el pr\u00f3ximo a\u00f1o en ese mundo de la moda, a lo mejor con una linea de lentes con su nombre.<\/p>\n<p>\u00abPrimero tengo que recargar energ\u00edas&nbsp; sobre todo porque gracias a Dios este ha sido un a\u00f1o muy intenso; pero algo si es seguro, no importa qu\u00e9 tan grande sean los compromisos, busco la manera de terminar el a\u00f1o comiendo pasteles en hoja en mi pa\u00eds\u00bb, afirm\u00f3.<\/p>\n<p>La entrevista completa con Sensato podr\u00e1 ser vista este domingo 16 de diciembre, en el horario de DeCalle, a las 7 de la noche por Teleantillas, canal 2.<\/p>\n<p>fuente: masvip.com.do&nbsp;<\/p>\n<\/p><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00abNo importa que tan grande sean los compromisos, siempre busco la manera de terminar el a\u00f1o, en mi pa\u00eds\u00bb, afirma al adelantar que tiene deseos de comer pasteles en RD<\/p>\n","protected":false},"author":3,"featured_media":22137,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-22138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22138"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22137"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}