{"id":22181,"date":"2012-12-17T17:17:47","date_gmt":"2012-12-17T21:17:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/quince-curiosidades-sobre-bill-gates\/"},"modified":"2012-12-17T17:17:47","modified_gmt":"2012-12-17T21:17:47","slug":"quince-curiosidades-sobre-bill-gates","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/quince-curiosidades-sobre-bill-gates\/","title":{"rendered":"Quince curiosidades sobre Bill Gates"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-22180\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_bill-gates-I.jpg\" width=\"150\" height=\"150\" alt=\"bill-gates-I\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_bill-gates-I.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_bill-gates-I-120x120.jpg 120w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/>William Henry Gates III, m\u00e1s conocido como Bill Gates, es un empresario y fil\u00e1ntropo estadounidense, cofundador de la empresa de software Microsoft, productora del sistema operativo para computadoras personales m\u00e1s utilizado en el mundo, Microsoft Windows.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Gates naci\u00f3 el&nbsp;<strong>28 de octubre de 1955<\/strong>&nbsp;en Seattle, Estados Unidos, y para conmemorar sus 56 a\u00f1os te traemos un recorrido a trav\u00e9s de su interesante vida en 15 curiosidades.<\/p>\n<p>1. Est\u00e1 casado con Melinda Gates, y ambos ostentan el liderazgo de la Fundaci\u00f3n Bill y Melinda Gates, dedicada a reequilibrar oportunidades en salud y educaci\u00f3n a nivel local, especialmente en las regiones menos favorecidas, raz\u00f3n por la cual han sido galardonados con el Premio Pr\u00edncipe de Asturias de Cooperaci\u00f3n Internacional 2006.<\/p>\n<p>2. Es el segundo hombre m\u00e1s rico del mundo seg\u00fan la revista Forbes (2011) con una fortuna de 56 mil millones de d\u00f3lares.<\/p>\n<p>3. Muchos libros han sido escritos acerca de Gates, Amazon muestra 137,632 resultados.<\/p>\n<p>4. La primera compa\u00f1\u00eda que fund\u00f3 fue Traf-O-Data.<\/p>\n<p>5. Microsoft sol\u00eda escribirse \u201cMicro-Soft\u201d.<\/p>\n<p>6. Su bisabuelo fue alcalde, su abuelo fue el vicepresidente de un banco y su padre un abogado exitoso.<\/p>\n<p>7. En 1968 cuando se instalaron las primeras computadoras en Lakeside Academy sus calificaciones bajaron porque pasaba d\u00edas y noches aprendiendo a usar el nuevo equipo.<\/p>\n<p>8. Gates, Paul Allen y sus amigos causaron que las computadoras en Lakeside Academy fallaran, por intentar hackearlas.<\/p>\n<p>9. Cuando era joven se balanceaba hacia delante y atr\u00e1s. Todav\u00eda lo hace cuando piensa profundamente.<\/p>\n<p>10. Se aburr\u00eda en Harvard y se la pas\u00f3 la mayor\u00eda del tiempo programando y jugando p\u00f3ker.<\/p>\n<p>11. Gates le dijo a un profesor de universidad que ser\u00eda billonario a los 30 a\u00f1os. Gates lo consigui\u00f3 a los 31.<\/p>\n<p>12. Uno de sus profesores dijo \u201cBill es un programador incre\u00edble, pero no es agradable como persona\u201d.<\/p>\n<p>13. Su primer trabajo de programaci\u00f3n consist\u00eda en hacer un programa que organice de manera eficiente una agenda, por medio del cual el sol\u00eda inscribirse siempre a materias donde estaban las mujeres m\u00e1s atractivas.<\/p>\n<p>14. Durante la \u00e9poca de mayor esplendor de la compa\u00f1\u00eda, Bill Gates ganaba aproximadamente 250 d\u00f3lares cada segundo.<\/p>\n<p>15. Gates es un apasionado de la velocidad, raz\u00f3n por la que ha sido detenido tres veces, entre 1976 y 1977. El \u00faltimo arresto en 1977, tuvo como agravante que conduc\u00eda sin licencia. A ra\u00edz de estas detenciones circula por Internet la famosa foto que muestra su ficha policial.<\/p>\n<p><a href=\"http:\/\/www.culturizando.com\/2011\/10\/bill-gates-en-15-curiosidades.html\" target=\"_blank\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>William Henry Gates III, m\u00e1s conocido como Bill Gates, es un empresario y fil\u00e1ntropo estadounidense, cofundador de la empresa de software Microsoft, productora del sistema operativo para computadoras personales m\u00e1s utilizado en el mundo, Microsoft Windows.<\/p>\n","protected":false},"author":3,"featured_media":22180,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-22181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22181"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22180"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}