{"id":22216,"date":"2012-12-19T19:53:48","date_gmt":"2012-12-19T23:53:48","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/los-otros-finales-del-mundo-a-los-que-lsobrevivimosr\/"},"modified":"2012-12-19T19:53:48","modified_gmt":"2012-12-19T23:53:48","slug":"los-otros-finales-del-mundo-a-los-que-lsobrevivimosr","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-otros-finales-del-mundo-a-los-que-lsobrevivimosr\/","title":{"rendered":"Los otros finales del mundo a los que \u00absobrevivimos\u00bb"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-22215\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_Ginetes-300x168.jpg\" width=\"300\" height=\"168\" alt=\"Ginetes-300x168\" class=\"caption\" style=\"float: left;\" \/> <\/p>\n<p>Los vaticinaron un Papa, un matem\u00e1tico, los romanos y multitud de sectas religiosas a lo largo de la historia. Todos, de momento, erraron en sus profec\u00edas<\/p>\n<p>  <!--more-->  <\/p>\n<p>Los profetas del fin del mundo son tan antiguos como la propia existencia humana. Y casi eterno es tambi\u00e9n su constante error de c\u00e1lculo (aqu\u00ed estamos para corroborarlo). La profec\u00eda maya que anuncia el final de los d\u00edas llega este viernes, pero no es la primera, ni probablemente ser\u00e1 la \u00faltima. En ABC.es te hacemos un repaso de los finales del mundo m\u00e1s llamativos que finalmente no se cumplieron:<\/p>\n<p>A\u00f1o 389 AC: las \u00e1guilas de R\u00f3mulo<\/p>\n<p>Un mito de la fundaci\u00f3n de Roma dec\u00eda que doce \u00e1guilas revelaron a R\u00f3mulo cu\u00e1nto durar\u00eda la ciudad en el tiempo. En un principio, la creencia popular pensaba que cada ave representaba 10 a\u00f1os, por lo que la destrucci\u00f3n total llegar\u00eda a los 120 a\u00f1os del nacimiento de la urbe.<\/p>\n<p>Una vez pasada la fecha, la creencia retras\u00f3 el apocalipsis hasta el 389 antes de Cristo, debido a otra interpretaci\u00f3n posterior en la que se asignaba otro n\u00famero a cada \u00e1guila. Pero Roma sigui\u00f3 adelante.<\/p>\n<p>A\u00f1o 1284: llega el Anticristo (Inocencio III)<br \/>El Papa Inocencio III estaba convencido de que Sat\u00e1n sobrevendr\u00eda al mundo 666 a\u00f1os despu\u00e9s del ascenso del Islam. El l\u00edder religioso escribi\u00f3: \u00abEl final de la bestia se acerca, y su n\u00famero, de acuerdo con la revelaci\u00f3n de San Juan, llegar\u00e1 en 666 a\u00f1os, de los que ya han pasado 600\u00bb.<\/p>\n<p>Las declaraciones del Santo Padre hay que contextualizarlas en una \u00e9poca de cruzadas y en la que el islamismo era una amenaza constante para Occidente. Nada pas\u00f3 en 1284, pero siete a\u00f1os m\u00e1s tarde, en 1291, el sult\u00e1n Khalik conquist\u00f3 Israel, arrebatando el lugar a los cristianos.<\/p>\n<p>A\u00f1o 1688: fin del mundo neperiano<\/p>\n<p>Hasta los cient\u00edficos m\u00e1s notables cayeron en la tentaci\u00f3n de predecir el fin del mundo. Es el caso del matem\u00e1tico John Napier, experto calculador y creador de los logaritmos neperianos.<\/p>\n<p>Pese a sus brillantes cuentas, lo que de verdad obsesionaba a Napier y ocupaba su tiempo era el fin del mundo y las ense\u00f1anzas del Apocalipsis. Bas\u00e1ndose en su cronolog\u00eda, vaticin\u00f3 que el apocalipsis llegar\u00eda en el a\u00f1o 1688 o en el 1700 en la que consideraba su obra m\u00e1s importante, Descubrimientos de todos los secretos del Apocalipsis de San Juan. Muri\u00f3 en 1617 sin conocer que sus predicciones no se iban a cumplir.<\/p>\n<p>A\u00f1o 1910: el cometa Halley<br \/>El b\u00f3lido espacial, que visita los alrededores de la Tierra desde hace cientos de a\u00f1os, fue visto como una amenaza real en 1910, cuando otro cient\u00edfico -el astr\u00f3nomo Camille Flammarion- aventur\u00f3 que podr\u00eda \u00abimpregnar con gas t\u00f3xico las atm\u00f3sfera y acabar con la vida en la Tierra\u00bb.<\/p>\n<p>La psicosis fue tal que se vendieron m\u00e1scaras de gas, pastillas \u00abanti-cometa\u00bb y paraguas especiales para protegerse del fen\u00f3meno. Incluso un grupo religioso de Estados Unidos -Los Seguidores Sagrados- intentaron sacrificar una virgen para impedir el suceso. Por supuesto, la estela de gas que dej\u00f3 fue inocua.<\/p>\n<p>A\u00f1os 1992: La Iglesia del D\u00eda que se Avecina<\/p>\n<p>Lee Jang Rim fue el creador de una instituci\u00f3n religiosa (La Iglesia del D\u00eda que se Avecina) en la que predicaba a quien quisiera escucharle que la existencia acabar\u00eda el 28 de octubre de 1992.<\/p>\n<p>Desafortunadamente para Lee Jang Rim, que contaba con 46 a\u00f1os entonces, el mundo no se acab\u00f3 y, al d\u00eda siguiente, sus adeptos, muchos de los cuales hab\u00edan abandonado sus trabajos y a sus familias, le pidieron cuentas: \u00abHan reclamado a la secta el dinero entregado para sufragar gastos; ayudas que en su mayor parte proceden de la venta de propiedades o pertenencias personales\u00bb, contaba ABC el 3 de noviembre de ese a\u00f1o.<\/p>\n<p>El fundador de la iglesia fue encarcelado inmediatamente y condenado a dos a\u00f1os de c\u00e1rcel por estafa, pese a que pidi\u00f3 perd\u00f3n p\u00fablicamente por el error en su predicci\u00f3n. Algunas fuentes calculan que amas\u00f3 hasta cuatro millones de d\u00f3lares gracias a las donaciones.<\/p>\n<p>1 de enero del a\u00f1o 2000: Uganda<br \/>El fin de 1999 todav\u00eda se recuerda para mal en Uganda, donde otra \u00abprofeta\u00bb err\u00e1tica, Credonia Mwerinde, protagoniz\u00f3 uno de los sucesos m\u00e1s macabros atribuidos a los \u00abfindelmundistas\u00bb.<\/p>\n<p>La \u00absacerdotisa\u00bb fund\u00f3 su propia secta, la \u00abRestauraci\u00f3n de los Diez Mandamientos de Dios\u00bb en 1994. La religiosa, que hab\u00eda ejercido antes la prostituci\u00f3n, se aprovech\u00f3 del analfabetismo reinante en el pa\u00eds africano y de una mezcla de cultos poco ortodoxa para lograr el ascenso de este movimiento religioso extremadamente radical y que adoptaba pr\u00e1cticas ilegales y sumamente s\u00e1dicas, como la de beber la sangre de beb\u00e9s previamente sacrificados.<\/p>\n<p>Aprovechando la llegada del a\u00f1o 2000, Credonia vaticin\u00f3 el d\u00eda del juicio final para el 1 de enero. Pero el des\u00e1nimo cundi\u00f3 entre sus seguidores al ver que, pasada la fecha, la vida segu\u00eda su curso habitual. Sin embargo, muchos de ellos siguieron a su l\u00edder durante semanas.<\/p>\n<p>El \u00faltimo acto de esta iglesia fue la reuni\u00f3n en la localidad de Kampala, donde supuestamente tendr\u00eda lugar una aparici\u00f3n de la Virgen Mar\u00eda. Centenares de fan\u00e1ticos se juntaron en una iglesia para disfrutar de esta experiencia mariana, pero lo que en realidad ocurri\u00f3 fue una matanza descomunal: los l\u00edderes de la secta cerraron puertas y ventanas y rociaron con gasolina y \u00e1cido a las m\u00e1s de 500 personas all\u00ed congregadas. Luego desaparecieron. Posteriormente se conocieron otras matanzas que elevaron la cifra de asesinados en la secta a m\u00e1s de un millar.<\/p>\n<p>A\u00f1os 2011: el pen\u00faltimo fin del mundo<\/p>\n<p>\u00abUn gran terremoto sacudir\u00e1 la tierra. Las tumbas se abrir\u00e1n y los restos de las personas que murieron como verdaderos creyentes resucitar\u00e1n e ir\u00e1n al cielo. Los cuerpos de los que no se salvar\u00e1n ser\u00e1n lanzados sobre esti\u00e9rcol y arena, y sus restos ser\u00e1n comidos por los gusanos y los animales\u00bb.<\/p>\n<p>Este l\u00fagubre augurio vino de la mano de Harold Camping, un \u00abprofeta\u00bb cristiano que cre\u00eda que el apocalipsis llegar\u00eda el 21 de octubre y que meses antes hab\u00eda anunciado tambi\u00e9n que el mundo acabar\u00eda el 21 de mayo. Tras pasar la fecha, el norteamericano dijo \u00abno haber entendido bien\u00bb el mensaje de Dios y sigui\u00f3 predicando su particular visi\u00f3n de la religi\u00f3n como si nada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los vaticinaron un Papa, un matem\u00e1tico, los romanos y multitud de sectas religiosas a lo largo de la historia. Todos, de momento, erraron en sus profec\u00edas<\/p>\n","protected":false},"author":3,"featured_media":22215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-22216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22216"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22215"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}