{"id":22220,"date":"2012-12-19T21:05:26","date_gmt":"2012-12-20T01:05:26","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/dos-cigarrillos-al-dia-roban-media-hora-de-vida-20-minutos-de-ejercicio-dan-una-hora-mas\/"},"modified":"2012-12-19T21:05:26","modified_gmt":"2012-12-20T01:05:26","slug":"dos-cigarrillos-al-dia-roban-media-hora-de-vida-20-minutos-de-ejercicio-dan-una-hora-mas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dos-cigarrillos-al-dia-roban-media-hora-de-vida-20-minutos-de-ejercicio-dan-una-hora-mas\/","title":{"rendered":"Dos cigarrillos al d\u00eda roban media hora de vida; 20 minutos de ejercicio dan una hora m\u00e1s"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-22219\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_carousel-3221.png\" width=\"300\" height=\"143\" alt=\"carousel-3221\" class=\"caption\" style=\"float: left;\" \/>La ciencia ya ha logrado que la sociedad sepa, sin lugar a dudas, de los enormes perjuicios del tabaco o de los excesos con el alcohol. No obstante, los cient\u00edficos no siempre logran explicarlo, comunicarlo de la mejor de las maneras.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El profesor David Spiegelhalter, estad\u00edstico de la Universidad de Cambridge (Reino Unido), ha querido encontrar una manera sencilla de comunicar el impacto de nuestro comportamiento en la esperanza de vida. Y lo ha logrado con ejemplos muy concretos, muy gr\u00e1ficos, traduciendo los efectos en minutos de vida.<\/p>\n<p>As\u00ed, actividades como fumar, tomar un par de copas, comer carne roja y ver la televisi\u00f3n en cualquier momento del a\u00f1o puede restar por lo menos 30 minutos de la esperanza de vida por cada d\u00eda de disfrute, mientras que no tomar m\u00e1s de una bebida alcoh\u00f3lica, comer muchas frutas y verduras y hacer ejercicio puede dar como resultado una suma de dos horas de vida al d\u00eda.<\/p>\n<p>Spiegelhalter \u2013cuyo estudio publica British Medical Journal\u2013 ha utilizado el concepto de envejecimiento m\u00e1s r\u00e1pido o m\u00e1s lento, expresando el efecto de los h\u00e1bitos de vida diaria como microlives, es decir, horas y media de esperanza de vida, por lo que<strong>&nbsp;media hora de esperanza de vida de un adulto puede ser un microlive<\/strong>porque equivale a una millon\u00e9sima parte de la vida despu\u00e9s de los 35 a\u00f1os.<\/p>\n<p>Usando datos de estudios de poblaci\u00f3n calcula que, como promedio de un h\u00e1bito de por vida, puede perderse un microlive por fumar dos cigarrillos, tener un sobrepeso de 5 kilogramos, consumir dos o tres bebidas alcoh\u00f3licas al d\u00eda, observar dos horas de televisi\u00f3n o comer una hamburguesa, mientras que tambi\u00e9n pueden ganarse microlives si solo se toma una copa de alcohol al d\u00eda (1 microlive), se comen frutas y verduras frescas (4 microlives), se hacen 20 minutos de ejercicio moderado (2 microlives) o se ingiere una estatina (1 microlive) \u2013un grupo de f\u00e1rmacos para reducir el colesterol\u2013 al d\u00eda todos los d\u00edas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ciencia ya ha logrado que la sociedad sepa, sin lugar a dudas, de los enormes perjuicios del tabaco o de los excesos con el alcohol. No obstante, los cient\u00edficos no siempre logran explicarlo, comunicarlo de la mejor de las maneras.<\/p>\n","protected":false},"author":3,"featured_media":22219,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-22220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22220"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22220\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22219"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}