{"id":22399,"date":"2012-12-29T16:30:56","date_gmt":"2012-12-29T20:30:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/los-adolescentes-mas-sedentarios-consumen-el-doble-de-refrescos-y-muy-poca-fruta\/"},"modified":"2012-12-29T16:30:56","modified_gmt":"2012-12-29T20:30:56","slug":"los-adolescentes-mas-sedentarios-consumen-el-doble-de-refrescos-y-muy-poca-fruta","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/los-adolescentes-mas-sedentarios-consumen-el-doble-de-refrescos-y-muy-poca-fruta\/","title":{"rendered":"Los adolescentes m\u00e1s sedentarios consumen el doble de refrescos y muy poca fruta"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-22398\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_76021-620-282.jpg\" width=\"620\" height=\"282\" alt=\"76021-620-282\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_76021-620-282.jpg 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_76021-620-282-300x136.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/>El sedentarismo nos est\u00e1 matando o, como poco, est\u00e1 empeorando gravemente nuestra salud. Porque sedentario equivale a&nbsp;<strong>menos actividad f\u00edsica, mucho tiempo sentados y una peor alimentaci\u00f3n<\/strong>. Y ya se advierte en los m\u00e1s j\u00f3venes.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<p>Seg\u00fan una investigaci\u00f3n de la&nbsp;<a title=\"Universidad de Zaragoza\" href=\"http:\/\/www.unizar.es\/\" target=\"_blank\">Universidad de Zaragoza<\/a>, los adolescentes europeos m\u00e1s sedentarios y que dedican m\u00e1s de cuatro horas al d\u00eda a \u00abpantallas\u00bb (televisi\u00f3n, ordenador e internet)&nbsp;<strong>consumen el doble de refrescos y reducen hasta un 70% la ingesta de frutas<\/strong>.<\/p>\n<p>Frente a estos datos, el estudio \u2013que publica&nbsp;<a title=\"Archives of Pediatrics and Adolescent Medicine\" href=\"http:\/\/www.20minutos.es\/archpedi.jamanetwork.com\/\" target=\"_blank\">Archives of Pediatrics and Adolescent Medicine<\/a>\u2013 muestra que en aquellos que invierten&nbsp;<strong>m\u00e1s tiempo al estudio disminuye el consumo de refrescos<\/strong>&nbsp;entre el 50 y el 60%.<\/p>\n<p>En el trabajo se muestra la asociaci\u00f3n entre diversas conductas sedentarias y el consumo de diversos grupos de alimentos en adolescentes europeos. Los resultados publicados se basan en&nbsp;<strong>m\u00e1s de 2.200 adolescentes con edades comprendidas entre 12,5 y 17,5 a\u00f1os<\/strong>&nbsp;procedentes de ocho ciudades europeas (Atenas, Dortmund, Gante, Lille, Roma, Estocolmo, Viena y Zaragoza).<\/p>\n<p>La investigaci\u00f3n ha tenido en cuenta el tiempo que los adolescentes europeos dedican a actividades sedentarias, como la utilizaci\u00f3n de medios electr\u00f3nicos. As\u00ed, el estudio ha detectado que los adolescentes europeos&nbsp;<strong>superan con creces la recomendaci\u00f3n a nivel mundial de no dedicar m\u00e1s de 2 horas al d\u00eda<\/strong>&nbsp;a actividades sedentarias, como es el caso de la televisi\u00f3n, ordenadores y videoconsolas.<\/p>\n<p>De hecho, esta investigaci\u00f3n ha observado que el tiempo que estos adolescentes europeos&nbsp;<strong>utilizan ante las \u00abpantallas\u00bb supera las cuatro horas diarias<\/strong>; dos horas a ver la televisi\u00f3n, una hora a jugar a los ordenadores y otra a utilizar internet en su tiempo libre.<\/p>\n<h2>Mayor prevalencia de obesidad<\/h2>\n<p>Estos datos se unen a los obtenidos en otro estudio internacional, que sugiere que determinadas conductas sedentarias como el consumo de televisi\u00f3n u ordenadores&nbsp;<strong>influyen en el consumo de diversos tipos de alimentos<\/strong>.<\/p>\n<p>En este sentido, el&nbsp;<strong>consumo de bebidas refrescantes se ha relacionado en algunos estudios con una mayor prevalencia<\/strong>&nbsp;de&nbsp;<a title=\"M\u00e1s informaci\u00f3n sobre la obesidad\" href=\"http:\/\/www.20minutos.es\/minuteca\/obesidad\" target=\"_blank\">obesidad<\/a>, debido al aporte suplementario de calor\u00edas que se consumen en elevada cantidad. Adem\u00e1s, el consumo de frutas y verduras est\u00e1 relacionado con la prevenci\u00f3n de algunos tipos de<a title=\"M\u00e1s informaci\u00f3n sobre el c\u00e1ncer\" href=\"http:\/\/www.20minutos.es\/minuteca\/cancer\" target=\"_blank\">c\u00e1ncer<\/a>&nbsp;y de enfermedades cardiovasculares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sedentarismo nos est\u00e1 matando o, como poco, est\u00e1 empeorando gravemente nuestra salud. Porque sedentario equivale a&nbsp;menos actividad f\u00edsica, mucho tiempo sentados y una peor alimentaci\u00f3n. Y ya se advierte en los m\u00e1s j\u00f3venes.&nbsp;<\/p>\n","protected":false},"author":3,"featured_media":22398,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-22399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22399"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22398"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}