{"id":22405,"date":"2012-12-29T20:56:42","date_gmt":"2012-12-30T00:56:42","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/las-acciones-de-facebook-bajan-debido-a-la-perdida-de-usuarios-de-instagram\/"},"modified":"2012-12-29T20:56:42","modified_gmt":"2012-12-30T00:56:42","slug":"las-acciones-de-facebook-bajan-debido-a-la-perdida-de-usuarios-de-instagram","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/las-acciones-de-facebook-bajan-debido-a-la-perdida-de-usuarios-de-instagram\/","title":{"rendered":"Las acciones de Facebook bajan debido a la p\u00e9rdida de usuarios de Instagram"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-22404\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/12\/sosua_images_464306-300x200.jpg\" width=\"300\" height=\"200\" alt=\"464306-300x200\" class=\"caption\" style=\"float: left;\" \/>Las acciones de Facebook cayeron el viernes luego de informaciones que apuntaban a que su aplicaci\u00f3n para compartir fotos, Instagram, perd\u00eda millones de usuarios debido a la publicaci\u00f3n de cambios en su pol\u00edticas que generaron la irritaci\u00f3n de miles de personas.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Seg\u00fan el seguidor especializado de audiencia AppData.com, durante la semana pasada el n\u00famero de usuarios diarios de Instagram cay\u00f3 de 12,4 a 3,5 millones.<\/p>\n<p>Las acciones de Facebook descend\u00edan un 2,5% en las primeras horas de transacciones, poco antes de repuntar hasta los 25,71 d\u00f3lares a comienzos de la tarde, lo que representa una ca\u00edda de 1,2%.<\/p>\n<p>A comienzos de mes, Instagram retir\u00f3 los cambios anunciados en su pol\u00edtica de privacidad lo que le hubiese permitido vender fotos sin compensaci\u00f3n econ\u00f3mica, un movimiento que gener\u00f3 la ira de miles de usuarios.<\/p>\n<p>Los foros de Twitter e Instagram echaban chispas sobre los t\u00e9rminos utilizados mientras miles de usuarios debat\u00edan si borrar sus cuentas o mantenerlas cuando entraran en vigor las nuevas normas.<\/p>\n<p>Facebook adquiri\u00f3 Instagram este a\u00f1o en un marco de constante presi\u00f3n sobre la forma en que la gigante red social puede rentabilizar su millonaria base de datos de usuarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las acciones de Facebook cayeron el viernes luego de informaciones que apuntaban a que su aplicaci\u00f3n para compartir fotos, Instagram, perd\u00eda millones de usuarios debido a la publicaci\u00f3n de cambios en su pol\u00edticas que generaron la irritaci\u00f3n de miles de personas.<\/p>\n","protected":false},"author":3,"featured_media":22404,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-22405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22405"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22404"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}