{"id":22815,"date":"2013-01-16T04:26:36","date_gmt":"2013-01-16T08:26:36","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-dieta-del-primer-ano-impacta-en-el-desarrollo-mental-de-por-vida\/"},"modified":"2013-01-16T04:26:36","modified_gmt":"2013-01-16T08:26:36","slug":"la-dieta-del-primer-ano-impacta-en-el-desarrollo-mental-de-por-vida","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-dieta-del-primer-ano-impacta-en-el-desarrollo-mental-de-por-vida\/","title":{"rendered":"La dieta del primer a\u00f1o impacta en el desarrollo mental de por vida"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22814\" alt=\"BEB-MA1\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_BEB-MA1.jpg\" width=\"300\" height=\"199\" \/>El d\u00e9ficit de nutrientes b\u00e1sicos entre la sexta semana y el primer a\u00f1o de vida puede dejar da\u00f1os irreversibles en el desarrollo neurocerebral de un persona. Consejos para una nutrici\u00f3n saludable.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Es que durante este per\u00edodo se produce la transformaci\u00f3n del cerebro que pasa de ser una estructura simple con m\u00ednimos surcos y circunvoluciones a ser una estructura compleja.<\/p>\n<p>La mielinizaci\u00f3n, la organizaci\u00f3n de neurotransmisores, arborizaci\u00f3n dendr\u00edtica y sinaptog\u00e9nesis son procesos que tienen lugar en este tiempo del beb\u00e9 y la evoluci\u00f3n \u00f3ptima de estas formaciones dependen directamente de m\u00faltiples factores como son el material gen\u00e9tico, el entorno y, tambi\u00e9n, la alimentaci\u00f3n.<\/p>\n<p>Entonces, es necesario valorar los aspectos nutricionales en todas las etapas, desde el embarazo hasta el post parto, para prevenir problemas futuros en el crecimiento de los ni\u00f1os.<\/p>\n<p>Por ejemplo, es importante promover la lactancia materna, que es el alimento ideal con los componentes que satisfacen todas las necesidades, y as\u00ed protegeremos el desarrollo neurol\u00f3gico de la poblaci\u00f3n infantil.<\/p>\n<p>Los nutrientes transferidos desde la placenta en el tercer trimestre, la alimentaci\u00f3n con leche humana, el alto aporte proteico y \u00e1cidos grasos de cadena larga son fundamentales para ayudar al buen desarrollo neurocerebral.<\/p>\n<p>En caso de que exista un d\u00e9ficit en los nutrientes fetales este determinar\u00e1 probablemente una alteraci\u00f3n estructural y funcional del cerebro con reducci\u00f3n del volumen de sustancia gris cortical y del volumen de los n\u00facleos de la base.<\/p>\n<p>El crecimiento cef\u00e1lico es una importante variable para evaluar el neurodesarrollo debido a que la medici\u00f3n de su per\u00edmetro se correlaciona con el peso estimado del cerebro y desarrollo los primeros dos a\u00f1os de vida.<\/p>\n<p>De esta forma, se recomienda para los beb\u00e9s de seis meses a un a\u00f1o, incluir en sus dietas \u00e1cidos grasos de gran jerarqu\u00eda para ayudar a la realizaci\u00f3n de los procesos de desarrollo mental.<\/p>\n<p>Alteraciones de los \u00e1cidos grasos esenciales comprometen el metabolismo de neurotransmisores y puede ocasionar la disminuci\u00f3n de la actividad de la membrana proteica y receptores.<\/p>\n<p>Por: doctora Carmen Vechiarelli, m\u00e9dica pediatra y neonat\u00f3loga, coordinadora del Servicio de Neonatolog\u00eda del Sanatorio Otamendi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00e9ficit de nutrientes b\u00e1sicos entre la sexta semana y el primer a\u00f1o de vida puede dejar da\u00f1os irreversibles en el desarrollo neurocerebral de un persona. Consejos para una nutrici\u00f3n saludable.<\/p>\n","protected":false},"author":3,"featured_media":22814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-22815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22815"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22815\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22814"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}