{"id":22817,"date":"2013-01-16T13:05:00","date_gmt":"2013-01-16T17:05:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/mp-policia-y-fad-realizan-operativo-en-sosua\/"},"modified":"2013-01-16T13:05:00","modified_gmt":"2013-01-16T17:05:00","slug":"mp-policia-y-fad-realizan-operativo-en-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/mp-policia-y-fad-realizan-operativo-en-sosua\/","title":{"rendered":"MP, Polic\u00eda y FAD realizan operativo en Sos\u00faa"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-22816\" alt=\"operativo_pn_y_militares\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_operativo_pn_y_militares.jpg\" width=\"707\" height=\"375\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_operativo_pn_y_militares.jpg 707w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_operativo_pn_y_militares-300x159.jpg 300w\" sizes=\"auto, (max-width: 707px) 100vw, 707px\" \/>Sos\u00faa.- Por M\u00e1ximo Reynoso. El Ministerio Publico y la Polic\u00eda Nacional asistidos por miembros del A2 de la Fuerza A\u00e9rea Dominicana adscritos al Comando A\u00e9reo Norte, iniciaron un amplio operativo preventivo del delito en diferentes sectores de este municipio.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Los polic\u00edas preventivos y los miembros del A2 de la FAD, encabezados por el magistrado Ram\u00f3n Cabrera, Fiscalizador de Sos\u00faa, visitaron varios negocios de expendio de bebidas alcoh\u00f3licas as\u00ed como pensiones, tanto en Los Charamicos, Las Piedras, Sos\u00faa Abajo y Maranatha.<\/p>\n<p>Durante el operativo fueron retenidas cuatro motocicletas, cuyos ocupantes no portaban documentaciones, ni mucho menos cedulas. Lo ocupado se encuentra en poder del ministerio p\u00fablico para los fines correspondientes.<\/p>\n<p>Algunas personas manifestaron, que a este pueblo le hace falta un poquito m\u00e1s de ese tipo de medidas, aunque trastorne un poco las actividades de los ciudadanos porque no hay otra manera de controlar el delito, porque si no hay presencia policial la sensaci\u00f3n de inseguridad es terrible.<\/p>\n<p>&nbsp;<\/p>\n<p>[<a href=\"http:\/\/www.cnntv3.tv\/tv3\/index.php\/noticias\/locales\/931-mp-policia-y-fad-realizan-operativo-en-sosua\">Fuente<\/a>]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- Por M\u00e1ximo Reynoso. El Ministerio Publico y la Polic\u00eda Nacional asistidos por miembros del A2 de la Fuerza A\u00e9rea Dominicana adscritos al Comando A\u00e9reo Norte, iniciaron un amplio operativo preventivo del delito en diferentes sectores de este municipio.<\/p>\n","protected":false},"author":3,"featured_media":22816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-22817","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22817"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22817\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22816"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}