{"id":22880,"date":"2013-01-17T19:03:39","date_gmt":"2013-01-17T23:03:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/poder-ejecutivo-crea-la-comision-nacional-de-desastres\/"},"modified":"2013-01-17T19:03:39","modified_gmt":"2013-01-17T23:03:39","slug":"poder-ejecutivo-crea-la-comision-nacional-de-desastres","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/poder-ejecutivo-crea-la-comision-nacional-de-desastres\/","title":{"rendered":"Poder Ejecutivo crea la Comisi\u00f3n Nacional de Desastres"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-22879\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_709_palacio_nacional468789.jpg\" width=\"400\" height=\"249\" alt=\"709_palacio_nacional468789\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_709_palacio_nacional468789.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_709_palacio_nacional468789-300x186.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Santo Domingo. El presidente Danilo Medina cre\u00f3, mediante el decreto No. 18-13, la Comisi\u00f3n Nacional de Desastres Naturales, que tendr\u00e1 la responsabilidad de planificar, dirigir, organizar, coordinar, ejecutar y evaluar los pilares fundamentales de la Iniciativa HOPEFOR, encaminada a dar respuesta a desastres naturales a gran escala.<\/p>\n<p>  <!--more-->  <\/p>\n<p><strong>La Comisi\u00f3n deber\u00e1 asumir la organizaci\u00f3n de un taller internacional para presentar la referida iniciativa a los pa\u00edses del Caribe Insular y organizar, dirigir y supervisar los trabajos de la Tercera Conferencia Internacional de Iniciativa HOPEFOR, a celebrarse el pa\u00eds en diciembre de este a\u00f1o.<\/strong><\/p>\n<p>De acuerdo al art\u00edculo dos del decreto la Comisi\u00f3n Nacional de Desastres Naturales la preside el Ministerio de la Presidencia, y la integran los ministerios de las Fuerzas Armadas, de Relaciones Exteriores y Medio Ambiente y Recursos Naturales, el Centro de Operaciones de Emergencia y la Defensa Civil.<\/p>\n<p>El art\u00edculo 6 del decreto firmado por el Presidente Medina instruye a la comisi\u00f3n a presentar un reglamento de operaciones en un plazo no mayor de 90 d\u00edas, a partir de la fecha.<\/p>\n<p><strong>Los recursos econ\u00f3micos para la gesti\u00f3n de la Iniciativa HOPEFOR ser\u00e1n aportados por la Presidencia de la Rep\u00fablica, y la comisi\u00f3n podr\u00e1 reclutar y contratar el personal nacional o internacional necesario para cumplir los objetivos previstos.<\/strong><\/p>\n<p>Entre los pilares fundamentales de la Iniciativa HOPEFOR se encuentran dise\u00f1ar y establecer un Plan de entrenamientos para actores civiles y militares envueltos en las operaciones de socorro; mejorar las capacidades operativas de la regi\u00f3n, elaborar un modelo de prevenci\u00f3n de desastres y crear e implementar un Centro Regional de Excelencia.<\/p>\n<p><strong>La Iniciativa HOPEFOR tiene como objetivo mejorar la coordinaci\u00f3n c\u00edvico militar y asegurar que los recursos militares y de la defensa civil se utilicen de manera apropiada, eficaz y coordinada, de conformidad con el derecho internacional humanitario.<\/strong><\/p>\n<p>La misma fue creada mediante resoluci\u00f3n de la Asamblea General de las Naciones Unidas e impulsada por Rep\u00fablica Dominicana, Turqu\u00eda y Qatar.<\/p>\n<p><a href=\"http:\/\/www.ensegundos.net\/2013\/01\/17\/poder-ejecutivo-crea-la-comision-nacional-de-desastres\/\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. El presidente Danilo Medina cre\u00f3, mediante el decreto No. 18-13, la Comisi\u00f3n Nacional de Desastres Naturales, que tendr\u00e1 la responsabilidad de planificar, dirigir, organizar, coordinar, ejecutar y evaluar los pilares fundamentales de la Iniciativa HOPEFOR, encaminada a dar respuesta a desastres naturales a gran escala.<\/p>\n","protected":false},"author":3,"featured_media":22879,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-22880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=22880"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/22880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/22879"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=22880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=22880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=22880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}