{"id":23019,"date":"2013-01-22T23:44:47","date_gmt":"2013-01-23T03:44:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/en-10-anos-los-virus-destruiran-equipos-tambien-fisicamente-kaspersky\/"},"modified":"2013-01-22T23:44:47","modified_gmt":"2013-01-23T03:44:47","slug":"en-10-anos-los-virus-destruiran-equipos-tambien-fisicamente-kaspersky","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/en-10-anos-los-virus-destruiran-equipos-tambien-fisicamente-kaspersky\/","title":{"rendered":"En 10 a\u00f1os los virus destruir\u00e1n equipos tambi\u00e9n f\u00edsicamente: Kaspersky"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-23018\" alt=\"virus_pc_fisico\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_virus_pc_fisico.png\" width=\"450\" height=\"300\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_virus_pc_fisico.png 450w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_virus_pc_fisico-300x200.png 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/>Los virus inform\u00e1ticos ser\u00e1n capaces en diez a\u00f1os de destruir equipos tambi\u00e9n f\u00edsicamente, sostuvo el fundador y consejero delegado de la firma de seguridad inform\u00e1tica Kaserpky Lab, Eugene Kasperky, en el marco de la conferencia sobre innovaci\u00f3n DLD13 que se celebra en M\u00fanich, en el sur de Alemania. <!--more--> <\/p>\n<p> Las tecnolog\u00edas para internet evolucionan a un ritmo vertiginoso, indic\u00f3 el experto ruso, quien agreg\u00f3 que \u201clamentablemente tambi\u00e9n las amenazas cibern\u00e9ticas se desarrollan a la misma velocidad\u201d.<\/p>\n<p>Los centros penitenciarios en Estados Unidos, por ejemplo, est\u00e1n conectados a la red y ser\u00eda factible que los reos pudieran abrir las puertas de las c\u00e1rceles a trav\u00e9s de sus tel\u00e9fonos m\u00f3viles inteligentes, dijo.<\/p>\n<p>El sistema es muy vulnerable y los programas cada vez m\u00e1s sofisticados, destac\u00f3.<\/p>\n<p>Si un delincuente com\u00fan es como una bicicleta, los virus como el programa de espionaje \u201cOctubre rojo\u201d, recientemente descubierto, es como una estaci\u00f3n espacial, se\u00f1al\u00f3.<\/p>\n<p>El experto en seguridad inform\u00e1tica admiti\u00f3 que desconoce el origen de estos virus, pero subray\u00f3 que \u201caunque los ataques vengan de \u2018los buenos\u2019, contin\u00faan siendo ataques\u201d.<\/p>\n<p>Las amenazas que se desprenden de los programas maliciosos modernos son comparables a ataques terroristas, agreg\u00f3.<\/p>\n<p>En tanto, el experto en virus inform\u00e1ticos Mikko Hypponen, de la firma F-Secure Corporation, se\u00f1al\u00f3 que en un futuro las guerras se dirigir\u00e1n tambi\u00e9n desde los ordenadores, al tiempo que indic\u00f3 que el potencial destructor de los programas maliciosos es inmenso y absolutamente comparable al de las armas tradicionales.<\/p>\n<p>Seg\u00fan el especialista, \u201cla guerra cibern\u00e9tica se dirige contra las infraestructuras\u201d, por lo que es totalmente factible que los virus alteren el funcionamiento de centrales energ\u00e9ticas e instalaciones industriales, con consecuencias imprevisibles.<\/p>\n<p>\u201cAntes de disparar armas se optar\u00e1 por ataques cibern\u00e9ticos contra el suministro el\u00e9ctrico y de agua\u201d, se\u00f1al\u00f3 Hypponen al pronosticar que la guerra v\u00eda internet se convertir\u00e1 en parte del enfrentamiento.<\/p>\n<p>Hace unos a\u00f1os, el gusano Stuxnet, capaz de atacar instalaciones industriales de forma selectiva, puso en alerta a los expertos en seguridad inform\u00e1tica, record\u00f3.<\/p>\n<p>Seg\u00fan los expertos, el virus hab\u00eda sido desarrollado por servicios secretos occidentales para sabotear el programa nuclear iran\u00ed.<\/p>\n<p>La novena edici\u00f3n de la DLD (Digital Life Design), una de las principales conferencias a nivel internacional del entorno digital, se celebra en la capital b\u00e1vara entre los d\u00edas 20 y 22.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los virus inform\u00e1ticos ser\u00e1n capaces en diez a\u00f1os de destruir equipos tambi\u00e9n f\u00edsicamente, sostuvo el fundador y consejero delegado de la firma de seguridad inform\u00e1tica Kaserpky Lab, Eugene Kasperky, en el marco de la conferencia sobre innovaci\u00f3n DLD13 que se celebra en M\u00fanich, en el sur de Alemania.<\/p>\n","protected":false},"author":3,"featured_media":23018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23019"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23018"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}