{"id":23061,"date":"2013-01-24T15:30:21","date_gmt":"2013-01-24T19:30:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ique-tipo-de-hombre-buscan-las-mujeres\/"},"modified":"2013-01-24T15:30:21","modified_gmt":"2013-01-24T19:30:21","slug":"ique-tipo-de-hombre-buscan-las-mujeres","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ique-tipo-de-hombre-buscan-las-mujeres\/","title":{"rendered":"\u00bfQu\u00e9 tipo de hombre buscan las mujeres?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-23060\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_pareja-300x203.jpg\" width=\"300\" height=\"203\" alt=\"pareja-300x203\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_pareja-300x203.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_pareja-300x203-75x52.jpg 75w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>A las mujeres les gustan los hombres. Esta frase que parece tan b\u00e1sica esconde uno de los m\u00e1s grandes secretos para tener \u00e9xito con las mujeres.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<p>Solo hay que saber descifrarlo y, para eso, debemos ir al significado profundo de la palabra \u201chombre\u201d, dice el escritor Fabio Fusaro.<\/p>\n<p>Seg\u00fan el diccionario, \u201chombre\u201d significa:&nbsp;\u201cSer racional perteneciente al g\u00e9nero humano. Criatura racional del sexo masculino\u201d.&nbsp;<\/p>\n<p>Ok\u2026 ese es el significado \u201cliteral\u201d de la palabra, pero profundicemos un poco.<\/p>\n<p>Un travesti es un hombre.<\/p>\n<p><strong>\u00bfSe enamoran habitualmente las mujeres de los travestis?<\/strong><\/p>\n<p>No.<\/p>\n<p>Un cobarde es un hombre.<\/p>\n<p><strong>\u00bfSe enamoran habitualmente las mujeres de los cobardes?<\/strong><\/p>\n<p>No.<\/p>\n<p>Entonces, la definici\u00f3n \u201ca las mujeres les gustan los hombres\u201d no apunta al sentido literal de la palabra \u201chombre\u201d como sustantivo, sino como adjetivo.<\/p>\n<p>Y, como adjetivo, la palabra \u201chombre\u201d define solamente a \u201ccierto tipo de seres humanos de sexo masculino\u201d.<\/p>\n<p>Diferenciemos entonces el sustantivo \u201chombre\u201d del adjetivo \u201chombre\u201d y llamemos a este \u00faltimo \u201cverdadero hombre\u201d.&nbsp;<\/p>\n<\/p>\n<p>El verdadero hombre no solo se diferencia del sexo femenino por tener pene, sino que\u2026<\/p>\n<p>* El verdadero hombre tiene orgullo, dignidad y amor propio.<\/p>\n<p>* El verdadero hombre no se somete a humillaciones.<\/p>\n<p>* El verdadero hombre sabe decir \u201cbasta\u201d.<\/p>\n<p>* El verdadero hombre no depende de nadie para vivir.<\/p>\n<p>* El verdadero hombre no suplica atenci\u00f3n, no mendiga amor.<\/p>\n<p>* El verdadero hombre jam\u00e1s es digno de l\u00e1stima.<\/p>\n<p>* El verdadero hombre cuando cae se levanta y, aunque herido, sigue adelante.<\/p>\n<p>* El verdadero hombre se fortalece con el sufrimiento.<\/p>\n<p>* El verdadero hombre conf\u00eda en s\u00ed mismo.<\/p>\n<p>* El verdadero hombre sabe lo que vale y hace respetar ese precio.<\/p>\n<p>* El verdadero hombre no le quita la vista a la realidad por dolorosa que sea.<\/p>\n<p>* El verdadero hombre ama, pero no es esclavo de ese amor.<\/p>\n<p>* El verdadero hombre no permite que jueguen con \u00e9l.<\/p>\n<p>Para los muchachos que est\u00e9n leyendo esto\u2026<\/p>\n<p>A cada uno de ustedes le cabe la definici\u00f3n de hombre como sustantivo. \u00bfLes cabe tambi\u00e9n la definici\u00f3n de hombre como adjetivo? Si la respuesta es no, les tengo una buena noticia: Los hombres nacen. Los verdaderos hombres se hacen.<\/p>\n<p>Por Fabio Fusaro, escritor y counselor. Autor de los libros \u201cMi novia \u2013 Manual de instrucciones\u201d, \u201cLa mujer de tus sue\u00f1os\u201d y \u201cMi ex\u2013novia\u201d. www.fabiofusaro.com, entremujeres.com.<\/p>\n<div><ins><\/ins><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A las mujeres les gustan los hombres. Esta frase que parece tan b\u00e1sica esconde uno de los m\u00e1s grandes secretos para tener \u00e9xito con las mujeres.&nbsp;<\/p>\n","protected":false},"author":3,"featured_media":23060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-23061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23061"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23060"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}