{"id":23078,"date":"2013-01-24T23:20:37","date_gmt":"2013-01-25T03:20:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/mas-informaciones-sobre-la-secuela-del-film-qlos-mercenarios-3q\/"},"modified":"2013-01-24T23:20:37","modified_gmt":"2013-01-25T03:20:37","slug":"mas-informaciones-sobre-la-secuela-del-film-qlos-mercenarios-3q","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/mas-informaciones-sobre-la-secuela-del-film-qlos-mercenarios-3q\/","title":{"rendered":"M\u00e1s informaciones sobre la secuela del Film \u00abLos Mercenarios 3\u00bb"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-23077\" alt=\"los-mercenarios-3-rodaje\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_los-mercenarios-3-rodaje.jpg\" width=\"640\" height=\"256\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_los-mercenarios-3-rodaje.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_los-mercenarios-3-rodaje-300x120.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>Sylvester Stallone ya pensaba en rodar Los mercenarios 3 cuando la segunda parte aun no hab\u00eda llegado a los cines. Y es que es de esperar que una franquicia con tantos \u00eddolos de las peliculas de acci\u00f3n produzca m\u00e1s secuelas, y m\u00e1s si cosecha los buenos resultados en taquilla de Los mercenarios 2.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Algunos detalles del rodaje y del reparto han sido revelados por Dolph Lundgren en sus \u00faltimas declaraciones a un medio norteamericano: \u201cCreo que el rodaje no empezar\u00e1 hasta el pr\u00f3ximo oto\u00f1o. Adem\u00e1s, estoy haciendo esto otra cosa. Tengo esta serie de TV, se llama Rescue 3, tengo que hacer eso primero. Me tomar\u00e1 seis o siete meses de este a\u00f1o, por lo menos hasta septiembre y como tengo entendido, Los mercenarios 3 no estar\u00e1 listo hasta oto\u00f1o\u201d, y a\u00f1ad\u00eda: \u201cNo s\u00e9 nada a ciencia cierta. He o\u00eddo decir que quieren Wesley Snipes y a Nicolas Cage. Los nombres son bastante importantes. Son buenos actores, y creo que a los fans les encantar\u00eda verlos con el resto de nosotros\u201d.<\/p>\n<p>Dolph Lundgren tambi\u00e9n habl\u00f3 de la libertad que les concede Stallone a la hora de interpretar y modificar sus personajes a la hora de rodar: \u201cHemos trabajado juntos muchas veces. Normalmente leo el gui\u00f3n, y luego agrego algunos comentarios sobre esto o aquello. \u00c9l conoce todos los actores que participan, as\u00ed que trata de satisfacerles. Ha hecho un gran trabajo hasta ahora, por lo que conf\u00edo en \u00e9l\u201d.<\/p>\n<p>Dolph Lundgren, Jason Statham, Jet Li, (entre otros), volver\u00e1n a formar parte de los mercenarios capitaneados por el veterano Sylvester Stallone, a quien pronto veremos encarnando a un experimentado asesino a sueldo en Una bala en la cabeza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sylvester Stallone ya pensaba en rodar Los mercenarios 3 cuando la segunda parte aun no hab\u00eda llegado a los cines. Y es que es de esperar que una franquicia con tantos \u00eddolos de las peliculas de acci\u00f3n produzca m\u00e1s secuelas, y m\u00e1s si cosecha los buenos resultados en taquilla de Los mercenarios 2.<\/p>\n","protected":false},"author":3,"featured_media":23077,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23078"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23078\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23077"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}