{"id":23119,"date":"2013-01-26T04:56:30","date_gmt":"2013-01-26T08:56:30","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-leyenda-del-comic-stan-lee-empeora-de-salud\/"},"modified":"2013-01-26T04:56:30","modified_gmt":"2013-01-26T08:56:30","slug":"la-leyenda-del-comic-stan-lee-empeora-de-salud","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-leyenda-del-comic-stan-lee-empeora-de-salud\/","title":{"rendered":"La leyenda del c\u00f3mic Stan Lee empeora de salud"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-23118\" alt=\"stan-lee\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_stan-lee.jpg\" width=\"543\" height=\"324\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_stan-lee.jpg 543w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_stan-lee-300x179.jpg 300w\" sizes=\"auto, (max-width: 543px) 100vw, 543px\" \/>El creador de personajes tan rese\u00f1ables como Capit\u00e1n Am\u00e9rica, Spider-Man, Los Cuatro Fant\u00e1sticos o los X-Men cancela su aparici\u00f3n en la Amazing Arizona Comic Con.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Stan Lee no podr\u00e1 viajar este fin de semana por problemas de salud a la Amazing Arizona Comic Convention de Phoenix. El icono del c\u00f3mic ya tuvo que cancelar dos apariciones p\u00fablicas desde septiembre debido a que se estaba recuperando de una operaci\u00f3n donde le hab\u00edan implantado un marcapasos. Stan Lee es un fiel admirador de sus fans y rara vez se ha perdido la oportunidad de hacerse ver para compartir sus historias. Por ello, confiamos en que su salud mejore, ya que a sus 90 a\u00f1os de edad no est\u00e1 nada mal. \u00bfSer\u00e1 que ha adoptado los \u201cs\u00faper poderes\u201d de sus personajes?<\/p>\n<p>Stan Lee es considerado el padre de la industria del c\u00f3mic. En 1941 public\u00f3 Capit\u00e1n Am\u00e9rica y posteriormente fue nombrado editor de Timely Comicy. A partir de entonces, cre\u00f3 a otros muchos personajes como Los Cuatro Fant\u00e1sticos, Hulk y Spider-Man y tambi\u00e9n cambi\u00f3 el nombre de la editorial a Marvel Comics. Despu\u00e9s llegar\u00edan otros personajes como Iron Man, Thor o X-Men y sus h\u00e9roes se fueron asomando tambi\u00e9n al mundo televisivo para posteriormente saltar a la pantalla grande gracias a su fama. Actualmente, incluso se ha dicho que podr\u00eda hacer un cameo en Star Wars VII de J.J. Abrams.<\/p>\n<p>La primera convenci\u00f3n del c\u00f3mic de este 2013 comienza hoy, d\u00eda 25, y acaba el 27. Sin Stan Lee, pero con una programaci\u00f3n muy completa en la que se ver\u00e1n a m\u00e1s de cien creadores de historietas, numerosos productos en exposici\u00f3n y mesas redondas. Entre otros, acudir\u00e1 Jim Lee, uno de los artistas que m\u00e1s vende en los \u00faltimos tiempos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El creador de personajes tan rese\u00f1ables como Capit\u00e1n Am\u00e9rica, Spider-Man, Los Cuatro Fant\u00e1sticos o los X-Men cancela su aparici\u00f3n en la Amazing Arizona Comic Con.<\/p>\n","protected":false},"author":3,"featured_media":23118,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23119"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23118"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}