{"id":23199,"date":"2013-01-30T13:42:37","date_gmt":"2013-01-30T17:42:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/las-ventajas-y-desventajas-de-la-suscripcion-a-servicios-en-internet\/"},"modified":"2013-01-30T13:42:37","modified_gmt":"2013-01-30T17:42:37","slug":"las-ventajas-y-desventajas-de-la-suscripcion-a-servicios-en-internet","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/las-ventajas-y-desventajas-de-la-suscripcion-a-servicios-en-internet\/","title":{"rendered":"Las ventajas y desventajas de la suscripci\u00f3n a servicios en Internet"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-23198\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_tarjeta11111-660x350.jpg\" width=\"660\" height=\"350\" alt=\"tarjeta11111-660x350\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_tarjeta11111-660x350.jpg 660w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/01\/sosua_images_tarjeta11111-660x350-300x159.jpg 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/>Todo se inici\u00f3 d\u00e9cadas atr\u00e1s, cuando peri\u00f3dicos y revistas comenzaron a utilizar un modelo de suscripciones donde el cliente pagaba un monto fijo de dinero para adquirir el producto cada cierto tiempo, recibi\u00e9ndolo en la puerta de su hogar u oficina. M\u00e1s tarde, ese sistema comprob\u00f3 su \u00e9xito en los rubros de la televisi\u00f3n y telecomunicaciones, manteni\u00e9ndose hasta el d\u00eda de hoy como el m\u00e9todo preferido por la industria para proveer de servicios tangibles e intangibles a las personas.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Internet no es la excepci\u00f3n. Porque cobrarle una cuota mensual al cliente para darle servicios durante uno o m\u00e1s meses parece ser una buena f\u00f3rmula que presenta ventajas \u2013 y algunas desventajas \u2013 a los usuarios, en una industria que busca de manera desesperada conseguir algo de dinero a cambio de sus contenidos en la red, a modo de no repetir el fracaso de empresas como Blockbuster que no fueron capaces de renovarse cuando lleg\u00f3 Internet y hoy enfrentan la bancarrota.<\/p>\n<p>Netflix por el lado de las pel\u00edculas, Spotify con la m\u00fasica, Dropbox, SkyDrive, iCloud y varios m\u00e1s entregando almacenamiento de datos, Microsoft y Adobe que ahora venden sus herramientas de oficina y profesionales<a href=\"http:\/\/www.fayerwayer.com\/2013\/01\/office-2013-ya-esta-disponible-quiere-que-te-suscribas-en-lugar-de-comprar-el-software\/\" target=\"_blank\">Office y Photoshop v\u00eda suscripci\u00f3n mensual con licencia por un tiempo limitado<\/a>&nbsp;e incluso la tradicional revista Newsweek, que el 31 de diciembre de 2012 lanz\u00f3 su \u00faltimo n\u00famero impreso en papel,&nbsp;<a href=\"http:\/\/www.fayerwayer.com\/2013\/01\/revista-newsweek-estrena-su-primera-version-100-digital-con-portada-animada\/\" target=\"_blank\">ahora se volc\u00f3 por completo a un sistema de suscripci\u00f3n digital<\/a>. Todos se est\u00e1n subiendo al carro de las suscripciones y seg\u00fan la firma analista Gartner, el 40% de las empresas que venden servicios digitales estar\u00e1n utilizando este formato de pago mensual para el a\u00f1o 2015.<\/p>\n<h1>Ventajas<\/h1>\n<h2>Todo f\u00e1cil, simple y ordenado<\/h2>\n<p>Cuando se saca la tarjeta de cr\u00e9dito y se opta por confiar en una empresa para proveer de manera mensual contenidos, ellos tambi\u00e9n ser\u00e1n los encargados de mantener en orden todo lo que compremos para ofrecerlo de manera limpia y f\u00e1cil de acceder. Por ejemplo, en el caso de compa\u00f1\u00edas como Netflix o Spotify, la biblioteca de medios es gestionada por dichas empresas y su gran enfoque es la creaci\u00f3n plataformas f\u00e1ciles de utilizar, donde s\u00f3lo sea necesario entrar y presionar \u201cplay\u201d para estar disfrutando por lo que pagamos.<\/p>\n<p>A esto contribuye un dise\u00f1o en la interfaz gr\u00e1fica de usuario muy pulida, con grandes equipos de trabajo girando s\u00f3lo en garantizar que a la persona le sea f\u00e1cil y atractivo entrar al servicio. Todo est\u00e1 en manos de ellos y la mayor\u00eda de las veces el cliente ni siquiera necesita tener conocimientos en computaci\u00f3n e inform\u00e1tica para contratar contenidos basados en computadoras.<\/p>\n<h2>Accesible desde cualquier lugar<\/h2>\n<p>Cuando una empresa almacena de manera central la informaci\u00f3n, s\u00f3lo es necesario un aparato que tenga acceso a Internet para ver lo que hemos adquirido. Casi todas las compa\u00f1\u00edas est\u00e1n conscientes de que el usuario espera que sus pel\u00edculas, m\u00fasica y archivos est\u00e9n a la mano desde cualquier parte, por lo que se invierten grandes esfuerzos por proveer de herramientas para entrar a los portales y poder reproducir en un gran n\u00famero de dispositivos.<\/p>\n<p>Por ejemplo, si almacenamos documentos de trabajo o estudios en SkyDrive o Dropbox, podemos consultarlos donde sea haya Internet, sin importar si es nuestra computadora personal donde los redactamos o no, siendo posible verlo incluso a trav\u00e9s del tel\u00e9fono si es que posee conectividad a redes m\u00f3viles o WiFi, tenga el sistema operativo que tenga.<\/p>\n<h2>Un precio reducido<\/h2>\n<p>Tradicionalmente, los productos digitales se otorgan a trav\u00e9s de la venta de una \u00fanica licencia que entrega los derechos de por vida al consumidor, manteniendo la propiedad de su compra hasta siempre. Pero cuando por ejemplo se adquieren programas y herramientas como Office o Photoshop a modo de alquiler, no se cancelan cientos de d\u00f3lares de entrada y de hecho, el costo es considerablemente inferior para cuando pagamos una suscripci\u00f3n mensual.<\/p>\n<p>Esto le permite a las personas que antes no pod\u00edan pagar por el servicio acceder a \u00e9l cancelando de manera similar a las cuotas, ampliando el nicho de clientes a los que apunta la empresa.<\/p>\n<h2>Comodidad al momento de la compra<\/h2>\n<p>A\u00f1os atr\u00e1s, para alquilar una pel\u00edcula hab\u00eda que salir y encontrar el local de Blockbuster m\u00e1s cercano, llevar dinero en efectivo y a veces invertir tanto tiempo en conseguir el filme como la duraci\u00f3n del mismo. Pero en la actualidad y gracias a portales como Netflix, una vez al mes se cancela una cuota a trav\u00e9s de Internet pagando con la tarjeta de cr\u00e9dito, algo realizable desde la comodidad del hogar y a s\u00f3lo un par de clicks de distancia.<\/p>\n<h1>Desventajas<\/h1>\n<h2>Total dependencia a Internet<\/h2>\n<p>Si bien tener los datos en la nube de Internet los hace accesibles desde cualquier lugar, supone la omnipresencia de una conexi\u00f3n de datos como requisito fundamental para disfrutar los contenidos adquiridos. \u00bfY si no hay conectividad? No se puede escuchar m\u00fasica, ni ver pel\u00edculas o acceder a los documentos. Servicios no tan dependientes como aplicaciones al estilo Photoshop pueden seguir accesibles incluso estando fuera de l\u00ednea, sin embargo, la mayor\u00eda de las suscripciones son por material de entretenimiento que no queda instalado en nuestro dispositivo de manera permanente.<\/p>\n<p>Otro punto relevante es el de la velocidad de Internet. Porque si no estamos en un lugar con buena se\u00f1al para el plan de datos del smartphone, la conectividad WiFi no es lo suficientemente fuerte o simplemente no tenemos acceso a redes de alta velocidad, ser\u00e1 muy dif\u00edcil hacer una transmisi\u00f3n en tiempo real de una pel\u00edcula en alta resoluci\u00f3n, como ofrece Netflix.<\/p>\n<h2>No existe la propiedad<\/h2>\n<p>Accediendo a todo desde la red s\u00f3lo cuando lo necesitamos, no existe un sentimiento de pertenencia sobre lo que pagamos, transform\u00e1ndose en contenido desechable. Las pel\u00edculas en Netflix est\u00e1n disponibles s\u00f3lo hasta que se acaba la suscripcion, al igual que la m\u00fasica y otros contenidos. Por otro lado, si pagamos cuotas por Microsoft Office, cuando se acaba el per\u00edodo de suscripci\u00f3n el producto ya no es nuestro y no lo podemos seguir utilizando. Con este sistema nada es realmente nuestro y todo tiene fecha de vencimiento.<\/p>\n<p>Una gran desventaja asociada es el cierre a la posibilidad de compartir contenidos. Prestar un disco compacto o DVD con una buena pel\u00edcula ser\u00eda cosa del pasado bajo este sistema de pago mensual, ya que el acceso al servicio es intransferible.<\/p>\n<h2>Lo que compras ya est\u00e1 gratis<\/h2>\n<p>Una de las primeras aplicaciones que se le dio a Internet fue el compartir m\u00fasica y pel\u00edculas. M\u00e1s tarde lleg\u00f3 la pirater\u00eda. Y la prensa independiente, por la que no hay que pagar. Todos estos elementos suponen una alternativa a servicios por los que hoy se puede abrir la billetera, pero que pueden ser conseguidos sin sacar la tarjeta de cr\u00e9dito v\u00eda otros medios informales, en una pr\u00e1ctica tan antigua como la Internet misma.<\/p>\n<h2>Cat\u00e1logo limitado de contenidos<\/h2>\n<p>Espec\u00edficamente en el caso de proveedores de multimedia, el cat\u00e1logo de contenidos est\u00e1 limitado a lo que empresas como Spotify o Netflix puedan conseguir, no estando disponible \u201ctoda la m\u00fasica del mundo\u201d. Porque ellos llegan a acuerdos comerciales con las casas discogr\u00e1ficas y estudios de cine para distribuir m\u00fasica y pel\u00edculas a un costo fijo mensual, d\u00e1ndose la posibilidad de que mucho de lo que busquemos no est\u00e9 en l\u00ednea.<\/p>\n<p><a href=\"http:\/\/www.fayerwayer.com\/2013\/01\/las-ventajas-y-desventajas-de-la-suscripcion-a-servicios-en-internet\/?utm_source=feedburner&amp;utm_medium=feed&amp;utm_campaign=Feed%253A+fayerwayer+(FayerWayer)\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todo se inici\u00f3 d\u00e9cadas atr\u00e1s, cuando peri\u00f3dicos y revistas comenzaron a utilizar un modelo de suscripciones donde el cliente pagaba un monto fijo de dinero para adquirir el producto cada cierto tiempo, recibi\u00e9ndolo en la puerta de su hogar u oficina. M\u00e1s tarde, ese sistema comprob\u00f3 su \u00e9xito en los rubros de la televisi\u00f3n y telecomunicaciones, manteni\u00e9ndose hasta el d\u00eda de hoy como el m\u00e9todo preferido por la industria para proveer de servicios tangibles e intangibles a las personas.<\/p>\n","protected":false},"author":3,"featured_media":23198,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23199"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23198"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}