{"id":23354,"date":"2013-02-04T15:33:00","date_gmt":"2013-02-04T19:33:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/urgencia-online-en-loma-de-los-chivos-piden-arreglo-de-calles\/"},"modified":"2013-02-04T15:33:00","modified_gmt":"2013-02-04T19:33:00","slug":"urgencia-online-en-loma-de-los-chivos-piden-arreglo-de-calles","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/urgencia-online-en-loma-de-los-chivos-piden-arreglo-de-calles\/","title":{"rendered":"Urgencia Online: En Loma de los Chivos piden arreglo de calles"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-23353\" alt=\"loma_de_los_chivos_en_malas_condiciones\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_loma_de_los_chivos_en_malas_condiciones.jpg\" width=\"210\" height=\"120\" \/>Sos\u00faa.- Por M\u00e1ximo Reynoso. Residentes en el barrio Loma de Los Chivos en este municipio, se quejan por el mal estado de sus calles, por lo que exigen a la alcaldesa licenciada Ilana Neumann, el reacondicionamiento de estas.<\/p>\n<p>  <!--more-->  <\/p>\n<p>De acuerdo a Nicol\u00e1s Mart\u00ednez, reci\u00e9n electo presidente de la Junta de Vecinos de esa comunidad, estos han sido olvidados por las autoridades ya que las v\u00edas est\u00e1n intransitables y cuando llueve el problema se complica.<\/p>\n<p>Yo espero que sea una buena noticia, que nos de la alcaldesa Ilana en las pr\u00f3ximas horas\u201c, dijo Mart\u00ednez. Aseguro que en diversas ocasiones se han reunido con el encargado de caminos vecinales del cabildo, quien les ha prometido que pasadas las lluvias proceder\u00edan a reacondicionar esas calles.<\/p>\n<p>[<a href=\"http:\/\/cnntv3.tv\/tv\/index.php\/k2-component\/regionales\/915-en-loma-de-los-chivos-piden-arreglo-de-calles\">Fuente<\/a>]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- Por M\u00e1ximo Reynoso. Residentes en el barrio Loma de Los Chivos en este municipio, se quejan por el mal estado de sus calles, por lo que exigen a la alcaldesa licenciada Ilana Neumann, el reacondicionamiento de estas.<\/p>\n","protected":false},"author":3,"featured_media":23353,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23354"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23353"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}