{"id":23371,"date":"2013-02-05T15:25:05","date_gmt":"2013-02-05T19:25:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/receta-de-pastel-de-pescado\/"},"modified":"2013-02-05T15:25:05","modified_gmt":"2013-02-05T19:25:05","slug":"receta-de-pastel-de-pescado","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/receta-de-pastel-de-pescado\/","title":{"rendered":"Receta de pastel de pescado"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-23370\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_119_pastel_de_pescado.jpg\" width=\"361\" height=\"257\" alt=\"119_pastel_de_pescado\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_119_pastel_de_pescado.jpg 361w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_119_pastel_de_pescado-300x213.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_119_pastel_de_pescado-75x52.jpg 75w\" sizes=\"auto, (max-width: 361px) 100vw, 361px\" \/>El<strong>&nbsp;pastel de pescado<\/strong>&nbsp;es una receta que se puede tomar tanto fr\u00eda como caliente, acompa\u00f1ada de mayonesa, salsa rosa e incluso salsas m\u00e1s dulces y que dura varios d\u00edas bien refrigerada.<\/p>\n<p>  <!--more-->  <\/p>\n<h3>Ingredientes:<\/h3>\n<ul>\n<li>150g de pescado, perca, merluza, rape,etc.<\/li>\n<li>1 pu\u00f1ado de gambas peladas<\/li>\n<li>1 cebolleta.<\/li>\n<li>1\/2 puerro.<\/li>\n<li>4 huevos.<\/li>\n<li>200 ml. de nata liquida.<\/li>\n<li>4 cucharadas de tomate triturado.<\/li>\n<li>sal y pimienta blanca.<\/li>\n<\/ul>\n<h3>Preparaci\u00f3n:<\/h3>\n<ol>\n<li>Lo primero que debemos hacer es hervir el pescado. Para ello lo metemos en una olla con agua, una hoja de laurel, sal y dos dientes de ajo. Cuando comience a hervir dejamos 2 minutos y ponemos a escurrir.<\/li>\n<li>Mientras se cuece el pescado vamos cortando la cebolleta y el puerro en finas l\u00e1minas. Despu\u00e9s las sofre\u00edmos en la sart\u00e9n hasta que la cebolleta se oscurezca un poco y quede pochada y entonces a\u00f1adimos el tomate triturado, dejando que se haga durante unos 10 minutos m\u00e1s. A\u00f1adimos las gambas y dejamos durante un par de minutos m\u00e1s removiendo a veces.<\/li>\n<li>Conforme se hace el sofrito batimos los huevos con la nata l\u00edquida en un bol grande hasta que quede una masa uniforme y desmenuzamos el pescado. Entonces a\u00f1adimos al bol de la nata y huevo el sofrito y removemos hasta que quede una masa unificada, en la que a\u00f1adimos por \u00faltimo el pescado.<\/li>\n<li>Ya solo queda poner la mezcla en el molde que vayamos a usar, con una capita de mantequilla y harina para que no se pegue y meterno en el horno precalentado a 180\u00ba durante unos 40 minutos.<\/li>\n<\/ol>\n<p><a href=\"http:\/\/www.siempretop.com\/receta-de-pastel-de-pescado-2\/\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El&nbsp;pastel de pescado&nbsp;es una receta que se puede tomar tanto fr\u00eda como caliente, acompa\u00f1ada de mayonesa, salsa rosa e incluso salsas m\u00e1s dulces y que dura varios d\u00edas bien refrigerada.<\/p>\n","protected":false},"author":3,"featured_media":23370,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23371"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23370"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}