{"id":23498,"date":"2013-02-09T20:31:34","date_gmt":"2013-02-10T00:31:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ensalada-templada-de-frutas-y-langostinos\/"},"modified":"2013-02-09T20:31:34","modified_gmt":"2013-02-10T00:31:34","slug":"ensalada-templada-de-frutas-y-langostinos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ensalada-templada-de-frutas-y-langostinos\/","title":{"rendered":"Ensalada templada de frutas y langostinos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-23497\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_ensalada-templada-de-frutas-y-langostinos.jpg\" width=\"570\" height=\"356\" alt=\"ensalada-templada-de-frutas-y-langostinos\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_ensalada-templada-de-frutas-y-langostinos.jpg 570w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_ensalada-templada-de-frutas-y-langostinos-300x187.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_ensalada-templada-de-frutas-y-langostinos-400x250.jpg 400w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/>Parece que durante la \u00e9poca de fr\u00edo las&nbsp;<a href=\"http:\/\/www.lasrecetascocina.com\/category\/ensaladas\/\" target=\"_blank\">ensaladas<\/a>&nbsp;tienen menos \u00e9xito en nuestra mesa, por eso yo acostumbro a hacer ensaladas templadas en \u00e9ste tiempo. Hoy les traigo una&nbsp;<strong>ensalada templada<\/strong>&nbsp;de frutas tropicales y langostinos que queda perfecta para \u00e9sta \u00e9poca.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00c9sta ensalada puedes ponerla como centro de mesa para compartir o como un primer plato acompa\u00f1\u00e1ndolo de un segundo plato un poco m\u00e1s fuerte como unas&nbsp;<a href=\"http:\/\/www.lasrecetascocina.com\/2012\/11\/19\/costillas-de-cordero-a-la-miel\/\" target=\"_blank\">costillas de cordero<\/a>&nbsp;o unas&nbsp;<a href=\"http:\/\/www.lasrecetascocina.com\/2012\/12\/09\/carrilleras-de-ternera-en-salsa-de-oporto\/\" target=\"_blank\">carrilleras de ternera<\/a>.<\/p>\n<h2>Ingredientes \u2013 4 raciones &#8211;<\/h2>\n<ul>\n<li>1 bolsa de mezcla de lechugas tiernas<\/li>\n<li>1 tomate<\/li>\n<li>sal<\/li>\n<li>1 granada<\/li>\n<li>1 pi\u00f1a (o media en funci\u00f3n de su tama\u00f1o)<\/li>\n<li>1 mango<\/li>\n<li>20 langostinos cocidos<\/li>\n<li>aceite de oliva<\/li>\n<\/ul>\n<p><strong>Para el ali\u00f1o<\/strong><\/p>\n<ul>\n<li>1 pu\u00f1ado de pasas sin pepitas<\/li>\n<li>1 pu\u00f1ado de pi\u00f1ones<\/li>\n<li>aceite de oliva virgen extra<\/li>\n<li>vinagre bals\u00e1mico<\/li>\n<\/ul>\n<div>\n<h2>Preparaci\u00f3n<\/h2>\n<p>Para \u00e9sta ensalada lo primero que tenemos que hacer es&nbsp;<strong>preparar el ali\u00f1o<\/strong>&nbsp;para que las pasas y los pi\u00f1ones vayan tomando sabor y se engorden un poquito. Para ello ponemos en un baso las pasas y los pi\u00f1ones y les cubrimos con el aceite y el vinagre bals\u00e1mico al gusto. Si nos acordamos de hacerlo<strong>&nbsp;una hora antes<\/strong>&nbsp;de preparar la ensalada, mejor, ya que las pasas quedar\u00e1n bien remojadas.<\/p>\n<p>En una fuente ponemos la lechuga y por encima el tomate,&nbsp;<strong>salamos&nbsp;y removemos<\/strong>&nbsp;para que cojas bien la sal.<\/p>\n<p>Pelamos la&nbsp;<strong>granada<\/strong>&nbsp;y a\u00f1adimos los granos limpios a la ensalada como se puede ver en la foto.<\/p>\n<p>Agregamos el ali\u00f1o que ten\u00edamos reposando con cuidado de repartir bien las pasas y pi\u00f1ones para que nos quede uniforme.&nbsp;<strong>Reservar un poco del jugo<\/strong>&nbsp;para el ali\u00f1o del final.<\/p>\n<p>Ahora vamos a&nbsp;<strong>hacer las frutas<\/strong>. Pelamos y hacemos trocitos peque\u00f1os la pi\u00f1a. En una sart\u00e9n untamos con una brocha de cocina un poco de aceite y lo ponemos al fuego. Cuando la sart\u00e9n est\u00e9 bien caliente a\u00f1adimos la pi\u00f1a y la vamos dando vueltas hasta que est\u00e9 bien fritita. Hacerla a medio gas con cuidado de que no se queme.<\/p>\n<p><strong>A\u00f1adimos la pi\u00f1a<\/strong>&nbsp;a la ensalada.<\/p>\n<p><strong>Consejo:<\/strong>&nbsp;Si cuando comes pi\u00f1a te pica la boca ver\u00e1s que si la fr\u00edes un poco \u00e9sto ya no pasa. A mi me suele picar la boca cuando la como pero de \u00e9sta manera la puedo comer perfectamente y ni noto el picor.<\/p>\n<p>Pelamos y partimos el mango en trocitos. Si al hacer la pi\u00f1a se os queda la sart\u00e9n un poco negra lo mejor es que la laves o que lo quites con papel de cocina. Ponemos un poco de aceite en la sart\u00e9n con una brocha de cocina y seguimos el mismo proceso que con la pi\u00f1a en el paso anterior. Cuando&nbsp;<strong>el mango est\u00e9 dorado<\/strong>&nbsp;lo a\u00f1adimos a la ensalada.<\/p>\n<p>Por \u00faltimo&nbsp;<strong>pelamos los langostinos cocidos<\/strong>&nbsp;y les damos un par de vueltas en la sart\u00e9n para templarlos y dorarlos (2 minutos). Los a\u00f1adimos por encima a la ensalada.<\/p>\n<p>Por \u00faltimo agregamos<strong>&nbsp;el jugo del ali\u00f1o<\/strong>&nbsp;que nos hab\u00eda sobrado al principio. En caso de que no nos sobrase nada agregamos un poco de aceite y vinagre por encima.<\/p>\n<p>\u00a1A disfrutar!<\/p>\n<p><strong>Grado de dificultad:<\/strong>&nbsp;F\u00e1cil<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Parece que durante la \u00e9poca de fr\u00edo las&nbsp;ensaladas&nbsp;tienen menos \u00e9xito en nuestra mesa, por eso yo acostumbro a hacer ensaladas templadas en \u00e9ste tiempo. Hoy les traigo una&nbsp;ensalada templada&nbsp;de frutas tropicales y langostinos que queda perfecta para \u00e9sta \u00e9poca.<\/p>\n","protected":false},"author":3,"featured_media":23497,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23498"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23497"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}