{"id":23550,"date":"2013-02-12T14:58:57","date_gmt":"2013-02-12T18:58:57","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/conozca-las-empresas-que-microsoft-ha-comprado\/"},"modified":"2013-02-12T14:58:57","modified_gmt":"2013-02-12T18:58:57","slug":"conozca-las-empresas-que-microsoft-ha-comprado","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/conozca-las-empresas-que-microsoft-ha-comprado\/","title":{"rendered":"Conozca las empresas que Microsoft ha comprado"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-17976\" alt=\"Microsoft-Logo-on-Wall\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/06\/sosua_images_Microsoft-Logo-on-Wall.jpg\" width=\"600\" height=\"376\" \/>Microsoft Corporation es una empresa multinacional de origen estadounidense, fundada el 4 de abril de 1975 por Bill Gates y Paul Allen. A continuaci\u00f3n mostraremos las empresa que Microsoft a comprado o invertido dinero.<\/p>\n<p>  <!--more--> <!-- Quick Adsense WordPress Plugin: http:\/\/quicksense.net\/ --> <\/p>\n<div><\/div>\n<p><strong>Nook : <\/strong>El a\u00f1o pasado acord\u00f3 invertir 605 millones en el negocio de lectores digitales y libros de texto universitarios de Barnes &amp; Noble Inc a lo largo de cinco a\u00f1os. El dispositivo Nook todav\u00eda est\u00e1 lejos de alcanzar el liderazgo del mercado que tiene Kindle, de Amazon.com Inc.<\/p>\n<p><strong>Skype<\/strong><\/p>\n<p>En mayo del 2011, sell\u00f3 un acuerdo para comprar la compa\u00f1\u00eda de video chat Skype por 8,500 millones de d\u00f3lares. El precio fue considerado alto en aquel momento, pero a\u00fan sigue siendo demasiado pronto para juzgar el \u00e9xito de la transacci\u00f3n.<\/p>\n<p><strong>Nokia<\/strong><\/p>\n<p>Microsoft ha pagado m\u00e1s de 1,000 millones de d\u00f3lares a Nokia desde que en el 2011 el fabricante finland\u00e9s de dispositivos m\u00f3viles acord\u00f3 fabricar tel\u00e9fonos que utilicen el software Windows.<\/p>\n<p>Las recompensas para Microsoft en regal\u00edas han sido decepcionantes, ya que los tel\u00e9fonos con Windows no han hecho mella en el dominio de mercado que tienen el iPhone de Apple Inc y los aparatos que usan el software Android de Google Inc.<\/p>\n<p><strong> Yahoo<\/strong><\/p>\n<p>Despu\u00e9s de no haber podido adquirir al gigante de Internet en el 2008, Microsoft firm\u00f3 un contrato por 10 a\u00f1os para proveer servicios de b\u00fasqueda en la web para Yahoo a cambio de una parte de los ingresos por publicidad. Hasta el momento, el acuerdo ha decepcionado a ambas empresas.<\/p>\n<p><strong>Danger<\/strong><\/p>\n<p>Seg\u00fan reportes, pag\u00f3 500 millones de d\u00f3lares por el moderno dise\u00f1ador de <em>smartphones<\/em><i> <\/i>en el 2008, pero la mayor\u00eda del personal abandon\u00f3 la empresa y la experiencia termin\u00f3 mal con el desastroso tel\u00e9fono Kin.<\/p>\n<p><strong>Facebook<\/strong><\/p>\n<p>Microsoft dio un gran golpe con la compra de una participaci\u00f3n del 1.6% en la red social por 240 millones de d\u00f3lares en el 2007. La participaci\u00f3n hoy vale mucho m\u00e1s y allan\u00f3 el camino para una cooperaci\u00f3n entre Facebook Inc y el programa de correo electr\u00f3nico Outlook y el motor de b\u00fasqueda Bing, ambos de Microsoft.<\/p>\n<p><strong>Aquantive<\/strong><\/p>\n<p>Microsoft pag\u00f3 6,300 millones de d\u00f3lares en efectivo por la compa\u00f1\u00eda de publicidad online en el 2007 y amortiz\u00f3 casi toda esa cantidad en el 2012, al admitir efectivamente que la inversi\u00f3n hab\u00eda perdido su valor.<\/p>\n<p><strong>Great plains\/Navision<\/strong><\/p>\n<p>La adquisici\u00f3n de estas dos compa\u00f1\u00edas en 2001 y 2002, respectivamente, deriv\u00f3 en la fundaci\u00f3n del negocio de software corporativo de Microsoft y es considerada un \u00e9xito.<\/p>\n<p><strong>Korea Telecom<\/strong><\/p>\n<p>Acord\u00f3 invertir 500 millones de d\u00f3lares por una participaci\u00f3n en la empresa de telecomunicaciones que es propiedad del Gobierno surcoreano en el 2001, con la esperanza de dejar su huella en uno de los mercados de internet m\u00e1s avanzados a cambio de una recompensa incierta.<\/p>\n<p><strong>Bungie<\/strong><\/p>\n<p>Pag\u00f3 solo decenas de millones de d\u00f3lares por el estudio productor de juegos Bungie, creador del exitoso Halo, en el 2000. Bungie eventualmente se separ\u00f3 de la compa\u00f1\u00eda, pero Microsoft mantuvo la lucrativa franquicia Halo.<\/p>\n<p><strong>AT&amp;T<\/strong><\/p>\n<p>En 1999, Microsoft compr\u00f3 5,000 millones de d\u00f3lares en acciones del gigante telef\u00f3nico AT&amp;T Inc con el objetivo de ubicar al software Windows en el segmento de decodificadores, pero no logr\u00f3 la entrada deseada en el emergente mercado de banda ancha por cable.<\/p>\n<p><strong>Apple<\/strong><\/p>\n<p>Invirti\u00f3 150 millones de d\u00f3lares en Apple en 1997, cuando la compa\u00f1\u00eda atravesaba problemas, y se comprometi\u00f3 a producir el software para la todav\u00eda poco popular Mac. El acuerdo puso fin a una extensa disputa por patentes entre las dos firmas, pero podr\u00eda decirse que salv\u00f3 a Apple y la coloc\u00f3 camino a eclipsar a Microsoft en t\u00e9rminos financieros.<\/p>\n<p><strong>Comcast<\/strong><\/p>\n<p>Invirti\u00f3 1,000 millones de d\u00f3lares en acciones en el proveedor de cable Comcast Corp en 1997 para poder desarrollar servicios de video y transmisi\u00f3n de datos a alta velocidad. La visi\u00f3n de Bill Gates de conectar la computadora y la televisi\u00f3n tard\u00f3 en materializarse y Microsoft vendi\u00f3 la participaci\u00f3n 12 a\u00f1os despu\u00e9s.<\/p>\n<p>Visto en: <a href=\"http:\/\/www.audienciaelectronica.net\/2013\/02\/10\/conozca-las-empresas-que-microsoft-ha-comprado\/\">http:\/\/www.audienciaelectronica.net\/2013\/02\/10\/conozca-las-empresas-que-microsoft-ha-comprado\/<\/a><br \/><a href=\"http:\/\/www.cnnexpansion.com\/negocios\/2013\/02\/06\/nook\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft Corporation es una empresa multinacional de origen estadounidense, fundada el 4 de abril de 1975 por Bill Gates y Paul Allen. A continuaci\u00f3n mostraremos las empresa que Microsoft a comprado o invertido dinero.<\/p>\n","protected":false},"author":3,"featured_media":17976,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23550"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17976"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}