{"id":23566,"date":"2013-02-12T16:22:17","date_gmt":"2013-02-12T20:22:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/presentan-dos-nuevos-modelos-de-vehiculos-urbanos-del-futuro\/"},"modified":"2013-02-12T16:22:17","modified_gmt":"2013-02-12T20:22:17","slug":"presentan-dos-nuevos-modelos-de-vehiculos-urbanos-del-futuro","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/presentan-dos-nuevos-modelos-de-vehiculos-urbanos-del-futuro\/","title":{"rendered":"Presentan dos nuevos modelos de veh\u00edculos urbanos del futuro"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-23565\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_moto1_del_futuro234546.png\" width=\"620\" height=\"350\" alt=\"moto1_del_futuro234546\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_moto1_del_futuro234546.png 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_moto1_del_futuro234546-300x169.png 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/>La tendencia del transportes ligeros y con sistema el\u00e9ctrico ha incrementado en todo el mundo y esta vez son dos nuevos modelos los que pretenden revolucionar el transporte del futuro.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El primero es Moveo, una motocicleta el\u00e9ctrica, plegable y con un peso de 25 kilos que la hace c\u00f3moda y liviana para poder transportarla. Funciona a trav\u00e9s de una bater\u00eda que se recarga en una hora, con un rendimiento de 35 kil\u00f3metros.<\/p>\n<p>Se estima que la firma h\u00fangara Antro comenzar\u00eda a vender Moveo desde el pr\u00f3ximo a\u00f1o a un precio entre 3.100 y 4.600 d\u00f3lares ( entre 1 mill\u00f3n y medio y 2 millones de pesos chilenos).<\/p>\n<p>El otro modelo es el monociclo de la empresa canadiense Ryno Motors, un veh\u00edculo el\u00e9ctrico con sistema de autobalenceo que mantiene el equilibrio mientras se conduce.<\/p>\n<p>Ya est\u00e1 disponible su versi\u00f3n limitada de pre-producci\u00f3n a un precio de 25 mil d\u00f3lares (alrededor de 12 millones de pesos).<\/p>\n<p>Adem\u00e1s, al ser veh\u00edculos con sistema el\u00e9ctrico tienen la caracter\u00edstica ambiental de contaminar menos que el trasporte tradicional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tendencia del transportes ligeros y con sistema el\u00e9ctrico ha incrementado en todo el mundo y esta vez son dos nuevos modelos los que pretenden revolucionar el transporte del futuro.<\/p>\n","protected":false},"author":3,"featured_media":23565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23566"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23565"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}