{"id":23585,"date":"2013-02-13T15:29:46","date_gmt":"2013-02-13T19:29:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/yankees-comienzan-entrenamientos-con-vista-puesta-en-titulo-de-serie-mundial\/"},"modified":"2013-02-13T15:29:46","modified_gmt":"2013-02-13T19:29:46","slug":"yankees-comienzan-entrenamientos-con-vista-puesta-en-titulo-de-serie-mundial","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/yankees-comienzan-entrenamientos-con-vista-puesta-en-titulo-de-serie-mundial\/","title":{"rendered":"Yankees comienzan entrenamientos con vista puesta en t\u00edtulo de Serie Mundial"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-23584\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_NewYorkYankees11.jpg\" width=\"400\" height=\"300\" alt=\"NewYorkYankees11\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_NewYorkYankees11.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_NewYorkYankees11-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>TAMPA, EEUU. Los Yankees de Nueva York comenzaron sus entrenamientos de primavera ayer con la vista puesta en lograr el t\u00edtulo n\u00famero 28 de su historia en la Serie Mundial.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>La concentraci\u00f3n de lanzadores y receptores dio inicio con preguntas que rodean al estelar tercera base dominicano Alex Rodr\u00edguez, que se recupera de una cirug\u00eda de cadera y quien fue nombrado recientemente en un informe por antiguos empleados de una cl\u00ednica de Miami, que lo relacionaban con ventas de drogas para mejorar el rendimiento.<\/p>\n<p><strong>\u201cRealmente no hay mucho que hablar\u201d, dijo el m\u00e1nager de los Yankees, el piloto Joe Girardi. \u201cHe tenido mis discusiones con Alex y hablamos sobre su rehabilitaci\u00f3n. Mi preocupaci\u00f3n es conseguir que est\u00e9 saludable. Eso es lo que voy a centrarme en \u00e9l. Eso es lo que este club se centrar\u00e1. No quiero distracciones\u201d, agreg\u00f3.<\/strong><\/p>\n<p>Girardi dijo que no abordaron detalles sobre el informe hasta que den los resultados de una investigaci\u00f3n de las Grandes Ligas sobre los informes acerca de la cl\u00ednica de la biog\u00e9nesis.<\/p>\n<p>\u201cRealmente no quiero hablar sobre eso\u201d, dijo Girardi. \u201cLas Grandes Ligas tiene que pasar por lo que tienen que pasar. Hemos hablado sobre rehabilitaci\u00f3n y lo que hab\u00eda hecho durante todo el invierno\u201d, a\u00f1adi\u00f3 el piloto.<\/p>\n<p><strong>\u201cSiempre tienes curiosidad acerca de las cosas que lees acerca de que podr\u00edan ser perjudiciales para el b\u00e9isbol. Pero hay que esperar y que la Major League Baseball haga lo que tiene que hacer. Hasta que la MLB haga lo suyo, no siento la necesidad de hablar de ello\u201d, coment\u00f3.<\/strong><\/p>\n<p>Tambi\u00e9n fue nombrado en los archivos de la cl\u00ednica el receptor venezolano de 26 a\u00f1os Francisco Cervelli, quien dijo Girardi tendr\u00e1 que ignorar las preguntas y centrarse en el b\u00e9isbol.<\/p>\n<p>\u201cPor supuesto que puede pesar en su mente\u201d, apunt\u00f3 Girardi, quien agreg\u00f3 que \u201cpero eso es una distracci\u00f3n que va a tener que bloquear\u201d.<\/p>\n<p>Cervelli dijo que compr\u00f3 suplementos legales de la cl\u00ednica pero asegur\u00f3 que nunca us\u00f3 sustancias prohibidas.<\/p>\n<p><strong>Los Yankees, que perdieron por barrida de 4-0 ante Detroit en la serie de campeonato de la Liga Americana el a\u00f1o pasado, espera que el campocorto Derek Jeter est\u00e9 listo para el 1 de abril contra los Medias Rojas de Boston despu\u00e9s de haber sufrido una fractura de tobillo en los playoffs anteriores.<\/strong><\/p>\n<p>\u201cEsperamos que va a estar de vuelta en el d\u00eda de la inauguraci\u00f3n\u201d, dijo Girardi de Jeter, quien es capit\u00e1n de los \u2018Mulos\u2019. AFP<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>TAMPA, EEUU. Los Yankees de Nueva York comenzaron sus entrenamientos de primavera ayer con la vista puesta en lograr el t\u00edtulo n\u00famero 28 de su historia en la Serie Mundial.<\/p>\n","protected":false},"author":3,"featured_media":23584,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23585"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23585\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23584"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}