{"id":23791,"date":"2013-02-19T12:25:34","date_gmt":"2013-02-19T16:25:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/arranca-la-migracion-de-hotmail-a-outlook\/"},"modified":"2013-02-19T12:25:34","modified_gmt":"2013-02-19T16:25:34","slug":"arranca-la-migracion-de-hotmail-a-outlook","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/arranca-la-migracion-de-hotmail-a-outlook\/","title":{"rendered":"Arranca la migraci\u00f3n de Hotmail a Outlook"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-23790\" alt=\"de_hotmail_a_otulook\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_de_hotmail_a_otulook.jpg\" width=\"660\" height=\"350\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_de_hotmail_a_otulook.jpg 660w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_de_hotmail_a_otulook-300x159.jpg 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/>Ya es oficial: Hotmail muere. Tras largos meses de agon\u00eda mientras la gente de Microsoft afinaba los detalles para la llegada del sustituto y tras salir de la fase BETA, a partir de hoy se comienzan a migrar oficialmente las cuentas de correo electr\u00f3nico hacia Outlook.<\/p>\n<p>  <!--more-->  <\/p>\n<p>\u00bfQu\u00e9 tienes que hacer para migrar? Si tienes una cuenta de Hotmail.com o Hotmail.es puedes comenzar a utilizar Outlook.com simplemente iniciando sesi\u00f3n en http:\/\/outlook.com con los datos de tu cuenta de Hotmail (usuario y contrase\u00f1a). No hace falta que cambies tu cuenta ni que obtengas una nueva.<\/p>\n<p>Al hacerlo ver\u00e1s un cambio en la imagen y distribuci\u00f3n de tu bandeja de entrada, y recibir\u00e1s un correo electr\u00f3nico en donde te dan la bienvenida a Outlook y te cuentan algunas de las novedades que integra, as\u00ed como de las cosas que puedes hacer. As\u00ed, por ejemplo, puedes solicitar un nuevo \u201calias\u201d para tu cuenta Outlook con el cual podr\u00e1s enviar y recibir correos y guardarlo todo en carpetas independientes (control\u00e1ndolo desde la bandeja de entrada): Me parece una opci\u00f3n \u00fatil, por ejemplo para tener una direcci\u00f3n de correo \u201cseria\u201d para enviar un curriculum vitae, y otra m\u00e1s \u201cinformal\u201d para los amigos.<\/p>\n<p>Claro, que si ya que estamos de renovaci\u00f3n prefieres cambiar el nombre de tu cuenta a una direcci\u00f3n de correo electr\u00f3nico de Outlook.com, para loguearte con ella incluso, nos proponen varias opciones para lograrlo f\u00e1cilmente.<\/p>\n<p>Ahora una duda com\u00fan: \u00bfQu\u00e9 pasar\u00e1 con los contactos y los correos que nos env\u00eden a la cuenta de Hotmail.com? Pues que los seguiremos recibiendo sin mayores contratiempos seg\u00fan nos aseguran desde Microsoft en el mismo correo de bienvenida a Outlook que te mencionaba antes:<\/p>\n<p>\u201cPuedes conseguir una nueva direcci\u00f3n de correo electr\u00f3nico desde Outlook. No tienes que preocuparte por los contactos y correos electr\u00f3nicos anteriores. Los conservar\u00e1s. Y seguir\u00e1s recibiendo los mensajes que env\u00eden a tu direcci\u00f3n de Hotmail\u201d.<\/p>\n<p>En dicho mensaje tambi\u00e9n nos invitan a conectar nuestra cuenta de Outlook con los perfiles en Facebook y Twitter para que en nuestra bandeja de entrada \u201ccobre vida\u201d, dicen: La intenci\u00f3n es que puedas leer las actualizaciones de Facebook y los tweets de tus amigos directamente en la bandeja de entrada de tu correo electr\u00f3nico, de forma que te vayas enterando de todo en una misma pantalla. Buena jugada de Microsoft para terminar de atraer a los fans de las redes sociales que a\u00fan pueden estar dudando sobre la \u2018nueva\u2019 propuesta.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya es oficial: Hotmail muere. Tras largos meses de agon\u00eda mientras la gente de Microsoft afinaba los detalles para la llegada del sustituto y tras salir de la fase BETA, a partir de hoy se comienzan a migrar oficialmente las cuentas de correo electr\u00f3nico hacia Outlook.<\/p>\n","protected":false},"author":3,"featured_media":23790,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23791"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23790"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}