{"id":23804,"date":"2013-02-20T11:05:27","date_gmt":"2013-02-20T15:05:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/a-la-espera-de-un-contrato-valverde-se-une-a-equipo-rd\/"},"modified":"2013-02-20T11:05:27","modified_gmt":"2013-02-20T15:05:27","slug":"a-la-espera-de-un-contrato-valverde-se-une-a-equipo-rd","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/a-la-espera-de-un-contrato-valverde-se-une-a-equipo-rd\/","title":{"rendered":"A la espera de un contrato, Valverde se une a equipo RD"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-23803\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_A054472F-34CB-4583-8C2C-D28F77AE6FBF.jpg__294__440__CROPz0x294y440.jpeg\" width=\"294\" height=\"200\" alt=\"A054472F-34CB-4583-8C2C-D28F77AE6FBF.jpg__294__440__CROPz0x294y440\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_A054472F-34CB-4583-8C2C-D28F77AE6FBF.jpg__294__440__CROPz0x294y440.jpeg 294w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_A054472F-34CB-4583-8C2C-D28F77AE6FBF.jpg__294__440__CROPz0x294y440-75x52.jpeg 75w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/>El agente libre dominicano Jos\u00e9 Valverde a\u00fan espera firmar con un equipo de Grandes Ligas, pero por el momento el cerrojero lanzar\u00e1 por la selecci\u00f3n de su pa\u00eds en el Cl\u00e1sico Mundial de B\u00e9isbol.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Seg\u00fan la p\u00e1gina de Twitter oficial de la selecci\u00f3n dominicana, Valverde se unir\u00e1 al equipo para ser parte de un bullpen que incluye a Fernando Rodney, Octavio Dotel, Joel Peralta y Santiago Casilla, entre otros.<\/p>\n<p>Curiosamente, Dotel ser\u00eda uno de los relevistas que los Tigres contar\u00edan esta temporada para algunas oportunidades en la novena entrada tras la ausencia de Valverde. Valverde, de 34 a\u00f1os de edad, tuvo 35 salvados por Detroit la campa\u00f1a pasada, pero registr\u00f3 3.78 de efectividad y perdi\u00f3 el control en la postemporada.<\/p>\n<p>El derecho permiti\u00f3 nueve carreras merecidas en solamente 2 2\/3 entradas en un total de cuatro presentaciones en los playoffs. Sus problemas obligaron al equipo a colocar a Phil Coke como el cerrador durante la Serie de Campeonato de la Liga Americana.<\/p>\n<p>Pese a conseguir 110 rescates en 118 oportunidades durante sus tres a\u00f1os con los Tigres, incluyendo todas sus 49 oportunidades en el 2011, Detroit opt\u00f3 por no retener al tres veces convocado al Juego de Estrellas.<\/p>\n<p>En su carrera, Valverde tiene 277 rescates con un promedio de carreras limpias admitidas de 3.11 en 10 temporadas con los D-backs, Astros y Tigres.<\/p>\n<p><a href=\"http:\/\/www.listindiario.com\/\/el-deporte\/2013\/2\/20\/266594\/A-la-espera-de-un-contrato-Valverde-se-une-a-equipo-RD\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El agente libre dominicano Jos\u00e9 Valverde a\u00fan espera firmar con un equipo de Grandes Ligas, pero por el momento el cerrojero lanzar\u00e1 por la selecci\u00f3n de su pa\u00eds en el Cl\u00e1sico Mundial de B\u00e9isbol.<\/p>\n","protected":false},"author":3,"featured_media":23803,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23804","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23804"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23804\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23803"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}