{"id":23806,"date":"2013-02-20T11:10:58","date_gmt":"2013-02-20T15:10:58","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/la-sangre-puede-dar-pistas-sobre-la-perdida-de-memoria-en-la-menopausia\/"},"modified":"2013-02-20T11:10:58","modified_gmt":"2013-02-20T15:10:58","slug":"la-sangre-puede-dar-pistas-sobre-la-perdida-de-memoria-en-la-menopausia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-sangre-puede-dar-pistas-sobre-la-perdida-de-memoria-en-la-menopausia\/","title":{"rendered":"La sangre puede dar pistas sobre la p\u00e9rdida de memoria en la menopausia"},"content":{"rendered":"<p><i><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-23805\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_MENOPAUSIA4654867547yuh54.jpg\" width=\"320\" height=\"320\" alt=\"MENOPAUSIA4654867547yuh54\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_MENOPAUSIA4654867547yuh54.jpg 320w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_MENOPAUSIA4654867547yuh54-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_MENOPAUSIA4654867547yuh54-300x300.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_MENOPAUSIA4654867547yuh54-120x120.jpg 120w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/>Una nueva investigaci\u00f3n de la Cl\u00ednica Mayo (Estados Unidos) sugiere que la sangre puede tener indicios de si las mujeres posmenop\u00e1usicas corren riesgo de sufrir problemas de memoria y accidente cerebrovascular. En concreto, se trata de la tendencia de coagulaci\u00f3n de la sangre la que puede contribuir a las \u00e1reas de da\u00f1o cerebral llamadas hiperintensidades de la materia blanca, seg\u00fan el estudio publicado en la revista &#8216;Neurology&#8217;.<\/i>&nbsp;&nbsp;&nbsp; El estudio involucr\u00f3 a 95 mujeres con una edad media de 53 a\u00f1os, que recientemente hab\u00edan pasado por la menopausia y de las que se tomaron im\u00e1genes por resonancia magn\u00e9tica (IRM) al inicio del estudio. Despu\u00e9s, recibieron un placebo, la terapia hormonal oral o el parche hormonal en la piel y se les hicieron im\u00e1genes de resonancia magn\u00e9tica peri\u00f3dicamente durante los siguientes cuatro a\u00f1os.<\/p>\n<p>  <!--more-->  <\/p>\n<p>&nbsp;&nbsp; Durante la investigaci\u00f3n, las mujeres con niveles m\u00e1s altos de microves\u00edculas trombog\u00e9nicas, las plaquetas m\u00e1s propensas a causar que la sangre se coagule, ten\u00edan m\u00e1s tendencia a mayores aumentos en la cantidad de hiperintensidades de la sustancia blanca (que se muestra como concentradas \u00e1reas blancas en una imagen de resonancia magn\u00e9tica), lo que puede conducir a la p\u00e9rdida de memoria.<\/p>\n<p>\u00abEste estudio sugiere que la tendencia de la sangre a coagularse puede contribuir a una cascada de eventos que conducen al desarrollo de da\u00f1o cerebral en mujeres que recientemente han pasado por la menopausia\u00bb, explica el autor de la investigaci\u00f3n, Kejal Kantarci, MD, de la Cl\u00ednica Mayo. A su juicio, una forma de detener la progresi\u00f3n de estas hiperintensidades de la materia blanca ser\u00eda impedir que las plaquetas desarrollen estas microves\u00edculas.<\/p>\n<p>&nbsp;&nbsp; Todas las mujeres ten\u00edan hiperintensidades de la materia blanca en el inicio del estudio. La cantidad aument\u00f3 en un volumen medio de 63 mil\u00edmetros c\u00fabicos a los 18 meses; 122 mil\u00edmetros c\u00fabicos, a los tres a\u00f1os, y 155 mil\u00edmetros c\u00fabicos en cuatro a\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una nueva investigaci\u00f3n de la Cl\u00ednica Mayo (Estados Unidos) sugiere que la sangre puede tener indicios de si las mujeres posmenop\u00e1usicas corren riesgo de sufrir problemas de memoria y accidente cerebrovascular. En concreto, se trata de la tendencia de coagulaci\u00f3n de la sangre la que puede contribuir a las \u00e1reas de da\u00f1o cerebral llamadas hiperintensidades de la materia blanca, seg\u00fan el estudio publicado en la revista &#8216;Neurology&#8217;.&nbsp;&nbsp;&nbsp; El estudio involucr\u00f3 a 95 mujeres con una edad media de 53 a\u00f1os, que recientemente hab\u00edan pasado por la menopausia y de las que se tomaron im\u00e1genes por resonancia magn\u00e9tica (IRM) al inicio del estudio. Despu\u00e9s, recibieron un placebo, la terapia hormonal oral o el parche hormonal en la piel y se les hicieron im\u00e1genes de resonancia magn\u00e9tica peri\u00f3dicamente durante los siguientes cuatro a\u00f1os.<\/p>\n","protected":false},"author":3,"featured_media":23805,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23806"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23806\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23805"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}