{"id":23849,"date":"2013-02-20T22:36:28","date_gmt":"2013-02-21T02:36:28","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/google-predice-que-los-ganadores-del-oscar-este-domingo-son\/"},"modified":"2013-02-20T22:36:28","modified_gmt":"2013-02-21T02:36:28","slug":"google-predice-que-los-ganadores-del-oscar-este-domingo-son","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/google-predice-que-los-ganadores-del-oscar-este-domingo-son\/","title":{"rendered":"Google predice que los ganadores del Oscar este domingo son\u2026"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-23848\" alt=\"google_en_el_oscar\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_google_en_el_oscar.jpg\" width=\"660\" height=\"350\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_google_en_el_oscar.jpg 660w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_google_en_el_oscar-300x159.jpg 300w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/>Google mont\u00f3 un sitio especial interactivo para los Oscar que se entregar\u00e1n este domingo a la mejor pel\u00edcula, mejor director, mejores actores y todo lo dem\u00e1s. Como viene haciendo desde hace algunos a\u00f1os, la compa\u00f1\u00eda tambi\u00e9n hizo una predicci\u00f3n sobre qui\u00e9nes ser\u00e1n los ganadores del reconocimiento, en base a la cantidad de b\u00fasquedas que recibieron.<\/p>\n<p>  <!--more-->  <\/p>\n<p>As\u00ed, si los ganadores se definieran en base al inter\u00e9s de las b\u00fasquedas, los ganadores de este a\u00f1o ser\u00edan:<\/p>\n<p>Mejor pel\u00edcula: Argo. Tambi\u00e9n nominadas: L\u00e9s Miserables, Lincoln, Django Unchained, Life of Pi, Zero Dark Thirty, Silver Linings Playbook, Beasts of the Southern Wild, Amour.<\/p>\n<p>Mejor actor principal: Hugh Jackman (L\u00e9s Miserables). Tambi\u00e9n nominados: Denzel Washington (Flight), Daniel Day-Lewis (Lincoln), Bradley Cooper (Silver Linings Playbook), Joaquin Phoenix (The Master)<\/p>\n<p>Mejor actriz principal: Jennifer Lawrence (Silver Linings Playbook). Tambi\u00e9n nominadas: Jessica Chastain (Zero Dark Thirty), Emmanuelle Riva (Amour), Quvenzhane Wallis (Beasts of the Southern Wild), Naomi Watts (The Impossible)<\/p>\n<p>Mejor actor secundario: Christoph Waltz (Django Unchained). Tambi\u00e9n nominados: Robert De Niro (Silver Linings Playbook), Alan Arkin (Argo), Philip Seymour Hoffman (The Master), Tommy Lee Jones (Lincoln)<\/p>\n<p>Mejor actriz secundaria: Anne Hathaway (L\u00e9s Miserables). Tambi\u00e9n nominadas: Amy Adams (The Master), Sally Field (Lincoln), Helen Hunt (The Sessions), Jacki Weaver (Silver Linings Playbook).<\/p>\n<p>Mejor Director: Steven Spielberg (Lincoln). Tambi\u00e9n nominados: Ang Lee (Life of Pi), David O. Russel (Silver Linings Playbook), Michael Haneke (Amour), Benh Zeitlin (Beasts of the Southern Wild)<\/p>\n<p>El sitio est\u00e1 bastante bueno, con trailers y toda la informaci\u00f3n sobre las pel\u00edculas. \u00bfEst\u00e1s de acuerdo con las predicciones de Google?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google mont\u00f3 un sitio especial interactivo para los Oscar que se entregar\u00e1n este domingo a la mejor pel\u00edcula, mejor director, mejores actores y todo lo dem\u00e1s. Como viene haciendo desde hace algunos a\u00f1os, la compa\u00f1\u00eda tambi\u00e9n hizo una predicci\u00f3n sobre qui\u00e9nes ser\u00e1n los ganadores del reconocimiento, en base a la cantidad de b\u00fasquedas que recibieron.<\/p>\n","protected":false},"author":3,"featured_media":23848,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23849"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23848"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}