{"id":23909,"date":"2013-02-22T13:05:54","date_gmt":"2013-02-22T17:05:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ipor-que-a-muchos-fans-no-les-gusta-la-nueva-publicidad-de-beyonce\/"},"modified":"2013-02-22T13:05:54","modified_gmt":"2013-02-22T17:05:54","slug":"ipor-que-a-muchos-fans-no-les-gusta-la-nueva-publicidad-de-beyonce","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ipor-que-a-muchos-fans-no-les-gusta-la-nueva-publicidad-de-beyonce\/","title":{"rendered":"\u00bfPor qu\u00e9 a muchos fans no les gusta la nueva publicidad de Beyonc\u00e9?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-23908\" alt=\"Bey_Pepsi_mh_022113\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_Bey_Pepsi_mh_022113.jpg\" width=\"293\" height=\"348\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_Bey_Pepsi_mh_022113.jpg 293w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_Bey_Pepsi_mh_022113-252x300.jpg 252w\" sizes=\"auto, (max-width: 293px) 100vw, 293px\" \/>La diva y Pepsi generaron controversia entre sus seguidores con el look de este nuevo comercial.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Beyonc\u00e9 pas\u00f3 de la m\u00fasica pop al arte pop.<\/p>\n<p>La famosa cantante le dio a sus fans un adelanto de su pr\u00f3xima publicidad para Pepsi en su cuenta de Facebook.<\/p>\n<p>\u201cEl arte pop me inspira a vivir AHORA\u201d, escribi\u00f3.<\/p>\n<p>La inspiraci\u00f3n en la obra de Andy Warhol muestra una combinaci\u00f3n de Bey en tres difirentes poses faciales seguidas por una lata de Pepsi.<\/p>\n<p>Sin embargo, tanto brillo y color distorsionado ha creado algunas opiniones encontradas entre sus fans.<\/p>\n<p>\u201cUmmm\u2026 \u00bfpor qu\u00e9 luce tan blanca?\u201d, escribi\u00f3 uno de ellos. \u201cY parecer como una chica blanca, dedos abajo para ti\u201d.<\/p>\n<p>Pepsi no respondi\u00f3 inmediatamente al pedido de comentarios.<\/p>\n<p>Recordemos que no es la primera vez que la eposa de Jay-Z es acusada de blanquearse la piel para una publicidad. Para promocionar su \u00faltimo \u00e1lbum, lanz\u00f3 un afiche que no gust\u00f3 a sus fans por el color de su piel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La diva y Pepsi generaron controversia entre sus seguidores con el look de este nuevo comercial.<\/p>\n","protected":false},"author":3,"featured_media":23908,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-23909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=23909"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/23909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/23908"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=23909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=23909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=23909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}