{"id":24017,"date":"2013-02-26T14:34:00","date_gmt":"2013-02-26T18:34:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/cuestion-existencial-ipor-que-google-se-llama-google\/"},"modified":"2013-02-26T14:34:00","modified_gmt":"2013-02-26T18:34:00","slug":"cuestion-existencial-ipor-que-google-se-llama-google","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/cuestion-existencial-ipor-que-google-se-llama-google\/","title":{"rendered":"Cuesti\u00f3n existencial: \u00bfPor qu\u00e9 Google se llama Google?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-24016\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_Google_86.jpg\" width=\"600\" height=\"400\" alt=\"Google_86\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_Google_86.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/02\/sosua_images_Google_86-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Hay veces que las marcas superan todo l\u00edmite de identificaci\u00f3n, al punto de llegar a describir con su propio nombre el producto o hasta incluso la actividad que realizan, como \u00abGooglear\u00bb o \u00abGooglealo\u00bb.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Los cerebros detr\u00e1s del buscador que hoy forma parte vital de nuestras vidas son Larry Page y Sergey Brin, quienes luego de conocerse en la Universidad de Stanford estudiando su doctorado en Ciencias de la Computaci\u00f3n, desarrollaron juntos un motor de b\u00fasqueda de Internet, a partir de las propuestas expuestas en su tesis doctoral.<\/p>\n<p>As\u00ed, en 1997, registraron el dominio \u00abGoogle\u00bb, estrenando su funcionamiento el 28 de septiembre del a\u00f1o siguiente. No tard\u00f3 en destronar a AltaVista, el buscador estrella de aquel momento y luego a\u00f1o tras a\u00f1o, creci\u00f3 e incorpor\u00f3 nuevos elementos. As\u00ed nacieron AdWords, su sistema de publicidad online y la Barra Google, por citar algunos ejemplos. A partir de all\u00ed es historia conocida por todos. Pero volvamos a la palabra en s\u00ed, Google.<\/p>\n<p>El t\u00e9rmino fue acu\u00f1ado mucho antes que Page y Brin crearan el revolucionario invento, incluso no hab\u00edan nacido. Fue creada en 1930 para designar un n\u00famero formado por un uno seguido de cien ceros.<\/p>\n<p>Edward Kasner, matem\u00e1tico estadounidense, consider\u00f3 que era bueno contar con un nombre para un n\u00famero tan grande y le pidi\u00f3 a su sobrino de nueve a\u00f1os que lo inventara, con la promesa de que mucha gente lo usar\u00eda.<\/p>\n<p>As\u00ed, el ni\u00f1o propuso googol, que desde entonces fue ampliamente usado por los matem\u00e1ticos en todas las lenguas. Kasner cont\u00f3 posteriormente que su sobrino le propuso despu\u00e9s un nombre para un n\u00famero inimaginablemente m\u00e1s grande: un uno seguido de un googol de ceros, que se llamar\u00eda googleplex.<\/p>\n<p>Los creadores de Google se inspiraron en la palabra inventada hace casi ocho d\u00e9cadas y precisan que el t\u00e9rmino \u00abrefleja la misi\u00f3n de la compa\u00f1\u00eda de organizar la inmensa cantidad de informaci\u00f3n disponible en la web y en el mundo\u00bb.<\/p>\n<p>Fuente:&nbsp;<a href=\"http:\/\/www.diarioveloz.com\/notas\/87541-cuestion-existencial-por-que-google-se-llama-google-\" title=\"http:\/\/www.diarioveloz.com\/notas\/87541-cuestion-existencial-por-que-google-se-llama-google-\" rel=\"nofollow\">http:\/\/www.diarioveloz.com\/notas\/87541-cuestion-existencial-por-que-goog&#8230;<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hay veces que las marcas superan todo l\u00edmite de identificaci\u00f3n, al punto de llegar a describir con su propio nombre el producto o hasta incluso la actividad que realizan, como \u00abGooglear\u00bb o \u00abGooglealo\u00bb.<\/p>\n","protected":false},"author":3,"featured_media":24016,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-24017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=24017"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24017\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/24016"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=24017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=24017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=24017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}