{"id":24047,"date":"2013-03-01T04:00:00","date_gmt":"2013-03-01T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/lasana-de-verduras\/"},"modified":"2013-03-01T04:00:00","modified_gmt":"2013-03-01T08:00:00","slug":"lasana-de-verduras","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/lasana-de-verduras\/","title":{"rendered":"Lasa\u00f1a de verduras"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-24046\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_lasaa.jpg\" width=\"680\" height=\"460\" alt=\"lasaa\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_lasaa.jpg 680w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_lasaa-300x202.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_lasaa-75x52.jpg 75w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/>Esta receta de<strong>&nbsp;lasa\u00f1a de verduras<\/strong>&nbsp;est\u00e1 especialmente pensada para los vegetarianos. La podremos tener lista en 90 minutos y da para seis raciones.<\/p>\n<p>  <!--more-->  <\/p>\n<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>Un paquete de l\u00e1minas de pasta para lasa\u00f1a ya precocidas.<\/li>\n<li>Br\u00f3coli troceado (100 gramos m\u00e1s o menos).<\/li>\n<li>Coliflor (troceada tambi\u00e9n y en la misma cantidad)<\/li>\n<li>Calabazas italianas o calabacines en cubos (igual).<\/li>\n<li>Un pu\u00f1ado de aceitunas negras en trocitos.<\/li>\n<li>La misma cantidad de zanahoria cortada en cubos.<\/li>\n<li>Dos tazas de pur\u00e9 de jitomate (o de salsa de tomate casera en su defecto).<\/li>\n<li>Una cebolla blanca grande muy picada.<\/li>\n<li>200 g. de crema de queso de las de untar.<\/li>\n<li>Queso rallado (tipo mozzarella).<\/li>\n<li>Dos dientes de ajo muy picados tambi\u00e9n.<\/li>\n<li>Una taza de caldo de verduras.<\/li>\n<li>Aceite de oliva.<\/li>\n<li>Or\u00e9gano.<\/li>\n<li>Una cucharada de albahaca picada fina.<\/li>\n<li>Dos cubitos de caldo de verduras en polvo<\/li>\n<\/ul>\n<p><strong>Preparaci\u00f3n:<\/strong><\/p>\n<ol>\n<li>En una sart\u00e9n calentamos el aceite y le a\u00f1adimos la cebolla hasta que se poche, para despu\u00e9s a\u00f1adir el ajo hasta que ambos est\u00e9n dorados.<\/li>\n<li>A continuaci\u00f3n a\u00f1adimos todas las verduras y las dejamos cocin\u00e1ndose durante 2 minutos. Despu\u00e9s agregamos tambi\u00e9n las aceitunas y el tomate (en salsa casera normal o pur\u00e9 de jitomate), y lo dejamos cocer otros 5 minutos m\u00e1s o menos, sazonando con la albahaca y el or\u00e9gano y con el caldo de verduras en polvo.<\/li>\n<li>Ahora licuamos o batimos la crema de queso de untar junto con el caldo de verduras l\u00edquido y lo dejamos aparte.<\/li>\n<li>En un recipiente apropiado para horno colocamos una base con las placas de lasa\u00f1a (pod\u00e9is reblandecerlas previamente en agua caliente como indiquen las instrucciones del paquete o dejar que se reblandezcan en la propia fuente con la salsa de tomate y los dem\u00e1s l\u00edquidos). Ponemos encima primero una capa de la mezcla de verduras y el tomate, despu\u00e9s otra de la crema de queso y espolvoreamos sobre ello el queso rallado. Hacemos tres capas iguales. En la cima terminamos con una capa de placas de lasa\u00f1a, crema de queso y queso rallado.<\/li>\n<li>Finalmente metemos al horno a una temperatura de 170\u00baC. durante 20 minutos aproximadamente.<\/li>\n<\/ol>\n<p>Bon app\u00e9tit!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta receta de&nbsp;lasa\u00f1a de verduras&nbsp;est\u00e1 especialmente pensada para los vegetarianos. La podremos tener lista en 90 minutos y da para seis raciones.<\/p>\n","protected":false},"author":3,"featured_media":24046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-24047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=24047"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/24046"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=24047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=24047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=24047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}