{"id":24157,"date":"2013-03-03T21:30:00","date_gmt":"2013-03-04T01:30:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/por-que-la-soledad-nos-enferma\/"},"modified":"2013-03-03T21:30:00","modified_gmt":"2013-03-04T01:30:00","slug":"por-que-la-soledad-nos-enferma","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/por-que-la-soledad-nos-enferma\/","title":{"rendered":"Por qu\u00e9 la soledad nos enferma"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-24156\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_130213145018_loneliness_cold_social_exclusion_304x171_sciencephotolibrary.jpg\" width=\"304\" height=\"171\" alt=\"130213145018_loneliness_cold_social_exclusion_304x171_sciencephotolibrary\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_130213145018_loneliness_cold_social_exclusion_304x171_sciencephotolibrary.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_130213145018_loneliness_cold_social_exclusion_304x171_sciencephotolibrary-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/>Los m\u00e9dicos saben desde hace tiempo que la soledad no es buena para la salud mental, ya que tiene asociadas patolog\u00edas como la depresi\u00f3n, el estr\u00e9s, la ansiedad y la falta de autoestima.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Pero cada vez hay mas evidencias de que el aislamiento social est\u00e1 tambi\u00e9n conectado con otros problemas f\u00edsicos.<\/p>\n<div>\n<div>\n<div>\n<p><a href=\"http:\/\/www.bbc.co.uk\/mundo\/noticias\/2013\/03\/130228_salud_soledad_enfermedades_jg.shtml#more-contextual-links\"><\/a><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>Algunos estudios sugieren que la soledad puede causar enfermedades con consecuencias fatales.<\/p>\n<p>En 2006, una investigaci\u00f3n realizada con 2.800 mujeres que padec\u00edan c\u00e1ncer de mama sugiri\u00f3 que aquellas pacientes que ve\u00edan poco a familiares y amigos ten\u00edan hasta cinco veces m\u00e1s posibilidades de morir que aquellas con una vida social mas activa.<\/p>\n<p>Es por eso que los cient\u00edficos est\u00e1n intentando averiguar qu\u00e9 efectos tiene la soledad sobre el cuerpo.<\/p>\n<p>Psic\u00f3logos de la Universidad de Chicago y de la Universidad Estatal de Ohio han demostrado que las personas que est\u00e1n socialmente aisladas desarrollan cambios en sus sistemas inmunol\u00f3gicos, que provocan una condici\u00f3n conocida como inflamaci\u00f3n cr\u00f3nica.<\/p>\n<p>Las inflamaciones temporales son necesarias para la cura de cortes o infecciones, pero si la inflaci\u00f3n persiste en el tiempo puede llevar a padecer enfermedades cardiovasculares y c\u00e1ncer.<\/p>\n<p>Los investigadores de la Universidad de Chicago descubrieron que las personas solitarias encuentran m\u00e1s estresantes las actividades diarias que aquellas con una vida social m\u00e1s activa.<\/p>\n<p>Los cient\u00edficos creen que el cortisol, la hormona que el cuerpo libera como respuesta al estr\u00e9s, causa inflamaciones y otras enfermedades.<\/p>\n<h2>Situaciones estresantes<\/h2>\n<div>\n<div>\n<p>El n\u00famero de personas que viven solas est\u00e1 creciendo en todo el mundo.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p>El \u00faltimo estudio de la Universidad Estatal de Ohio se fij\u00f3 en los niveles de inflamaci\u00f3n en respuesta al estr\u00e9s en personas solitarias.<\/p>\n<p>La doctora Lisa Jeremka compar\u00f3 a mujeres que han sobrevivido a un c\u00e1ncer de mama con voluntarias sanas.<\/p>\n<p>Las someti\u00f3 a una conocida prueba llamada Test de Estr\u00e9s Social de Trier, en la que, sin previo aviso, las participantes deb\u00edan dar una charla frente a un panel explicando por qu\u00e9 eran las mejores candidatas para un puesto de trabajo.<\/p>\n<p>Despu\u00e9s se les pidi\u00f3 que hicieran una operaci\u00f3n de aritm\u00e9tica frente al panel.<\/p>\n<p>Los ex\u00e1menes realizados tras este test mostraron que en ambos grupos, las personas solitarias eran las que presentaban un mayor nivel de inflamaci\u00f3n.<\/p>\n<p>\u00abSi se est\u00e1 solo se pude tener un nivel de inflamaci\u00f3n mayor sin importar si se padece una enfermedad cr\u00f3nica\u00bb, se\u00f1ala la doctora Jeremka.<\/p>\n<p>\u00abDurante mucho tiempo a los m\u00e9dicos les cost\u00f3 reconocer la importancia de la soledad en la salud. Ahora sabemos que es necesario analizar y entender los contextos sociales de los pacientes\u00bb.<\/p>\n<p>El n\u00famero de personas que viven solas est\u00e1 creciendo en todo el mundo. Muchos son ancianos, que se han quedado solos despu\u00e9s de la muerte de sus parejas o cuando sus familias se han mudado.<\/p>\n<p>Por ejemplo, en Reino Unido, la mitad de los mayores de 75 a\u00f1os viven solos y uno de cada diez padece de soledad aguda.<\/p>\n<p>\u00abEstar solo significa no sentirse conectado o cuidado, no tiene que ver con estar f\u00edsicamente solo\u00bb, se\u00f1ala doctora Lisa Jeremka.<\/p>\n<p>\u00abNecesitamos encontrar la manera de ayudar a la gente solitaria. Lamentablemente, no podemos decirle a todo el mundo que salga y encuentre a alguien que le quiera. Necesitamos crear redes de apoyo\u00bb, concluye la experta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los m\u00e9dicos saben desde hace tiempo que la soledad no es buena para la salud mental, ya que tiene asociadas patolog\u00edas como la depresi\u00f3n, el estr\u00e9s, la ansiedad y la falta de autoestima.<\/p>\n","protected":false},"author":3,"featured_media":24156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-24157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=24157"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24157\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/24156"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=24157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=24157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=24157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}