{"id":24243,"date":"2013-03-05T15:56:39","date_gmt":"2013-03-05T19:56:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/crean-parches-para-la-piel-contra-el-cancer-de-prostata\/"},"modified":"2013-03-05T15:56:39","modified_gmt":"2013-03-05T19:56:39","slug":"crean-parches-para-la-piel-contra-el-cancer-de-prostata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/crean-parches-para-la-piel-contra-el-cancer-de-prostata\/","title":{"rendered":"Crean parches para la piel contra el c\u00e1ncer de pr\u00f3stata"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-24241\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_130304113701_prostata_304x171_spl.jpg\" width=\"304\" height=\"171\" alt=\"130304113701_prostata_304x171_spl\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_130304113701_prostata_304x171_spl.jpg 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_130304113701_prostata_304x171_spl-300x168.jpg 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/>Unos parches para la piel que liberan estr\u00f3geno en la sangre pueden ser un tratamiento m\u00e1s barato y seguro para el c\u00e1ncer de pr\u00f3stata que las terapias actuales, seg\u00fan un estudio.<\/p>\n<p>  <!--more-->  <\/p>\n<p>El tratamiento m\u00e1s usado hoy en d\u00eda se basa en inyecciones de una sustancia qu\u00edmica que corta los niveles de testosterona -la fuerza motriz de muchos c\u00e1nceres de pr\u00f3stata- pero causa efectos secundarios.<\/p>\n<div>\n<div>\n<div>\n<ul><\/ul>\n<p><a href=\"http:\/\/www.bbc.co.uk\/mundo\/noticias\/2013\/03\/130304_salud_cancer_parche_prostata_gtg.shtml#more-contextual-links\"><\/a><\/p>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>Cient\u00edficos del Imperial College de Londres compararon la aplicaci\u00f3n de parches con inyecciones en 254 pacientes.<\/p>\n<p>El resultado, publicado en&nbsp;<em>Lancet Oncology<\/em>, fue que los parches eran seguros y evitaban efectos secundarios parecidos a los s\u00edntomas que aparecen durante la menopausia.<\/p>\n<h2>M\u00e1s estr\u00f3geno para menos testosterona<\/h2>\n<p>Desde hace mucho tiempo se usa estr\u00f3geno para combatir el c\u00e1ncer de pr\u00f3stata.<\/p>\n<p>El estr\u00f3geno y la testosterona son sustancias qu\u00edmicas muy parecidas, por lo que aumentar de forma gradual los niveles de estr\u00f3geno en el cuerpo puede reducir la cantidad de testosterona producida y as\u00ed ralentizar el crecimiento de este tipo de c\u00e1ncer.<\/p>\n<p>El consumo por v\u00eda oral de estr\u00f3geno provoca significativos problemas de salud, incluida una sobredosis en el h\u00edgado.<\/p>\n<div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-24242\" width=\"304\" height=\"171\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/wscdn.bbc.co.uk_worldservice_assets_images_2013_03_04_130304113355_prostata.png\" alt=\"Parche\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/wscdn.bbc.co.uk_worldservice_assets_images_2013_03_04_130304113355_prostata.png 304w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/wscdn.bbc.co.uk_worldservice_assets_images_2013_03_04_130304113355_prostata-300x168.png 300w\" sizes=\"auto, (max-width: 304px) 100vw, 304px\" \/> <\/p>\n<p>Los parches liberan estr\u00f3geno a trav\u00e9s de la piel.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p>Este \u00f3rgano produce sustancias que causan co\u00e1gulos en la sangre, ataques card\u00edacos y accidentes cerebrovasculares.<\/p>\n<p>Por eso, el tratamiento por excelencia son las inyecciones de LHRHa (hormona liberadora de hormona luteinizante), que reduce la producci\u00f3n de estr\u00f3genos y testosterona.<\/p>\n<p>Sin embargo, tambi\u00e9n tiene efectos secundarios parecidos a los que sufren las mujeres durante la menopausia.<\/p>\n<h2>El paso siguiente<\/h2>\n<p>\u00abNosotros no estamos alegando que esto sea equivalente a las terapias actuales, pero pareciera como si estuvi\u00e9ramos alcanzando los niveles de castraci\u00f3n de la testosterona\u00bb, explic\u00f3 Paul Abel, del Imperial College de Londres.<\/p>\n<p>Sin embargo, los investigadores necesitan hacer un seguimiento a los pacientes por m\u00e1s tiempo.<\/p>\n<p>\u00abEl siguiente paso es probar si los parches de estr\u00f3geno son tan efectivos deteniendo el crecimiento del c\u00e1ncer de pr\u00f3stata como las terapias de hormonas actuales. Actualmente estamos haciendo pruebas en 600 pacientes\u00bb, agreg\u00f3.<\/p>\n<p>Por su parte, Kate Law, de la fundaci\u00f3n&nbsp;<em>Cancer Research UK<\/em>, organismo que financi\u00f3 parte del estudio, declar\u00f3 que cada vez m\u00e1s hombres \u00absobreviven al c\u00e1ncer de pr\u00f3stata gracias a los avances en la investigaci\u00f3n. Pero todav\u00eda necesitamos con urgencia desarrollar tratamientos m\u00e1s efectivos y reducir los efectos secundarios\u00bb.<\/p>\n<p>Mientras que el director de&nbsp;<em>Prostate Cancer UK<\/em>, Iain Frame, considera que \u00abtodav\u00eda no est\u00e1 muy claro si los parches de hormona pueden ser una alternativa efectiva a las inyecciones de hormona, pero esperamos con expectaci\u00f3n los resultados de los nuevos ensayos\u00bb.<\/p>\n<p><a href=\"http:\/\/www.bbc.co.uk\/mundo\/noticias\/2013\/03\/130304_salud_cancer_parche_prostata_gtg.shtml\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unos parches para la piel que liberan estr\u00f3geno en la sangre pueden ser un tratamiento m\u00e1s barato y seguro para el c\u00e1ncer de pr\u00f3stata que las terapias actuales, seg\u00fan un estudio.<\/p>\n","protected":false},"author":3,"featured_media":24241,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-24243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=24243"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24243\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/24241"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=24243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=24243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=24243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}