{"id":24525,"date":"2013-03-14T04:00:00","date_gmt":"2013-03-14T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/4-grandes-errores-que-cometen-las-suegras-con-sus-nueras\/"},"modified":"2013-03-14T04:00:00","modified_gmt":"2013-03-14T08:00:00","slug":"4-grandes-errores-que-cometen-las-suegras-con-sus-nueras","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/4-grandes-errores-que-cometen-las-suegras-con-sus-nueras\/","title":{"rendered":"4 grandes errores que cometen las suegras con sus nueras"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-24524\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_Tips-iMujer-La-relacin-con-la-suegra.jpg\" width=\"600\" height=\"400\" alt=\"Tips-iMujer-La-relacin-con-la-suegra\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_Tips-iMujer-La-relacin-con-la-suegra.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_Tips-iMujer-La-relacin-con-la-suegra-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Para muchas mujeres, mantener una buena relaci\u00f3n con la suegra es bastante dif\u00edcil, pues impl\u00edcitamente existe una especie de lucha de poder y sentimientos. En este sentido, el sitio Grandparents.com realiz\u00f3 una investigaci\u00f3n para determinar que es lo que m\u00e1s molesta a las nueras de sus \u201cmadres pol\u00edticas\u201d y de paso aconsejarles a \u00e9stas c\u00f3mo cambiar su actuar.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p><strong>1. Llegar sin aviso previo<\/strong><\/p>\n<p>Terry Orbuch, doctora en psicolog\u00eda e investigadora de la Universidad de Michigan y la principal autora de una investigaci\u00f3n del Instituto Nacional de la Salud sobre el matrimonio y el divorcio, se\u00f1ala que aparecerse sin avisar, es una de las mayores quejas de las nueras.<\/p>\n<p>Despu\u00e9s de analizar parejas por m\u00e1s de 26 a\u00f1os, Orbuch dice que las nueras necesitan autonom\u00eda e independencia, por lo tanto, cuando una suegra lleva sin avisar transgrede eso.<\/p>\n<p>Por otro lado, Terry Apter, autora del libro \u201c\u00bfQu\u00e9 quiero de m\u00ed?\u201d, a\u00f1ade que esta acci\u00f3n es una falta de respeto hacia la nuera y su control del espacio familiar. Por ello, recomienda ofrecer disculpas cuando se incurra en esto.<\/p>\n<p>Lo ideal, indica la experta, es simplemente avisar a la \u201chija pol\u00edtica\u201d que \u201cte gustar\u00eda visitarla\u201d y preguntarle cu\u00e1l es el mejor momento para hacerlo.<\/p>\n<p><strong>2. Dar un consejo que la nuera no pidi\u00f3<\/strong><\/p>\n<p>A nadie le gusta que le den consejos que no ha pedido, y en el caso de una nuera, puede ser tomado como una cr\u00edtica. Apter plantea que es como si le dijeras: \u201cEstar\u00e1s mejor si haces las cosas a mi manera\u201d.<\/p>\n<p>Incluso si tu intenci\u00f3n es buena, lo m\u00e1s probable es que un consejo no pedido sea tomado por la nuera como una amenaza a su autoridad, especialmente si tiene que ver con su rol de madre, esposa o jefa de hogar.<\/p>\n<p>Por eso, seg\u00fan Apter, lo mejor es \u201cmoderse la lengua\u201d y si no puedes, empezar con un halago. Por ejemplo: \u201cEres una maravillosa madre\/ esposa\/ persona\u201d. Si la nuera se muestra abierta a hablar del tema, seguir conversando, pero si se ve ofendida, no seguir con el tema.<\/p>\n<p><strong>3. Criticar a sus hijos<\/strong><\/p>\n<p>Lo habitual es que los abuelos crean que sus nietos son maravillosos, pero si comienzas a decir que el ni\u00f1o es impulsivo, desordenado o desconsiderado, tu nuera lo tomar\u00e1 como una cr\u00edtica a su forma de crianza. Una madre puede estar molesta con su hijo, pero no quiere que otros le encuentren fallas.<\/p>\n<p>Por eso, lo mejor es siempre centrarse en las cosas que aprecias de tus nietos.<\/p>\n<p><strong>4. Quejarse de la nuera con el hijo<\/strong><\/p>\n<p>Hablar mal de tu nuera con tu hijo, es una p\u00e9sima idea porque no s\u00f3lo lo pone a \u00e9l en una posici\u00f3n dif\u00edcil, tambi\u00e9n a ti.<\/p>\n<p>Apter dice que un hombre no quiere escuchar cosas negativas de la mujer que ama, menos si provienen de su madre. Lo m\u00e1s probable es que s\u00f3lo consigas que \u00e9l se enoje contigo.<\/p>\n<p>La experta aconseja buscar soluciones positivas a los problemas. Por ejemplo, si una suegra se siente \u201cexcluida\u201d de la vida de los nietos, la mejor forma de plantearlo no es atacando o quej\u00e1ndose de que la nuera no deja verlos, sino expresando el deseo de acercarse a los ni\u00f1os y buscar la mejor forma y momento para hacerlo.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Para muchas mujeres, mantener una buena relaci\u00f3n con la suegra es bastante dif\u00edcil, pues impl\u00edcitamente existe una especie de lucha de poder y sentimientos. En este sentido, el sitio Grandparents.com realiz\u00f3 una investigaci\u00f3n para determinar que es lo que m\u00e1s molesta a las nueras de sus \u201cmadres pol\u00edticas\u201d y de paso aconsejarles a \u00e9stas c\u00f3mo cambiar su actuar.<\/p>\n","protected":false},"author":3,"featured_media":24524,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-24525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=24525"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/24524"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=24525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=24525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=24525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}