{"id":24706,"date":"2013-03-20T19:04:32","date_gmt":"2013-03-20T23:04:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/republica-dominicana-pierde-rd203-millones-por-cada-dia-paro-de-los-maestros\/"},"modified":"2013-03-20T19:04:32","modified_gmt":"2013-03-20T23:04:32","slug":"republica-dominicana-pierde-rd203-millones-por-cada-dia-paro-de-los-maestros","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/republica-dominicana-pierde-rd203-millones-por-cada-dia-paro-de-los-maestros\/","title":{"rendered":"Rep\u00fablica Dominicana pierde RD$203 millones por cada d\u00eda paro de los maestros"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-24705\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/03\/sosua_images_timthumb.jpg\" width=\"190\" height=\"110\" alt=\"timthumb\" class=\"caption\" style=\"float: left;\" \/>La ministra de Educaci\u00f3n, Josefina Pimentel, exhort\u00f3 a la Asociaci\u00f3n Dominicana de Profesores (ADP) a reconsiderar su \u201cdesafortunada decisi\u00f3n\u201d de suspender la docencia a casi 2.5 millones de estudiantes por 48 horas, y afirm\u00f3 que la paralizaci\u00f3n representa al Estado un costo de RD$203 millones por d\u00eda. La funcionaria deplor\u00f3 que con este m\u00e9todo el gremio est\u00e9 lesionando el sagrado derecho de los ni\u00f1os de recibir docencia.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Pimentel se\u00f1al\u00f3 que el Ministerio de Educaci\u00f3n (MINERD) ha tenido la iniciativa de materializar su propuesta integral de aumento salarial, y que las v\u00edas del di\u00e1logo permanecen abiertas para continuar viabilizando acuerdos a favor de una ense\u00f1anza con calidad.<\/p>\n<p>\u201cParalizar la docencia por 48 horas y llamar, al d\u00eda siguiente, a una jornada de asambleas en las escuelas, que es igual a proseguir el paro, constituye una intransigencia y un irrespeto al compromiso que contrajo la ADP ante la sociedad dominicana, de mantener la lucha por mejores salarios sin suspender la docencia\u201d, expres\u00f3.<\/p>\n<p>Dijo que m\u00e1s de dos millones de estudiantes ver\u00e1n alterado durante tres d\u00edas el ritmo de sus clases, tiempo que no se sabe si podr\u00e1n recuperar porque ellos (los maestros) no dan garant\u00edas de que en lo adelante la docencia no sufrir\u00e1 otras graves interrupciones.<\/p>\n<p>Asimismo, manifest\u00f3 que no se puede mantener los mismos esquemas con un gremio magisterial que se ha quedado atrapado en los m\u00e9todos de exigencias reivindicativas que ni en el pasado eran adecuados.<\/p>\n<\/p>\n<p>La ministra se expres\u00f3 en esos t\u00e9rminos durante una reuni\u00f3n celebrada en el liceo V\u00edctor Estrella Liz (La Perito), de esta capital, con directores regionales distritales, departamentales, viceministros y otros funcionarios del MINERD, con el fin de socializar el plan integral de incentivos salariales para los maestros del sector p\u00fablico y la resoluci\u00f3n No. 27-2013 que establece una nueva escala y ajuste salarial a los docentes del sistema educativo.<\/p>\n<p>Explic\u00f3 que las medidas que el MINERD ha tomado respecto al incremento salarial de los maestros y al personal docente son positivas para el sistema educativo nacional, tema con el que se trabaja desde hace tres meses.<\/p>\n<p>Reiter\u00f3 que a partir de este mes de marzo ning\u00fan maestro recibir\u00e1 menos de 15,000 pesos por una jornada de trabajo, lo que beneficiar\u00e1 a 7,000 de ellos, que ver\u00e1n incrementados sus salarios en m\u00e1s de la mitad. El aumento ser\u00e1 retroactivo al mes de febrero.<\/p>\n<p>\u201cSi nosotros atendemos la demanda de 30,000 pesos por tanda en estos momentos o sencillamente de un incremento de golpe de un 100 por ciento, tendr\u00edamos que dejar de lado y sacrificar muchas l\u00edneas de trabajo que van a permitir expandir en materia de cobertura y atender con mayor equidad y capacidad de inclusi\u00f3n a otros sectores de nuestra poblaci\u00f3n escolar\u201d, afirm\u00f3 a&nbsp;<a href=\"http:\/\/elnuevodiario.com.do\/app\/article.aspx?id=323931\" target=\"_blank\">El Nuevo Diario<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ministra de Educaci\u00f3n, Josefina Pimentel, exhort\u00f3 a la Asociaci\u00f3n Dominicana de Profesores (ADP) a reconsiderar su \u201cdesafortunada decisi\u00f3n\u201d de suspender la docencia a casi 2.5 millones de estudiantes por 48 horas, y afirm\u00f3 que la paralizaci\u00f3n representa al Estado un costo de RD$203 millones por d\u00eda. La funcionaria deplor\u00f3 que con este m\u00e9todo el gremio est\u00e9 lesionando el sagrado derecho de los ni\u00f1os de recibir docencia.<\/p>\n","protected":false},"author":3,"featured_media":24705,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-24706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=24706"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/24706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/24705"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=24706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=24706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=24706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}