{"id":25080,"date":"2013-04-04T03:45:00","date_gmt":"2013-04-04T07:45:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/alcaldesa-de-sosua-inaugura-segundo-curso-de-bisuteria\/"},"modified":"2013-04-04T03:45:00","modified_gmt":"2013-04-04T07:45:00","slug":"alcaldesa-de-sosua-inaugura-segundo-curso-de-bisuteria","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/alcaldesa-de-sosua-inaugura-segundo-curso-de-bisuteria\/","title":{"rendered":"Alcaldesa de Sos\u00faa inaugura segundo curso de bisuter\u00eda"},"content":{"rendered":"<p class=\"MsoNormal\">La licenciada Ilana Neumann, Alcaldesa del municipio de Sos\u00faa dio inicio recientemente a un nuevo curso de bisuter\u00eda en los salones de la sala capitular. En esta ocasi\u00f3n el curso tiene la novedad de que las jovencitas voluntarias para aprender tan noble oficio son de mayor edad que las graduadas recientemente y adem\u00e1s superan por siete al primer grupo que era de veinte.<\/p>\n<p>  <!--more-->  <\/p>\n<p class=\"MsoNormal\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-25078\" alt=\"Ilana_curso_bisuteria2\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Ilana_curso_bisuteria2.jpg\" width=\"1028\" height=\"768\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Ilana_curso_bisuteria2.jpg 1028w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Ilana_curso_bisuteria2-300x224.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Ilana_curso_bisuteria2-1024x765.jpg 1024w\" sizes=\"auto, (max-width: 1028px) 100vw, 1028px\" \/>En su primer d\u00eda de clases, veintisiete doncellas, cuyas edades oscilan entre los trece y quince a\u00f1os mostraron su felicidad al poder recibir la ense\u00f1anza de tan importante oficio en la propia persona de la alcaldesa de Sos\u00faa y sus asistentes, Daphna Villam\u00e1n (sobrina) y Herminia Tic\u00e9.<\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-25079\" alt=\"Ilana_curso_bisuteria3\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Ilana_curso_bisuteria3.jpg\" width=\"1028\" height=\"768\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Ilana_curso_bisuteria3.jpg 1028w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Ilana_curso_bisuteria3-300x224.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Ilana_curso_bisuteria3-1024x765.jpg 1024w\" sizes=\"auto, (max-width: 1028px) 100vw, 1028px\" \/>Pacientemente Ilana mostr\u00f3 al inicio de este nuevo curso, su destreza y amor por cada una de las j\u00f3venes participantes ya que varias de ellas mostraron nerviosismo al tener de frente la propia alcaldesa quien pacientemente les apoy\u00f3 y ense\u00f1\u00f3 dulcemente como se realizan las obras de artes llamadas bisuter\u00eda.<\/p>\n<p class=\"MsoNormal\">Estos cursos en el que recientemente fueron graduadas veinte ni\u00f1as a las que se les otorg\u00f3 igual cantidad de certificados de participaci\u00f3n a nombre del Despacho de la Alcaldesa, son impartidos todos los s\u00e1bados a partir de las nueve de la ma\u00f1ana en el cabildo local. En los momentos de receso todas son bien atendidas con la entrega de un refrigerio por el personal del ayuntamiento.<\/p>\n<p class=\"MsoNormal\">Las herramientas de trabajo y todo el material gastable, tales como hilos, piedras decorativas entre otros son entregados gratuitamente a cada joven. Estos utensilios y materiales pueden ser llevados a casa para seguir practicando y realizar la tarea de la semana.<\/p>\n<p class=\"MsoNormal\">Ilana Neumann dijo sentirse feliz de poder iniciar este nuevo curso y agreg\u00f3 que decidieron aumentar la edad de las j\u00f3venes para que estas puedan aprovechar las ventajas de la bisuter\u00eda y poder obtener sus propios beneficios con mayor rapidez. Este tipo de curso promete continuar por un largo per\u00edodo ya que hubo varias j\u00f3venes que quedaron fuera por la falta de espacio en el lugar de ense\u00f1anza y lo inmanejable que se puede convertir un aula con m\u00e1s de treinta estudiantes.<\/p>\n<p class=\"MsoNormal\">\n<p class=\"MsoNormal\">Nota: Cada joven estudiante del curso de Bisuter\u00eda ha sido elegida en los distintos sectores del municipio de Sos\u00faa, tomando en consideraci\u00f3n su rendimiento escolar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La licenciada Ilana Neumann, Alcaldesa del municipio de Sos\u00faa dio inicio recientemente a un nuevo curso de bisuter\u00eda en los salones de la sala capitular. En esta ocasi\u00f3n el curso tiene la novedad de que las jovencitas voluntarias para aprender tan noble oficio son de mayor edad que las graduadas recientemente y adem\u00e1s superan por siete al primer grupo que era de veinte.<\/p>\n","protected":false},"author":3,"featured_media":25078,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-25080","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=25080"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25080\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/25078"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=25080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=25080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=25080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}