{"id":25082,"date":"2013-04-05T04:00:00","date_gmt":"2013-04-05T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/las-mujeres-jovenes-no-son-inmunes-al-cancer-de-mama\/"},"modified":"2013-04-05T04:00:00","modified_gmt":"2013-04-05T08:00:00","slug":"las-mujeres-jovenes-no-son-inmunes-al-cancer-de-mama","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/las-mujeres-jovenes-no-son-inmunes-al-cancer-de-mama\/","title":{"rendered":"Las mujeres j\u00f3venes no son inmunes al c\u00e1ncer de mama"},"content":{"rendered":"<div><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-25081\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_cancer-mama543245654642.jpg\" width=\"374\" height=\"252\" alt=\"cancer-mama543245654642\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_cancer-mama543245654642.jpg 374w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_cancer-mama543245654642-300x202.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_cancer-mama543245654642-75x52.jpg 75w\" sizes=\"auto, (max-width: 374px) 100vw, 374px\" \/>Aunque seas joven, no pienses que eres inmune al c\u00e1ncer de mama. Durante los \u00faltimos 30 a\u00f1os, ha habido un aumento peque\u00f1o, pero sostenido, de c\u00e1ncer de mama metast\u00e1tico en mujeres de menos de 40 a\u00f1os (en &nbsp;los Estados Unidos). &nbsp;Y vale la pena investigar el asunto m\u00e1s a fondo.<\/div>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><\/div>\n<div>Si tienes menos de 40 a\u00f1os, presta m\u00e1s atenci\u00f3n a tus senos. Durante los \u00faltimos 30 a\u00f1os, el c\u00e1ncer de mama avanzado (o metast\u00e1tico, cuando ya se ha expandido a otras partes del cuerpo) en mujeres menores de 40 a\u00f1os se ha triplicado (en Estados Unidos). El aumento fue de 250 casos por a\u00f1o en 1976, y 850 casos en 2009. Pero el aumento absoluto fue menor. En 1976, la tasa de c\u00e1ncer de mama avanzado en ese grupo (de 25 a 29 a\u00f1os) fue de 1.5 por cada 100,000 mujeres; y en 2009 fue de poco m\u00e1s de 3 por persona por cada 100,000 mujeres.<\/div>\n<div><\/div>\n<div><\/div>\n<div>A pesar de que el n\u00famero de casos se triplic\u00f3, la tasa s\u00f3lo se duplic\u00f3, ya que el n\u00famero de mujeres aument\u00f3 en el per\u00edodo de los 30 a\u00f1os estudiados. Aunque ese aumento es relativamente peque\u00f1o, la tendencia no muestra evidencia de que va a disminuir. Eso predice que un creciente n\u00famero de mujeres j\u00f3venes pudieran desarrollar c\u00e1ncer de mama metast\u00e1tico, a una edad en que los ex\u00e1menes de detecci\u00f3n no suelen practicarse rutinariamente, por lo que es m\u00e1s dif\u00edcil que se descubra a tiempo.<\/div>\n<div><\/div>\n<div>\n<p>Lo anterior se report\u00f3 en un estudio encabezado por la Dra. Rebecca Johnson (directora m\u00e9dica del programa de oncolog\u00eda de adolescentes y adultos j\u00f3venes del Hospital Pedi\u00e1trico de Seattle), y se bas\u00f3 en estad\u00edsticas del Registro del Instituto Nacional del C\u00e1ncer de Estados Unidos. De acuerdo al estudio, el n\u00famero de&nbsp;mujeres j\u00f3venes diagnosticadas&nbsp;con&nbsp;c\u00e1ncer de mama&nbsp;ha aumentado lenta, pero continuamente, desde los a\u00f1os 70.<\/p>\n<div><\/div>\n<div>\n<p>El estudio se public\u00f3 en la edici\u00f3n del 27 de febrero de la revista&nbsp;<em>Journal of the American Medical Association<\/em>. &nbsp;Los investigadores encontraron que la mayor incidencia ocurri\u00f3 en las mujeres entre los 25 y los 34 a\u00f1os de edad, con incrementos cada vez m\u00e1s peque\u00f1os en las mujeres mayores, medidos en intervalos de cinco a\u00f1os. No hubo aumentos significativos de la incidencia en mujeres mayores de 55 a\u00f1os.<\/p>\n<p>Tambi\u00e9n se observaron datos sobre la etapa del c\u00e1ncer, si estaba localizado o si se hab\u00eda propagado a otros \u00f3rganos (huesos, cerebro, pulmones, etc.). Se encontr\u00f3 el aumento en todas las razas a partir de 1992, cuando los datos estuvieron disponibles por primera vez.<\/p>\n<p>No se puede saber con seguridad qu\u00e9 provoca el aumento, pues el estudio s\u00f3lo observ\u00f3 el n\u00famero de mujeres diagnosticadas con la enfermedad ya avanzada debido al paso del tiempo. Es necesario hacer una investigaci\u00f3n para averiguar con exactitud la causa (o causas) de la tendencia.<\/p>\n<p>Los hallazgos del estudio son importantes e interesantes, pero seg\u00fan algunos expertos, aunque es cierto que el&nbsp;c\u00e1ncer de mama&nbsp;o&nbsp;c\u00e1ncer del seno&nbsp;avanzado ha ido en aumento en las mujeres de entre 25 y 39 a\u00f1os, sigue siendo relativamente bajo en comparaci\u00f3n con las mujeres despu\u00e9s de los 40 a\u00f1os.<\/p>\n<p>Pero aunque las personas m\u00e1s j\u00f3venes piensan que no pueden desarrollar c\u00e1ncer, lo cierto es que el c\u00e1ncer no respeta ni edad ni condici\u00f3n y para combatirlo de la forma m\u00e1s efectiva, es importante detectarlo a tiempo.<\/p>\n<p>El resultado del estudio, sin embargo, no es una raz\u00f3n para cambiar las recomendaciones de la&nbsp;mamograf\u00eda. Muchas organizaciones, como la Asociaci\u00f3n Americana Contra el C\u00e1ncer, recomiendan evaluaciones de rutina a partir de los 40 a\u00f1os, mientras que el Grupo de Trabajo de Servicios Preventivos de los Estados Unidos sugiere que las&nbsp;mamograf\u00edas de rutina&nbsp;no se empiecen hasta los 50 a\u00f1os.<\/p>\n<p>En todo caso, es importante que tu m\u00e9dico est\u00e9 al tanto de tus antecedentes familiares de c\u00e1ncer de mama, y que sigas sus indicaciones respecto a las mamograf\u00edas y\/o a otras pruebas. Pero nadie conoce tu cuerpo mejor que t\u00fa. Hazte un&nbsp;autoexamen&nbsp;una vez al mes para mantenerte alerta a cualquier n\u00f3dulo o alteraci\u00f3n que notes en tus senos, y buscar ayuda m\u00e9dica inmediata si notas alguna se\u00f1al o cualquier s\u00edntoma o cambio que te preocupe.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aunque seas joven, no pienses que eres inmune al c\u00e1ncer de mama. Durante los \u00faltimos 30 a\u00f1os, ha habido un aumento peque\u00f1o, pero sostenido, de c\u00e1ncer de mama metast\u00e1tico en mujeres de menos de 40 a\u00f1os (en &nbsp;los Estados Unidos). &nbsp;Y vale la pena investigar el asunto m\u00e1s a fondo.<\/p>\n","protected":false},"author":3,"featured_media":25081,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-25082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=25082"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/25081"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=25082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=25082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=25082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}