{"id":25418,"date":"2013-04-18T14:15:23","date_gmt":"2013-04-18T18:15:23","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/males-dermatologicos-presentes-en-los-jovenes\/"},"modified":"2013-04-18T14:15:23","modified_gmt":"2013-04-18T18:15:23","slug":"males-dermatologicos-presentes-en-los-jovenes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/males-dermatologicos-presentes-en-los-jovenes\/","title":{"rendered":"Males dermatol\u00f3gicos presentes en los j\u00f3venes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-25417\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_males_dermatologicos_en_los_jovenes.jpg\" width=\"191\" height=\"264\" alt=\"males_dermatologicos_en_los_jovenes\" class=\"caption\" style=\"float: left;\" \/>En la etapa juvenil la apariencia f\u00edsica es importante porque ayuda a desarrollar la autoestima en adolescentes y j\u00f3venes adultos. Esto incluye el buen estado de la piel, que es el \u00f3rgano m\u00e1s grande del cuerpo que puede afectarse por los cambios producidos en este per\u00edodo, y es la v\u00eda a trav\u00e9s de la cual se pueden contraer m\u00faltiples enfermedades. Es por esta raz\u00f3n que se debe iniciar su cuidado lo m\u00e1s temprano posible, para lucirla saludable.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Seg\u00fan Carmen Delia Marmolejos Frica, dermat\u00f3loga-cosmiatra del Instituto Dermatol\u00f3gico Dominicano y Cirug\u00eda de Piel Doctor Huberto Bogaert D\u00edaz,&nbsp; las enfermedades dermatol\u00f3gicas m\u00e1s frecuentes en los j\u00f3venes son el acn\u00e9, la dermatitis fotosensibilizante&nbsp; por exposici\u00f3n solar, las estr\u00edas, las manchas producidas por el sol, la escabiasis y la pitiriasis versicolor.<\/p>\n<p>Caracter\u00edsticas y tratamiento indicado<br \/>Seg\u00fan se establece en la Gu\u00eda de Dermatolog\u00eda Pedi\u00e1trica del autor Mario Maga\u00f1a Garc\u00eda, el acn\u00e9 es un padecimiento cr\u00f3nico, propio de la adolescencia, caracterizado por la presencia de lesiones que involucran el fol\u00edculo piloseb\u00e1ceo, que inician como comedones (llamados puntos negros) y originan p\u00e1pulas (elevaciones en la piel que al desaparecer no dejan cicatr\u00edz), p\u00fastulas y abscesos en la piel del rostro, pecho y espalda.<\/p>\n<p>La doctora Marmolejos explica que para el acn\u00e9 se pueden aplicar varios tratamientos dependiendo de su clasificaci\u00f3n, que pueden ser t\u00f3picos, t\u00f3picos combinados con los sist\u00e9micos (antibi\u00f3ticos), y en caso de que sea severo se implementan tratamientos sist\u00e9micos con retinoides orales. Tambi\u00e9n se utilizan filtros solares y jabones tipo syndet (suaves) que no contengan detergentes.<\/p>\n<p>La dermatitis fotosensibilizante se desarrolla espec\u00edficamente en \u00e1reas expuestas a la luz solar. Se manifiesta con el color rojo y descamaci\u00f3n en la piel, produciendo resequedad y mucha picaz\u00f3n al paciente. Para su eliminaci\u00f3n se utilizan lociones hidratantes y calmantes, jabones suaves y protectores solares. Tambi\u00e9n se recetan antihistam\u00ednicos orales, dependiendo del picor que tenga el paciente.<\/p>\n<p>En el caso de las estr\u00edas, estas se producen por el estiramiento de la piel sobre todo en personas que levantan pesas y mujeres embarazadas. El tratamiento consiste en la implementaci\u00f3n de t\u00f3picos combinados con las tecnolog\u00edas de \u201cpeeling\u201d qu\u00edmicos, microdermoabrasi\u00f3n, radiofrecuencia l\u00e1ser (procedimiento que no la elimina, pero ayuda a disimularlas) y la radiofrecuencia pixel, un aparato de \u00faltima&nbsp; tecnolog\u00eda disponible para toda la poblaci\u00f3n en el Instituto Dermatol\u00f3gico, el cual ha tenido buenos resultados, seg\u00fan afirma la doctora Marmolejos.<\/p>\n<p>La escabiasis, producida por \u00e1caros, presenta p\u00e1pulas escariadas en la piel del paciente ocasionando m\u00e1s picaz\u00f3n de noche que durante el d\u00eda. Se transmite por contacto directo, se localiza en sitios donde hay mucho hacinamiento y en personas que comparten ba\u00f1os, camas y ropas. En su tratamiento se utiliza antihistam\u00ednicos orales porque la picaz\u00f3n es muy fuerte. La pitiriasis versicolor, \u201cpa\u00f1o\u201d, es producida por hongos y requiere de tratamiento oral y t\u00f3pico.<\/p>\n<p>(+)<br \/>C\u00d3MO PREVENIR LAS ENFERMEDADES<br \/>Seg\u00fan la dermat\u00f3loga, para el acn\u00e9 no existe prevenci\u00f3n, debido a que no se puede iniciar ning\u00fan tratamiento antes de desarrollar la enfermedad. Lo m\u00e1s recomendable es que luego de su aparici\u00f3n, el paciente visite a un dermat\u00f3logo para evitar su progreso. Para prevenir la dermatitis fotosensibilizante debemos evitar la exposici\u00f3n solar en horario de diez de la ma\u00f1ana a tres de la tarde, ingerir suficiente l\u00edquido, usar ropas ligeras y aplicarnos protector solar cada dos horas.<\/p>\n<p>Las estr\u00edas se pueden evitar manteniendo un peso adecuado, una dieta balanceada con frutas y vegetales; en las actividades del gimnasio se debe evitar el levantamiento de pesas que sobrepasen la capacidad del organismo y en el caso de las mujeres embarazadas, estas deben usar lociones hidratantes antiestr\u00edas. Para impedir la presencia de pa\u00f1os, la piel se debe secar bien despu\u00e9s del ba\u00f1o, eliminar el sudor y no compartir las toallas con otras personas. La \u00fanica manera de evitar la escabiasis es mediante la higiene, utilizando ba\u00f1os limpios y el uso exclusivo de la ropa.<\/p>\n<p>La dermat\u00f3loga explica que durante el ciclo menstrual se produce una descarga hormonal, por esta raz\u00f3n algunas mujeres, incluyendo las embarazadas, presentan espinillas y otras lesiones en la piel, por lo que recomienda no exprimirse la lesi\u00f3n para evitar la proliferaci\u00f3n de manchas y el uso de crema antibi\u00f3ticos para el acn\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la etapa juvenil la apariencia f\u00edsica es importante porque ayuda a desarrollar la autoestima en adolescentes y j\u00f3venes adultos. Esto incluye el buen estado de la piel, que es el \u00f3rgano m\u00e1s grande del cuerpo que puede afectarse por los cambios producidos en este per\u00edodo, y es la v\u00eda a trav\u00e9s de la cual se pueden contraer m\u00faltiples enfermedades. Es por esta raz\u00f3n que se debe iniciar su cuidado lo m\u00e1s temprano posible, para lucirla saludable.<\/p>\n","protected":false},"author":3,"featured_media":25417,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-25418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=25418"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/25417"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=25418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=25418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=25418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}