{"id":25492,"date":"2013-04-22T14:27:56","date_gmt":"2013-04-22T18:27:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/estudio-revela-que-78-de-los-adolescentes-utilizan-celulares\/"},"modified":"2013-04-22T14:27:56","modified_gmt":"2013-04-22T18:27:56","slug":"estudio-revela-que-78-de-los-adolescentes-utilizan-celulares","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/estudio-revela-que-78-de-los-adolescentes-utilizan-celulares\/","title":{"rendered":"Estudio revela que 78% de los adolescentes utilizan celulares"},"content":{"rendered":"<p><hardreturn><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-25491\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_chicas_cel435432334y.jpg\" width=\"450\" height=\"450\" alt=\"chicas_cel435432334y\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_chicas_cel435432334y.jpg 450w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_chicas_cel435432334y-150x150.jpg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_chicas_cel435432334y-300x300.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_chicas_cel435432334y-120x120.jpg 120w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/>CHICAGO \u2014 De los&nbsp;<strong>j\u00f3venes<\/strong>&nbsp;de entre 12 y 17 a\u00f1os de edad, el 78% usan&nbsp;<strong>tel\u00e9fonos celulares<\/strong>y casi la mitad de esos aparatos tienen acceso a la internet, una cifra que tiende a crecer y que est\u00e1 cambiando la manera en que los j\u00f3venes se conectan a la red mundial.<\/hardreturn><\/p>\n<p>  <!--more-->  <\/p>\n<p>Una encuesta del&nbsp;<strong>Pew Internet &amp; American Life Project<\/strong>&nbsp;determin\u00f3 que uno de cada cuatro menores tienen acceso a la internet mayormente por tel\u00e9fono celular, una proporci\u00f3n que asciende a casi la mitad cuando se trata de propietarios de tel\u00e9fonos multiusos.<\/p>\n<p>En contraste, s\u00f3lo el 15% de los adultos dijeron que se conectan a la internet principalmente con sus tel\u00e9fonos m\u00f3viles.<\/p>\n<p>\u00abHoy en d\u00eda es parte de la vida cotidiana\u00bb, expres\u00f3 Donald Conkey, un estudiante de secundaria en Wilmette, al norte de Chicago, quien es un adolescente que tiene un tel\u00e9fono con acceso a internet. \u00abTodo el mundo est\u00e1 usando su tel\u00e9fono de la misma manera, y lo usan todo el tiempo\u00bb.<\/p>\n<p>Conkey y otros j\u00f3venes afirman que si se sumara todo el tiempo que se la pasan dando uso a sus tel\u00e9fonos celulares \u2014en aplicaciones, en b\u00fasqueda de cosas en internet, con mensajes de texto o bajando canciones y videos \u2014 ascender\u00eda por lo menos a un par de horas diarias.<\/p>\n<p>\u00abCuando se me olvida el tel\u00e9fono en casa, me siento desnudo\u00bb, dice Michael Weller, un estudiante de la escuela secundaria New Trier, donde estudia tambi\u00e9n Conkey. \u00abRealmente, necesito sentirme conectado todo el tiempo\u00bb.<\/p>\n<p>Seg\u00fan el&nbsp;<strong>estudio<\/strong>, ni\u00f1as adolescentes de entre 14 y 17 a\u00f1os son las que m\u00e1s usan su tel\u00e9fono celular para conectarse a internet. Y aunque los j\u00f3venes de menos recursos econ\u00f3micos siguen siendo los menos propensos a utilizar la red, los que contaban con tel\u00e9fonos usaban esa herramienta para conectarse.<\/p>\n<p>Ello implica que, a medida que esta generaci\u00f3n va madurando, las grandes corporaciones tendr\u00e1n que cambiar las estrategias de publicidad y mercadeo que utilizan, as\u00ed como las maneras en que los padres vigilan las comunicaciones de sus hijos.<\/p>\n<p>Actualmente ya existen&nbsp;<a href=\"http:\/\/www.eldiariony.com\/Negocios-tecnologia-aplicaciones-gratis-armas-de-doble-filo-facebook-instagram#.UXL6DUrAxT8\" target=\"_blank\">tel\u00e9fonos celulares<\/a>&nbsp;que les permiten a los padres bloquear ciertos contenidos. Las compa\u00f1\u00edas telef\u00f3nicas ofrecen servicios con los que \u00e9stos pueden ver la lista de textos que env\u00edan sus hijos. Y hay varias aplicaciones que les dan a los padres el control de los contenidos que ofrece un navegador de internet, aunque muchos expertos coinciden en que esas aplicaciones a veces pueden fallar.<\/p>\n<p>A pesar de todas esas herramientas, muchos expertos consideran que el monitoreo de los padres no es suficiente. Algunos son m\u00e1s estrictos, otros menos.<\/p>\n<p>\u00abHay como dos extremos: por un lado los que monitorean todo y bloquean una enorme cantidad de cosas, y los que se rinden y dicen &#8216;esto me cuesta demasiado trabajo\u00bb&#8217;, dice Mary Madden, una investigadora del Centro Pew que fue coautora del estudio.<\/p>\n<p>A\u00f1ade que muchos padres se niegan a quitarles&nbsp;<a href=\"http:\/\/www.eldiariony.com\/estudio-utilizar-celular-contagioso#.UXL6SErAxT8\" target=\"_blank\">los tel\u00e9fonos&nbsp;<\/a>a sus hijos porque quieren que los ni\u00f1os se mantengan en contacto con ellos.<\/p>\n<p>\u00abLos adultos todav\u00eda est\u00e1n tratando de ajustarse a las nuevas reglas, para s\u00ed mismos y para sus hijos\u00bb, coment\u00f3 Madden. \u00abSon tiempos dif\u00edciles para ser padre\u00bb.<\/p>\n<p>Y es particularmente dif\u00edcil decirles a sus hijos que no pueden tener un tel\u00e9fono celular, inclusive para ni\u00f1os en primaria, donde el artefacto tecnol\u00f3gico se ha convertido en un s\u00edmbolo de estatus.<\/p>\n<p><strong>Testimonios de padres<\/strong><\/p>\n<p>Sherry Budziak, una madre en Vernon Hills, Illinois, dice que su hija de 6 a\u00f1os tiene amiguitas que env\u00edan textos usando el iPod Touch, un artefacto que no tiene conexi\u00f3n telef\u00f3nica pero s\u00ed de internet.<\/p>\n<p>Ella no est\u00e1 dispuesta a permitir eso. Pero s\u00ed le autoriz\u00f3 a su hija de 11 a\u00f1os tener un&nbsp;<a href=\"http:\/\/www.eldiariony.com\/mensaje-texto-celulares-horas-contestar-estudio-conducta-usuarios-llamadas-centro-pew?nocache=1#.UXL5bErAxT8\" target=\"_blank\">iPhone<\/a>, para poder mantenerse en contacto. Budziak, quien trabaja en el sector tecnol\u00f3gico y sabe c\u00f3mo funciona un tel\u00e9fono celular multiusos, ajust\u00f3 el artefacto de tal manera que la hija puede hacer y recibir llamadas y textos, y utilizar los juegos que sus padres le bajen de la internet.<\/p>\n<p>\u00abEs decir, somos del tipo de padres m\u00e1s conservadores\u00bb, comenta Budziak.<\/p>\n<p>Budziak le dice a su hija, y a las amiguitas de ella, que el tel\u00e9fono es de la mam\u00e1, no de la hija. Ello significa que la madre y su esposo monitorean todos los textos y llamadas cuando lo desean.<\/p>\n<p>\u00bfSu hija se queja de tanta vigilancia?<\/p>\n<p>A veces, dice Budziak, pero \u00abella quiere tanto&nbsp;<a href=\"http:\/\/www.eldiariony.com\/smarthphones-duplicarian-presencia-en-america-latina#.UXL5k0rAxT8\" target=\"_blank\">tener un tel\u00e9fono&nbsp;<\/a>que no le importa. Tener un tel\u00e9fono con restricciones es mejor que no tener tel\u00e9fono\u00bb.<\/p>\n<p>Mark Tremayne, profesor de comunicaciones en la Universidad de Texas en Arlington, dice que \u00e9l y su esposa postergaron planes de comprarle un iPhone a su hijo hasta que cumpla los 13 a\u00f1os, lo cual ocurrir\u00e1 pronto. Dicen que monitorear\u00e1n los contenidos.<\/p>\n<p><a href=\"http:\/\/www.eldiariony.com\/estudio-revela-78-por-ciento-adolescentes-celular-telefonos-internet-acceso&amp;source=RSS#.UXVIyKIsu8B\">fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHICAGO \u2014 De los&nbsp;j\u00f3venes&nbsp;de entre 12 y 17 a\u00f1os de edad, el 78% usan&nbsp;tel\u00e9fonos celularesy casi la mitad de esos aparatos tienen acceso a la internet, una cifra que tiende a crecer y que est\u00e1 cambiando la manera en que los j\u00f3venes se conectan a la red mundial.<\/p>\n","protected":false},"author":3,"featured_media":25491,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-25492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=25492"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/25491"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=25492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=25492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=25492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}