{"id":25498,"date":"2013-04-22T14:47:57","date_gmt":"2013-04-22T18:47:57","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/vivir-sin-sexo-las-cuatro-razones-de-la-abstinencia-sexual\/"},"modified":"2013-04-22T14:47:57","modified_gmt":"2013-04-22T18:47:57","slug":"vivir-sin-sexo-las-cuatro-razones-de-la-abstinencia-sexual","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/vivir-sin-sexo-las-cuatro-razones-de-la-abstinencia-sexual\/","title":{"rendered":"Vivir sin sexo: las cuatro razones de la abstinencia sexual"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-25497\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_IMG_0000136947_W_00600_0.jpg\" width=\"600\" height=\"400\" alt=\"IMG_0000136947_W_00600_0\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_IMG_0000136947_W_00600_0.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_IMG_0000136947_W_00600_0-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Para algunos es una elecci\u00f3n; para otros una realidad dolorosa e inevitable. Eso s\u00ed, siempre es voluntaria. \u00bfQu\u00e9 hay detr\u00e1s de la falta total de relaciones sexuales? Pol\u00e9mico y cuestionado, ponemos el tema en debate. Cuentan los d\u00edas. Los meses. Los a\u00f1os\u2026 Para algunos es casi un orgullo manifestar p\u00fablicamente cu\u00e1nto tiempo hace que no tienen sexo. Para otros, como siempre, no tanto, y se convierte en un silencio pleno de dolor, tab\u00faes y verg\u00fcenza.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Si bien el dicho \u2013y los sex\u00f3logos- afirman que el sexo es salud, muchas personas viven en abstinencia. Lejos de noches de placer, caricias y juegos er\u00f3ticos, el celibato elegido tiene sus motivos. Repas\u00e9moslos.<\/p>\n<p>1-Las razones religiosas. En este \u00e1mbito hay diferentes causas. Por un lado, los religiosos y religiosas de la Iglesia Cat\u00f3lica Apost\u00f3lica Romana consagran su cuerpo a Cristo y realizan votos de castidad para toda la vida.<\/p>\n<p>Muchos creyentes, sobre todo los m\u00e1s j\u00f3venes, tambi\u00e9n se imponen el llegar v\u00edrgenes al matrimonio. Y otros, los m\u00e1s practicantes, optan por no mantener contacto \u00edntimo de ning\u00fan tipo durante la Cuaresma y hasta Semana Santa.<\/p>\n<p>2-La edad: la realidad de los adultos mayores. Los a\u00f1os, las diferentes enfermedades, la viudez\u2026 Son muchos los factores que le juegan en contra a este grupo y logran que se decida dejar de lado la vida sexual.<\/p>\n<p>3-Cuesti\u00f3n de salud. Los primeros meses del embarazo, luego del parto, durante algunos tratamientos espec\u00edficos o despu\u00e9s de determinadas cirug\u00edas, la abstinencia se origina en la recomendaci\u00f3n m\u00e9dica.<\/p>\n<p>En el caso de aquellos hombres que est\u00e1n bajo tratamiento por problemas de erecci\u00f3n, tanto los sex\u00f3logos como los andr\u00f3logos recomiendan no mantener contacto f\u00edsico para evitar que aumenten los niveles de estr\u00e9s y ansiedad, cosa que afectar\u00eda a\u00fan m\u00e1s la impotencia.<\/p>\n<p>4-Miedos y tab\u00faes. La educaci\u00f3n recibida, malas experiencias, inseguridades f\u00edsicas, ansiedad, miedo a mostrar el cuerpo o a demostrar desconocimiento entre las s\u00e1banas\u2026 Estos son, entre otros, algunos de los motivos que llevan a elegir a la abstinencia como modo de vida. Sin embargo, detr\u00e1s de esta aparente elecci\u00f3n consentida, se esconden temores profundos que pueden resolverse con terapia adecuada.<\/p>\n<p><strong>Asexualidad no es sin\u00f3nimo de castidad<\/strong><\/p>\n<p>A diferencia de la abstinencia elegida, la asexualidad se refiere a la falta o a la disminuci\u00f3n de atracci\u00f3n sexual, y la b\u00fasqueda de otros recursos para sostener la relaci\u00f3n de pareja. \u201cLas personas asexuadas consideran que no sufren ning\u00fan trastorno (deseo sexual hipoactivo o fobias sexuales). Por el contrario, se sienten saludables y aceptan la disminuci\u00f3n del deseo como una de las diferentes formas de identidad sexual\u201d, explica el doctor Walter Ghedin, m\u00e9dico psiquiatra y sex\u00f3logo. Y agrega: \u201cLa mayor\u00eda de los sujetos asexuados se sienten as\u00ed desde que empiezan a tener relaciones. Otros han pasado por un periodo de deseo m\u00e1s alto y luego vuelven a niveles bajos\u201d.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Para algunos es una elecci\u00f3n; para otros una realidad dolorosa e inevitable. Eso s\u00ed, siempre es voluntaria. \u00bfQu\u00e9 hay detr\u00e1s de la falta total de relaciones sexuales? Pol\u00e9mico y cuestionado, ponemos el tema en debate. Cuentan los d\u00edas. Los meses. Los a\u00f1os\u2026 Para algunos es casi un orgullo manifestar p\u00fablicamente cu\u00e1nto tiempo hace que no tienen sexo. Para otros, como siempre, no tanto, y se convierte en un silencio pleno de dolor, tab\u00faes y verg\u00fcenza.<\/p>\n","protected":false},"author":3,"featured_media":25497,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-25498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=25498"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/25497"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=25498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=25498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=25498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}