{"id":25749,"date":"2013-05-01T04:00:00","date_gmt":"2013-05-01T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ique-le-pasa-a-mi-cuerpo-cambios-fisicos-en-la-adolescencia\/"},"modified":"2013-05-01T04:00:00","modified_gmt":"2013-05-01T08:00:00","slug":"ique-le-pasa-a-mi-cuerpo-cambios-fisicos-en-la-adolescencia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ique-le-pasa-a-mi-cuerpo-cambios-fisicos-en-la-adolescencia\/","title":{"rendered":"\u201c\u00bfQu\u00e9 le pasa a mi cuerpo?\u201d Cambios f\u00edsicos en la adolescencia"},"content":{"rendered":"<p><em><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-25748\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_adolescencia-cambios4362.jpg\" width=\"225\" height=\"259\" alt=\"adolescencia-cambios4362\" class=\"caption\" style=\"float: left;\" \/>Durante la adolescencia, el cuerpo atraviesa por varios cambios para transitar el camino hacia la adultez. Un d\u00eda, tu cuerpo se sentir\u00e1 diferente y es probable que te sientas confundido(a) y te llene una sensaci\u00f3n de extra\u00f1eza. \u00bfQu\u00e9 le pasa a tu cuerpo? Aqu\u00ed te hablo de los cambios que ver\u00e1s f\u00edsicamente durante la adolescencia o pubertad.<\/em><\/p>\n<p>  <!--more-->  <\/p>\n<div><em><br \/><\/em><\/div>\n<div>\n<p>ntre saltar el lazo, jugar en el parque, correr con amiguitos, jugar a las mu\u00f1ecas, transcurre la infancia. De repente, puede ser que una ni\u00f1a se re\u00fana a jugar a la casita con sus amiguitas y \u00a1boom! Se da cuenta de que una de ellas no se ve igual. Algo le est\u00e1 creciendo en el pecho. Entonces, todas se miran para ver si a todas les pasa igual. Puede que s\u00ed, puede que no. Cada persona se desarrolla a diferente ritmo. Por eso, la primera regla de la adolescencia y sus cambios: \u00a1no te compares con otros! A esa ni\u00f1a de la que hablo, le est\u00e1n saliendo sus pechos, y a todas les suceder\u00e1 lo mismo en alg\u00fan momento empezando a los 9 a\u00f1os, que es cuando empiezan a desarrollarse aunque no lo notes hasta que tengas entre los 12 y los 18 a\u00f1os, que es cuando los senos se forman completamente.<\/p>\n<p>A los ni\u00f1os, de repente al ponerse el uniforme de f\u00fatbol y gritar en el partido, les podr\u00eda salir un \u201cgallo\u201d o sea, que la voz suena destemplada. Tambi\u00e9n podr\u00edan empezar a notar que el sudor huele m\u00e1s fuerte y que sus piernas y su cara se llenan de vellos. Tambi\u00e9n, puede ser que desarrollen m\u00e1s los m\u00fasculos o incluso, que engorden. Les pasa tanto a los chicos como a las chicas: la grasa los prepara para el cuerpo de la adultez, pero en algunos se nota m\u00e1s que en otros. Empiezan a ganar peso como parte de la pubertad y se preguntan por qu\u00e9 otros adolescentes en cambio, siguen flacos como un fideo.<\/p>\n<p>Repito, no te compares. Cada persona va a su ritmo y de acuerdo a su cuerpo. Por eso, m\u00e1s bien prep\u00e1rate para los cambios en ese cuerpo que ahora sentir\u00e1s como ajeno, pero que poco a poco ir\u00e1 logrando un equilibrio para dar paso a tu nuevo cuerpo, el de mujer o el de hombre. La adolescencia es una etapa llena de altibajos y nuevas sensaciones. Disfr\u00fatalos y ac\u00e9ptalos como parte del regalo de la vida.&nbsp; Presta atenci\u00f3n a lo que podr\u00edas ir notando en tu cuerpo:<\/p>\n<p><strong>Si eres ni\u00f1a:<\/strong><\/p>\n<ul>\n<li>La gl\u00e1ndula mamaria empieza a desarrollarse o a crecer alrededor de los 8 a\u00f1os. Sin embargo, s\u00f3lo hasta los 12 a\u00f1os se empiezan a notar los senos alcanzando su desarrollo total para cuando cumplas 18. Como dije, cada ni\u00f1a es diferente, as\u00ed que estas edades son promedios generalizados.<\/li>\n<li>El vello p\u00fabico, el vello en las axilas y en las piernas empieza a aparecer entre los 9 y 10 a\u00f1os y se desarrollan completamente entre los 13 y 14 a\u00f1os.<\/li>\n<li>La primera menstruaci\u00f3n (menarqu\u00eda) puede suceder tan r\u00e1pido como a los 10 a\u00f1os y tan tarde como a los 15. La edad promedio de la menstruaci\u00f3n es dos a\u00f1os despu\u00e9s del inicio del desarrollo de los senos y el vello p\u00fabico. La primera menstruaci\u00f3n es considerada como el evento \u201coficial\u201d de inicio de la pubertad.<\/li>\n<li>Las ni\u00f1as ven un aumento r\u00e1pido en su estatura entre los 9 y los14 a\u00f1os.<\/li>\n<\/ul>\n<p><strong>Si eres ni\u00f1o:<\/strong><\/p>\n<ul>\n<li>Los test\u00edculos y el escroto pueden empezar a crecer a los 9 a\u00f1os de edad y de inmediato el pene empieza a alargarse. Para cuando cumplas 16 o 17 a\u00f1os, ya tus genitales tendr\u00e1n el tama\u00f1o y la forma que te acompa\u00f1ar\u00e1n en tu adultez.<\/li>\n<li>El vello p\u00fabico, el vello en las axilas, en el pecho, en la cara&nbsp; y en las piernas empieza a aparecer a los 12 a\u00f1os y se desarrolla completamente entre los 15 y 16 a\u00f1os.<\/li>\n<li>En el caso de los ni\u00f1os, no existe un solo evento que marque el inicio de la pubertad, tal como sucede en las ni\u00f1as con la primera menstruaci\u00f3n. Lo que marca ese momento para los chicos es tener erecciones con eyaculaci\u00f3n durante la noche&nbsp; que, algunos le llaman, \u201csue\u00f1os h\u00famedos\u201d. Los sue\u00f1os h\u00famedos se presentan por primera vez entre los 13 y los 17 a\u00f1os de edad. Estos sue\u00f1os coinciden tambi\u00e9n con el mayor crecimiento en cuanto a la estatura en los varones.<\/li>\n<li>El cambio de voz se presenta simult\u00e1neamente con el crecimiento del pene.<\/li>\n<\/ul>\n<p>Recuerda que los cambios por los que pasa tu cuerpo durante la adolescencia dependen mucho de la gen\u00e9tica. Es decir, tu altura (estatura) y tu talla seguramente tendr\u00e1n mucho en com\u00fan con el cuerpo de tu mam\u00e1 y de tu pap\u00e1.<\/p>\n<p>Si tienes dudas o no te sientes en sinton\u00eda con tu cuerpo e incluso te sientes avergonzado(a) por los cambios que est\u00e1s experimentando, habla con tus padres que son quienes m\u00e1s te quieren y en quienes puedes confiar plenamente.<\/p>\n<p>Tambi\u00e9n recuerda que es importante que establezcas h\u00e1bitos sanos como una alimentaci\u00f3n saludable y alguna actividad f\u00edsica que te agrade y que puedas hacer regularmente (quiz\u00e1 alg\u00fan deporte, bailar o caminar) que te ayudar\u00e1n a sentirte bien tanto f\u00edsica, como emocionalmente.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante la adolescencia, el cuerpo atraviesa por varios cambios para transitar el camino hacia la adultez. Un d\u00eda, tu cuerpo se sentir\u00e1 diferente y es probable que te sientas confundido(a) y te llene una sensaci\u00f3n de extra\u00f1eza. \u00bfQu\u00e9 le pasa a tu cuerpo? Aqu\u00ed te hablo de los cambios que ver\u00e1s f\u00edsicamente durante la adolescencia o pubertad.<\/p>\n","protected":false},"author":3,"featured_media":25748,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-25749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=25749"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/25749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/25748"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=25749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=25749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=25749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}