{"id":26040,"date":"2013-05-07T18:47:10","date_gmt":"2013-05-07T22:47:10","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-embajador-de-estados-unidos-dejara-republica-dominicana-finales-de-mes\/"},"modified":"2013-05-07T18:47:10","modified_gmt":"2013-05-07T22:47:10","slug":"el-embajador-de-estados-unidos-dejara-republica-dominicana-finales-de-mes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-embajador-de-estados-unidos-dejara-republica-dominicana-finales-de-mes\/","title":{"rendered":"El embajador de Estados Unidos dejar\u00e1 Rep\u00fablica Dominicana finales de mes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-26039\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_raul_h_yzaguirre.jpg\" width=\"400\" height=\"500\" alt=\"raul_h_yzaguirre\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_raul_h_yzaguirre.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_raul_h_yzaguirre-240x300.jpg 240w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Tras casi tres a\u00f1os de representar a los Estados Unidos en la Rep\u00fablica Dominicana, el embajador Ra\u00fal Yzaguirre present\u00f3 su renuncia y se retirar\u00e1 del pa\u00eds al finalizar este mes.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p><strong>Ayer Yzaguirre inform\u00f3 al ministro de Relaciones Exteriores, Carlos Morales Troncoso, que present\u00f3 la renuncia a su cargo, por cuestiones de salud, y regresar\u00e1 a su hogar en la ciudad de Mt. Airy, estado de Maryland, junto a su esposa.<\/strong><\/p>\n<p><strong>Dijo que parte del pa\u00eds complacido de que la relaci\u00f3n bilateral contin\u00faa prosperando a medida que los Estados Unidos y la Rep\u00fablica Dominicana trabajan lado a lado para avanzar las metas compartidas en varios sectores.<\/strong><\/p>\n<p>\u201cMe siento complacido de haber tenido el privilegio de representar al presidente Barack Obama como jefe de la embajada de los Estados Unidos, en un pa\u00eds que ha demostrado una hospitalidad incondicional\u201d, manifest\u00f3 el diplom\u00e1tico.<\/p>\n<p>Tras su renuncia, el actual ministro Consejero de la misi\u00f3n diplom\u00e1tica, Daniel L. Foote, asumir\u00e1 la posici\u00f3n de embajador en Santo Domingo hasta que llegue un sustituto.<\/p>\n<p>Yzaguirre present\u00f3 al entonces presidente Leonel Fern\u00e1ndez su carta credencial el 18 de noviembre de 2010. El diplom\u00e1tico ha tenido diversos puestos y nombramientos a lo largo de su carrera, pero es m\u00e1s conocido por su liderazgo, entre 1978 y 2004 al frente al Consejo Nacional de la Raza (NCLR, sigla en ingl\u00e9s), una de las principales organizaciones de la comunidad hispana en Estados Unidos. Es oriundo de San Juan, Texas, pero tiene su hogar en la ciudad de Mt. Airy, Maryland.<\/p>\n<p><strong>Por Dominga Ram\u00edrez Garc\u00eda<\/strong>&nbsp;publicado en&nbsp;<a href=\"http:\/\/eldia.com.do\/nacionales\/2013\/5\/6\/113641\/Yzaguirre-concluye-su-mision-diplomatica-RD\" target=\"_blank\">El D\u00eda<\/a><\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tras casi tres a\u00f1os de representar a los Estados Unidos en la Rep\u00fablica Dominicana, el embajador Ra\u00fal Yzaguirre present\u00f3 su renuncia y se retirar\u00e1 del pa\u00eds al finalizar este mes.<\/p>\n","protected":false},"author":3,"featured_media":26039,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-26040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26040"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26039"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}