{"id":26054,"date":"2013-05-08T04:00:00","date_gmt":"2013-05-08T08:00:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/facebook-estudia-la-felicidad-de-la-gente-segun-el-estado-de-su-situacion-sentimental\/"},"modified":"2013-05-08T04:00:00","modified_gmt":"2013-05-08T08:00:00","slug":"facebook-estudia-la-felicidad-de-la-gente-segun-el-estado-de-su-situacion-sentimental","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/facebook-estudia-la-felicidad-de-la-gente-segun-el-estado-de-su-situacion-sentimental\/","title":{"rendered":"Facebook estudia la felicidad de la gente seg\u00fan el estado de su situaci\u00f3n sentimental"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-26053\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_facebook-estudio-relaciones_sentimentales.png\" width=\"520\" height=\"350\" alt=\"facebook-estudio-relaciones_sentimentales\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_facebook-estudio-relaciones_sentimentales.png 520w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_facebook-estudio-relaciones_sentimentales-300x201.png 300w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/>Facebook, ha realizado un estudio para descubrir qu\u00e9 tipo de relaci\u00f3n hace a sus usuarios m\u00e1s felices. Y diferenciando entre sexo y tipo de relaci\u00f3n el estudio ha revelado datos sorprendentes como que las mujeres son m\u00e1s felices en una relaci\u00f3n abierta o que los hombres, en general, se sienten mejor estando casados que comprometidos.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<div>Para medir la felicidad de los usuarios de Facebook se considera cu\u00e1ntas personas utilizan palabras positivas en sus actualizaciones de estado. Este m\u00e9todo permite ver si el estado sentimental de una persona afecta a su positividad o y negatividad.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Las personas que est\u00e1n en una relaci\u00f3n o casados parecen ser m\u00e1s felices&nbsp;que aquellos que no lo est\u00e1n. Y dentro de este grupo aquellos que est\u00e1n en una relaci\u00f3n parecen menos felices en comparaci\u00f3n con los casados. Las personas casadas, sin embargo, tienden a tener mayor edad que los solteros y seg\u00fan &nbsp;Facebook, los resultados de otros estudios apuntan a que con la edad, la personas tienden a ser m\u00e1s felices.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Estar en una relaci\u00f3n abierta parece ser un verdadero problema, y la positividad mostrada entre las personas con esta condici\u00f3n es incluso m\u00e1s baja que la de las personas que incluyen a s\u00ed mismos como viudos\/as o \u201cen una relaci\u00f3n complicada\u201d y mucho peor que estar soltero. Las personas viudas, en cambio, muestran menos emociones en general, ya sean positivas o negativas.<\/div>\n<div><\/div>\n<div><\/div>\n<div>Los hombres son menos felices en las relaciones&nbsp;abiertas que las mujeres, lo cual tiene sentido teniendo en cuenta que las mujeres son m\u00e1s propensas a informar de una relaci\u00f3n abierta (40%) que los hombres. Los hombres son m\u00e1s positivas que las mujeres cuando se encuentran inmersos en una relaci\u00f3n estable o un matrimonio, pero son m\u00e1s negativos cuando est\u00e1n comprometidos o casados.<\/div>\n<div><\/div>\n<div><\/div>\n<div>El estudio tambi\u00e9n destaca el hecho de que la gente que no revela su estado civil&nbsp;o sentimental suelen ser un 50% m\u00e1s negativos que el resto. Alrededor del 30% de las mujeres y el 40% de los hombres en Facebook se describen como solteros.<\/div>\n<div><\/div>\n<div><b><i>Fuente:&nbsp;<\/i><\/b>Actualidad.orange.es<\/div>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Facebook, ha realizado un estudio para descubrir qu\u00e9 tipo de relaci\u00f3n hace a sus usuarios m\u00e1s felices. Y diferenciando entre sexo y tipo de relaci\u00f3n el estudio ha revelado datos sorprendentes como que las mujeres son m\u00e1s felices en una relaci\u00f3n abierta o que los hombres, en general, se sienten mejor estando casados que comprometidos.<\/p>\n","protected":false},"author":3,"featured_media":26053,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-26054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26054"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26054\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26053"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}