{"id":26076,"date":"2013-05-08T13:39:05","date_gmt":"2013-05-08T17:39:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/ipor-que-un-avion-no-esta-hecho-del-mismo-material-que-su-caja-negra-2\/"},"modified":"2013-05-08T13:39:05","modified_gmt":"2013-05-08T17:39:05","slug":"ipor-que-un-avion-no-esta-hecho-del-mismo-material-que-su-caja-negra-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ipor-que-un-avion-no-esta-hecho-del-mismo-material-que-su-caja-negra-2\/","title":{"rendered":"\u00bfPor qu\u00e9 un avi\u00f3n no esta hecho del mismo material que su caja negra?"},"content":{"rendered":"<p><em><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-26071\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_caja_negra-.jpg\" width=\"293\" height=\"240\" alt=\"caja_negra-\" title=\"Caja Negra\" class=\"caption\" \/>Si las \u201ccajas negras\u201d empleadas por los aviones para registrar las conversaciones en cabina y los datos de vuelo son tan indestructibles \u00bfpor qu\u00e9 no pueden hacer todo el avi\u00f3n con el mismo material? T\u00edpica pregunta que siempre hacen aquellos que no estan muy metidos en esto de la aviaci\u00f3n, pero debes aceptar que mas de alguna vez te lo preguntaste .<\/em><\/p>\n<p>  <!--more-->  <\/p>\n<h2>La caja negra<\/h2>\n<h3><\/h3>\n<div id=\"attachment_2343\">Cuando hay accidentes de aviones, las autoridades siempre salen en busca de la caja negra, la cual tiene garantizada su supervivencia sin importar lo aparatoso del accidente\u2026 Si estas son indestructibles \u00bfpor qu\u00e9 no hacen todo el avi\u00f3n del mismo material\u2026 y qu\u00e9 decir de los barcos, los carros y los edificios? As\u00ed todos estar\u00edamos m\u00e1s a salvo seg\u00fan el pensar de la gente.<\/div>\n<p>Las cajas negras, que en realidad son amarillas, rojas o naranja fosforescente, son la principal fuente de informaci\u00f3n para determinar la causa de un accidente. Por lo general son dos, una cumple la funci\u00f3n de grabar las voces en la cabina y la otra la informaci\u00f3n del vuelo. Cada caja cuesta alrededor de $15.000 y la raz\u00f3n por la que sobreviven al impacto de una colisi\u00f3n, es porque est\u00e1n hechas con algunos de los materiales m\u00e1s fuertes y pesados de la Tierra.<\/p>\n<p>Las cajas negras son otra historia. Su coraza est\u00e1 hecha de acero antigolpes, antifuego y antiagua, que de acuerdo con las especificaciones de la Administraci\u00f3n Federal de Aeron\u00e1utica de EE.UU., debe soportar la presi\u00f3n del agua a 6000 metros de profundidad durante 30 d\u00edas y sin oxidarse; resistir 3400 gravedades o lo que es igual, resistir viajar a 650 kil\u00f3metros por hora y pararse en seco en medio metro; aguantar temperaturas de al menos 1100\u00b0 C (m\u00e1s alta que la de la lava) durante treinta minutos; y tener un transmisor de radio que haga posible su localizaci\u00f3n. A\u00fan despu\u00e9s de todo esto las cajas negras usualmente funcionan por a\u00f1os.<\/p>\n<p>En el interior se encuentra el dispositivo de grabaci\u00f3n. Est\u00e1 montado en un molde, el cual est\u00e1 dentro de otra caja, a su vez cubierta por una armadura de acero y titanio. Los modelos m\u00e1s recientes son del tama\u00f1o de un&nbsp;<em>six pack<\/em>de cerveza y pesan unos 20 kilos. Si esto no es suficiente para aclarar tu pregunta, hagamos un experimento para ilustrar.<\/p>\n<div id=\"attachment_2339\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-26074\" title=\"fligh_recorder\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/elaviadorsv.net_wp-content_uploads_2013_03_fligh_recorder.jpg\" alt=\"\" width=\"515\" height=\"355\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/elaviadorsv.net_wp-content_uploads_2013_03_fligh_recorder.jpg 635w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/elaviadorsv.net_wp-content_uploads_2013_03_fligh_recorder-300x206.jpg 300w\" sizes=\"auto, (max-width: 515px) 100vw, 515px\" \/> <\/p>\n<p>Flight Recorder<\/p>\n<\/p><\/div>\n<h2><\/h2>\n<h2>\u00bfPor que no hacen el avi\u00f3n del mismo material?<\/h2>\n<p>La primera raz\u00f3n es econ\u00f3mica, las cajas negras est\u00e1n hechas de titano y acero inoxidable, lo cual har\u00eda al avi\u00f3n mucho m\u00e1s caro y los precios de los vuelos se disparar\u00edan. Imag\u00ednense tener que pagar algo as\u00ed como $20,000 por un vuelo de 1 hora. Dudo que mucha gente lo hiciera.<\/p>\n<p>La segunda es el peso del avi\u00f3n, debido al blindaje que lleva la caja negra, el peso del avi\u00f3n se quintuplicar\u00eda, lo cual requerir\u00eda pistas m\u00e1s largas y sobre todo, m\u00e1s duras. Si un avi\u00f3n cinco veces m\u00e1s pesado aterrizara en una pista actual probablemente destruir\u00eda el concreto de la pista, y aunque existiera alguna, la cantidad de gasolina necesaria para lograr hacerlo volar ser\u00eda equivalente a la que utiliza un transbordador espacial.<\/p>\n<p>El tercero se relaciona directamente con las leyes de Newton, particularmente la primera que dice: \u201cTodo cuerpo tiende a mantener su estado de reposo o movimiento mientras no se le aplique una fuerza externa para cambiarlo de estado\u201d. En el caso de que un avi\u00f3n indestructible choque con la tierra, el cuerpo del avi\u00f3n absorber\u00eda muy poco del impacto y la fuerza ser\u00eda trasladada al interior, en el que los tripulantes ser\u00edan sacudidos de un lado a otro de la misma forma que un pollito se ver\u00eda en una licuadora. Los aviones actuales tienen algo parecido a los coches, en el que algunas partes est\u00e1n dise\u00f1adas espec\u00edficamente para absorber un impacto, sin \u00e9stas un choque ser\u00eda a\u00fan m\u00e1s peligroso.<\/p>\n<p>La \u00faltima y m\u00e1s contundente es que un avi\u00f3n no est\u00e1 dise\u00f1ado para chocar, con la m\u00ednima cantidad de accidentes fatales que tienen los aviones, las compa\u00f1\u00edas a\u00e9reas se concentran en otras modificaciones como hacer los aviones m\u00e1s livianos para disminuir los costos, lo cual, a la larga benefician m\u00e1s a los millones de viajeros que todos los a\u00f1os llegan sanos y salvos a sus destinos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si las \u201ccajas negras\u201d empleadas por los aviones para registrar las conversaciones en cabina y los datos de vuelo son tan indestructibles \u00bfpor qu\u00e9 no pueden hacer todo el avi\u00f3n con el mismo material? T\u00edpica pregunta que siempre hacen aquellos que no estan muy metidos en esto de la aviaci\u00f3n, pero debes aceptar que mas de alguna vez te lo preguntaste .<\/p>\n","protected":false},"author":3,"featured_media":26072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[323],"tags":[],"class_list":["post-26076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-c82-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26076"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26072"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}