{"id":26117,"date":"2013-05-10T04:31:10","date_gmt":"2013-05-10T08:31:10","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/autoridades-reconocen-auge-prostitucion-en-sosua-advierten-no-permitiran-incentivo-de-esa-practica\/"},"modified":"2013-05-10T04:31:10","modified_gmt":"2013-05-10T08:31:10","slug":"autoridades-reconocen-auge-prostitucion-en-sosua-advierten-no-permitiran-incentivo-de-esa-practica","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/autoridades-reconocen-auge-prostitucion-en-sosua-advierten-no-permitiran-incentivo-de-esa-practica\/","title":{"rendered":"Autoridades reconocen auge prostituci\u00f3n en Sos\u00faa; advierten no permitir\u00e1n incentivo de esa practica"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-26115\" alt=\"Bahia_de_sosua_2013\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Bahia_de_sosua_2013.jpg\" width=\"640\" height=\"350\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Bahia_de_sosua_2013.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Bahia_de_sosua_2013-300x164.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Bahia_de_sosua_2013-400x220.jpg 400w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/>Tras reconocer que en los \u00faltimos tiempos la prostituci\u00f3n se ha convertido en un creciente mal social en el municipio de Sos\u00faa, el director provincial de Turismo; Lorenzo Sancassani, dijo que es prioridad de todas las autoridades frenar el auge de este mal y de otros que, como el narcotr\u00e1fico, afectan la tranquilidad de ese lugar y el auge del turismo.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Sancassani admiti\u00f3 que algunos propietarios de negocios han estado incentivando la prostituci\u00f3n como una forma de mantener sus establecimientos funcionando, sin embargo, dijo que no son justificables esas acciones y que no ser\u00e1n permitidas bajo ninguna circunstancia.<\/p>\n<p>El funcionario de turismo manifest\u00f3 que junto a la comunidad, se toman todas las medidas necesarias para devolver a la comunidad y a sus visitantes la tranquilidad, apoyando las iniciativas y a los empresarios que s\u00ed quieren tener un comercio l\u00edcito.<\/p>\n<p>Expres\u00f3 que desde que asumi\u00f3 sus funciones ha realizando reuniones con el nuevo comandante policial de la jurisdicci\u00f3n y el director de la Polic\u00eda Tur\u00edstica (POLITUR) a fin de trazar planes de acci\u00f3n que frenen el problema de la prostituci\u00f3n.<\/p>\n<p>\u201cEl Ministerio de Turismo y la Procuradur\u00eda General de la Rep\u00fablica, est\u00e1n coordinando acciones para controlar este problema y garantizar un ambiente donde podamos retomar el turismo interno y familiar\u201d,apunt\u00f3 Sancassani.<\/p>\n<p>Dijo que han iniciado las negociaciones para desarrollar la playa de Sos\u00faa y se enfocan en el proyecto del Parque Marino, que se hab\u00eda quedado estancado adem\u00e1s de dar especial atenci\u00f3n a la industria de buceo en la bah\u00eda de Sos\u00faa.<\/p>\n<div>Sancassani indic\u00f3 que coordina varias acciones con la Politur, la Procuradur\u00eda Fiscal de Puerto Plata y la Polic\u00eda Nacional para garantizar la seguridad de los habitantes y turistas de toda la costa Norte, adem\u00e1s, cit\u00f3 los trabajos de organizaci\u00f3n y reubicaci\u00f3n de los vendedores y la rotulaci\u00f3n de los taxistas para evitar los taxistas piratas, el desorden y la delincuencia.<\/div>\n<div>&nbsp;<\/div>\n<div>[<a href=\"http:\/\/www.puertoplatadigital.com\/verNoticia.aspx?Id=12733\">Fuente<\/a>]<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tras reconocer que en los \u00faltimos tiempos la prostituci\u00f3n se ha convertido en un creciente mal social en el municipio de Sos\u00faa, el director provincial de Turismo; Lorenzo Sancassani, dijo que es prioridad de todas las autoridades frenar el auge de este mal y de otros que, como el narcotr\u00e1fico, afectan la tranquilidad de ese lugar y el auge del turismo.<\/p>\n","protected":false},"author":3,"featured_media":26115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-26117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26117"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26115"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}