{"id":26165,"date":"2013-05-10T19:04:12","date_gmt":"2013-05-10T23:04:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/padre-de-jenny-rivera-le-dice-sujeto-prieto-maldito-y-desgraciado-a-tony-dandrades\/"},"modified":"2013-05-10T19:04:12","modified_gmt":"2013-05-10T23:04:12","slug":"padre-de-jenny-rivera-le-dice-sujeto-prieto-maldito-y-desgraciado-a-tony-dandrades","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/padre-de-jenny-rivera-le-dice-sujeto-prieto-maldito-y-desgraciado-a-tony-dandrades\/","title":{"rendered":"Padre de Jenny Rivera, le dice sujeto prieto, maldito y desgraciado a Tony Dandrades"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-26163\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Tony-Dandrades.jpg\" width=\"580\" height=\"300\" alt=\"Tony-Dandrades\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Tony-Dandrades.jpg 580w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Tony-Dandrades-300x155.jpg 300w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/>Nuestro reportero dominicano de \u201cPrimer Impacto\u201d Tony Dandrades, fue acusado por el padre de la fenecida Jenny Rivera, de aprovecharse de la confianza de Don Pedro Rivera de dejarlo entrar en su casa y salir a divulgar otras cosas.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div><strong>\u201cCon toda la confianza del mundo llevo un prieto a mi casa, le ense\u00f1o donde dorm\u00eda Jenny, como vivimos, y este desgraciado en lugar de decir una cosa bien hecha, por la confianza que le di de llevarlo a mi casa, dijo: Pedro Rivera en la ruina, y sus hijos gozando de gran fortuna\u201d, fueron las palabras ofrecidas por parte de Don Pedro.<\/strong><\/div>\n<div>\n<p>Adem\u00e1s coment\u00f3 que es una cobard\u00eda por parte de Dandrades , quien porque por subir el rating le van echar la tierra encima a una familia.<\/p>\n<p>\u201cEse maldito con eso caus\u00f3 una controversia muy grande en mi familia y eso no se debe de hacer \u201c, concluy\u00f3 diciendo Pedro Rivera.<\/p>\n<p>Tony, por su parte en su cuenta de Twitter public\u00f3 lo siguiente:<\/p>\n<p><strong>@tdandrades : Espero que Don Pedro R. les haya contado bien la historia! \u00e9l fue quien me mostro las condiciones en las que viv\u00eda! para la c\u00e1mara no miente.<\/strong><\/p>\n<p>seguido de otro twetts :<\/p>\n<p><strong>@tdandrades : El fue se\u00f1or Rivera quien me invit\u00f3 a ver las condiciones en las que viv\u00eda! No le perdono sus comentarios racistas sobre persona.<\/strong><\/p>\n<p><strong>Por Thelma Figueroa Amador @thelmafigueroa<\/strong><\/p>\n<\/p><\/div>\n<div><strong><br \/><\/strong><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nuestro reportero dominicano de \u201cPrimer Impacto\u201d Tony Dandrades, fue acusado por el padre de la fenecida Jenny Rivera, de aprovecharse de la confianza de Don Pedro Rivera de dejarlo entrar en su casa y salir a divulgar otras cosas.<\/p>\n","protected":false},"author":3,"featured_media":26163,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-26165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26165"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26165\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26163"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}