{"id":26235,"date":"2013-05-12T14:15:55","date_gmt":"2013-05-12T18:15:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/icomezon-vaginal-ique-puede-ser\/"},"modified":"2013-05-12T14:15:55","modified_gmt":"2013-05-12T18:15:55","slug":"icomezon-vaginal-ique-puede-ser","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/icomezon-vaginal-ique-puede-ser\/","title":{"rendered":"\u00bfComez\u00f3n vaginal? \u00bfQu\u00e9 puede ser?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-26233\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_comezon_vaginal_2-.jpg\" width=\"600\" height=\"400\" alt=\"comezon_vaginal_2-\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_comezon_vaginal_2-.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_comezon_vaginal_2--300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>Frecuente a lo largo de la vida de una mujer, la comez\u00f3n vaginal genera en quienes la padecen una sensaci\u00f3n de incomodidad e inseguridad, ya que su ubicaci\u00f3n limita la posibilidad de encontrar alivio a trav\u00e9s de rascar la zona. Conocida tambi\u00e9n como prurito vaginal, es una picaz\u00f3n o irritaci\u00f3n que se presenta en la piel de la vagina y en \u00e1reas circundantes; esto de acuerdo con informaci\u00f3n de los Institutos Nacionales de Salud (NIH) en Estados Unidos.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>ara la ginec\u00f3loga y obstetra Kenneth Loaiciga Vega, la comez\u00f3n vaginal se puede producir por las siguientes causas:<\/p>\n<p>1. Vulvovaginitis. Es la inflamaci\u00f3n de la regi\u00f3n genital femenina: vulva, vagina y cuello uterino. Es muy frecuente, present\u00e1ndose hasta en el 25% de las mujeres que acuden a la consulta por un problema ginecol\u00f3gico.<\/p>\n<p>2. Irritantes. Productos como los jabones, detergentes, duchas vaginales y los productos de ba\u00f1o perfumados pueden causar irritaci\u00f3n local.<\/p>\n<p>3. Al\u00e9rgica. Se puede desarrollar una reacci\u00f3n al\u00e9rgica en la piel provocada por condones de l\u00e1tex, esmalte de u\u00f1as, perfumes, toallitas para beb\u00e9, papel higi\u00e9nico perfumado.<\/p>\n<p>4. Herpes. Es el estadio inicial de la enfermedad el prurito es el primer s\u00edntoma en aparecer. Se acompa\u00f1a de una particular sensaci\u00f3n de quemaz\u00f3n seguida dentro de las primeras 12 a 24 horas de ardor y dolor.<\/p>\n<p>5. Diabetes. Alto nivel de az\u00facar en sangre, en los diab\u00e9ticos, se asocia con alteraciones inmunol\u00f3gicas, causando una mayor susceptibilidad y frecuencia de infecciones.<\/p>\n<p>Algunas alternativas para prevenir o tratar la comez\u00f3n vaginal son las siguientes:<\/p>\n<p>1. Eliminaci\u00f3n o minimizaci\u00f3n de los factores causales.<\/p>\n<p>2. Antibi\u00f3ticos para infecciones vaginales bacterianas, incluyen infecciones de transmisi\u00f3n sexual.<\/p>\n<p>Si sufres de prurito o de otra molestia es preferible que acudas con un especialista, ya que \u00e9ste es el m\u00e1s indicado para hacer un diagn\u00f3stico. Recuerda que lo m\u00e1s importante es tu salud.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Frecuente a lo largo de la vida de una mujer, la comez\u00f3n vaginal genera en quienes la padecen una sensaci\u00f3n de incomodidad e inseguridad, ya que su ubicaci\u00f3n limita la posibilidad de encontrar alivio a trav\u00e9s de rascar la zona. Conocida tambi\u00e9n como prurito vaginal, es una picaz\u00f3n o irritaci\u00f3n que se presenta en la piel de la vagina y en \u00e1reas circundantes; esto de acuerdo con informaci\u00f3n de los Institutos Nacionales de Salud (NIH) en Estados Unidos.<\/p>\n","protected":false},"author":3,"featured_media":26233,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-26235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26235"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26233"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}