{"id":26257,"date":"2013-05-13T16:55:37","date_gmt":"2013-05-13T20:55:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/marvel-y-los-salarios-ivolveran-todos-sus-actores-para-the-avengers-2\/"},"modified":"2013-05-13T16:55:37","modified_gmt":"2013-05-13T20:55:37","slug":"marvel-y-los-salarios-ivolveran-todos-sus-actores-para-the-avengers-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/marvel-y-los-salarios-ivolveran-todos-sus-actores-para-the-avengers-2\/","title":{"rendered":"Marvel y los salarios: \u00bfVolver\u00e1n todos sus actores para \u2018The Avengers 2\u2019?"},"content":{"rendered":"<p itemprop=\"articleBody\"><em><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-26255\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_The-Avengers-2-300x167.jpg\" width=\"300\" height=\"167\" alt=\"The-Avengers-2-300x167\" class=\"caption\" style=\"float: left;\" \/>The Avengers<\/em>&nbsp;se convirti\u00f3 en 2012,&nbsp;<strong>con m\u00e1s de US$1,500 millones,<\/strong>&nbsp;en la tercera pel\u00edcula de mayor recaudaci\u00f3n de la historia, pero el estudio&nbsp;Marvel&nbsp;no tiene la seguridad de que sus actores, incluido&nbsp;Robert Downey Jr.,&nbsp;<strong>vayan a regresar al rodaje de la segunda parte por cuestiones econ\u00f3micas.<\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p itemprop=\"articleBody\">Downey Jr., cuyo contrato con el estudio ha concluido, es la principal preocupaci\u00f3n, seg\u00fan reporta&nbsp;EFE.<\/p>\n<p itemprop=\"articleBody\">El actor&nbsp;<strong>gan\u00f3 m\u00e1s de US$50 millones<\/strong>&nbsp;por&nbsp;<em>The Avengers<\/em>\u2013seg\u00fan&nbsp;<em>Deadline<\/em>, en realidad podr\u00edan ser hasta 80 millones\u2013, una cifra similar a la que va a llevarse tras&nbsp;el \u00e9xito de&nbsp;<em>Iron Man 3<\/em>, que acabar\u00e1 con ingresos superiores a los US$1,000 millones de d\u00f3lares.<\/p>\n<p itemprop=\"articleBody\">\u201c\u00bfNo es una locura? Est\u00e1n muy molestos\u201d, dijo Downey Jr. acerca de los ejecutivos de Marvel en una entrevista con la revista&nbsp;<em>GQ<\/em>. \u201cSoy lo que se conoce como un coste estrat\u00e9gico\u201d, agreg\u00f3.<\/p>\n<p itemprop=\"articleBody\"><strong>EL&nbsp;CONTRATO<\/strong><br \/>Tras la buena acogida del primer&nbsp;<em>Iron Man<\/em>, el int\u00e9rprete logr\u00f3 incluir nuevas cl\u00e1usulas en su contrato con Marvel, productora del filme propiedad de Disney, para llevarse un porcentaje de&nbsp;<strong>entre un 5% y un 7%<\/strong>&nbsp;de los ingresos que generaran las pel\u00edculas en las que diera vida a ese personaje en el futuro.<\/p>\n<p itemprop=\"articleBody\">\u201cNo s\u00e9 qu\u00e9 pasar\u00e1. Tuve un largo contrato con ellos y ahora vamos a renegociarlo\u201d, coment\u00f3 el actor en el programa de Jon Stewart.<\/p>\n<p itemprop=\"articleBody\">Seg\u00fan&nbsp;<em>The Hollywood Reporter<\/em>, Downey Jr. y el estudio se sentaron a hablar en una cena para poner las bases de un nuevo contrato que ligue a ambas partes para rodar la segunda y la tercera parte de&nbsp;<em>The Avengers<\/em>. Sin embargo,&nbsp;<strong>nada se sabe<\/strong>&nbsp;en torno a&nbsp;una posible cuarta entrega&nbsp;de&nbsp;<em>Iron Man<\/em>.<\/p>\n<p itemprop=\"articleBody\">En cualquier caso, todo parece indicar que el estudio<strong>aceptar\u00e1 las pretensiones del actor m\u00e1s valorado dentro de la franquicia.<\/strong>&nbsp;Un ejemplo del valor de Downey Jr. es que&nbsp;<em>Iron Man 2<\/em>&nbsp;consigui\u00f3 un 39% por ciento m\u00e1s de ingresos en taquilla que&nbsp;<em>Thor<\/em>&nbsp;y un 69% m\u00e1s que&nbsp;<em>Captain America<\/em>.<\/p>\n<p itemprop=\"articleBody\">El analista Doug Creutz, de la empresa Cowen and Co., dijo que perder a Downey Jr. supondr\u00eda un terrible golpe para Marvel. \u201c\u00c9l es Tony Stark (el alter ego de Iron Man).<strong>Las otras sagas no tienen el mismo potencial.<\/strong>&nbsp;Sin \u00e9l, esa franquicia posiblemente rendir\u00eda al nivel que las dem\u00e1s de Marvel\u201d, sostuvo.<\/p>\n<p itemprop=\"articleBody\"><strong>\u00bfY&nbsp;LOS&nbsp;OTROS&nbsp;\u2018VENGADORES\u2019?<\/strong><br \/>El panorama es m\u00e1s sombr\u00edo para los dem\u00e1s actores de<em>The Avengers<\/em>.&nbsp;<em>Deadline<\/em>&nbsp;asegura que, mientras Downey Jr. recib\u00eda esas estratosf\u00e9ricas cifras, otros miembros del reparto percibieron \u00fanicamente US$200,000 como sueldo base, sin contar extras por los ingresos finales.<\/p>\n<p itemprop=\"articleBody\">Ahora, nombres como Chris Evans (<em>Captain America<\/em>),Chris Hemsworth&nbsp;(<em>Thor<\/em>), Mark Ruffalo (<em>Hulk<\/em>) o Jeremy Renner (<em>Hawkeye<\/em>), buscar\u00e1n obtener un cheque de unos US$5 millones de d\u00f3lares, algo que no ha sentado bien al estudio.<br \/>Scarlett Johansson&nbsp;y Samuel L. Jackson, actores de mayor calibre,&nbsp;<strong>firmaron salarios en torno a los US$6 millones.<\/strong><\/p>\n<p itemprop=\"articleBody\">Seg\u00fan la publicaci\u00f3n, Marvel habr\u00eda amenazado con romper algunos de esos contratos menores y&nbsp;<strong>escoger a otros actores que aceptasen esos papeles por menos dinero,<\/strong>&nbsp;si bien Downey Jr. est\u00e1 luchando por que se respeten los salarios que piden sus compa\u00f1eros.<\/p>\n<p itemprop=\"articleBody\">El estudio ha demostrado en el pasado que no le tiembla el pulso.<\/p>\n<p itemprop=\"articleBody\">El papel de \u2018Hulk\u2019 lo han interpretado hasta ahora tres actores (Eric Bana, Edward Norton y Ruffalo). Don Cheadle sustituy\u00f3 a Terrence Howard en el papel de Rhodey en&nbsp;<em>Iron Man 2<\/em>&nbsp;y Zachary Levi tomar\u00e1 el relevo de Josh Dallas como Fandral en&nbsp;<em>Thor: The Dark World<\/em>, en este caso por un conflicto en la agenda del actor.<\/p>\n<p itemprop=\"articleBody\">De acuerdo a Estrenos21, la segunda parte de&nbsp;<em>The Avengers<\/em>, cuyo rodaje est\u00e1 previsto para febrero de 2014, se espera que llegue a los cines el 1 de mayo de 2015, mientras que la tercera entrega probablemente lo har\u00e1 en 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The Avengers&nbsp;se convirti\u00f3 en 2012,&nbsp;con m\u00e1s de US$1,500 millones,&nbsp;en la tercera pel\u00edcula de mayor recaudaci\u00f3n de la historia, pero el estudio&nbsp;Marvel&nbsp;no tiene la seguridad de que sus actores, incluido&nbsp;Robert Downey Jr.,&nbsp;vayan a regresar al rodaje de la segunda parte por cuestiones econ\u00f3micas.<\/p>\n","protected":false},"author":3,"featured_media":26255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-26257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26257"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26255"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}