{"id":26318,"date":"2013-05-14T18:31:46","date_gmt":"2013-05-14T22:31:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/dominicana-audris-rijo-pasa-a-la-final-de-nuestra-belleza-latina\/"},"modified":"2013-05-14T18:31:46","modified_gmt":"2013-05-14T22:31:46","slug":"dominicana-audris-rijo-pasa-a-la-final-de-nuestra-belleza-latina","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dominicana-audris-rijo-pasa-a-la-final-de-nuestra-belleza-latina\/","title":{"rendered":"Dominicana Audris Rijo pasa a la final de Nuestra Belleza Latina"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-26317\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Audris-Rijo-fotos-.jpg\" width=\"475\" height=\"595\" alt=\"Audris-Rijo-fotos-\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Audris-Rijo-fotos-.jpg 475w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Audris-Rijo-fotos--239x300.jpg 239w\" sizes=\"auto, (max-width: 475px) 100vw, 475px\" \/>La competencia en el Reality Show, Nuestra Belleza Latina, llega a su final el pr\u00f3ximo domingo 19 de mayo. Y la dominicana Audris Rijo logr\u00f3 superar, de nuevo esta gran prueba, pasar a la gran final venciendo todos los obst\u00e1culos con elegancia, tal como lo expresara Juli\u00e1n Gil; \u201cT\u00fa tienes la corona puesta ,yo creo que hoy est\u00e1s lista para ser lo que t\u00fa quieras, siempre dije que yo iba a tratar de convertirte en una mejor mujer, en una l\u00edder, y en una chica que se pueda desarrollar en el mundo del entretenimiento y sabes que yo creo que tu hoy est\u00e1s lista para hacer lo que t\u00fa quieras. T\u00fa sabes c\u00f3mo se dice eso en Rep\u00fablica Dominicana PLATANO POWER\u201d.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Es la recta final, no hay ma\u00f1ana, y por ello este domingo 19 de mayo a partir de las 9:00pm, Con Jatnna trae, adem\u00e1s de la final, una entrega especial de Nuestra Belleza Latina. Y Jatnna Tav\u00e1rez se traslada a la ciudad de Miami para estar presente en la gran noche y de esta manera dar apoyo a nuestra representante. Audris, ahora y durante toda esta semana, necesita, el apoyo y la buena vibra del pueblo dominicano, quien tiene todo el deseo y espera que la hermosa trigue\u00f1a nos d\u00e9 nuestra primera corona en el m\u00e1s importante reality de la belleza en Latinoam\u00e9rica.<\/p>\n<p>En la pasada gala, se generaron muchas expectativas cuando la criolla fue escogida en el \u00faltimo turno, es decir fue la quinta finalista seleccionada, lo que imprime m\u00e1s emoci\u00f3n a su participaci\u00f3n y a las posibilidades de ser la ganadora.<\/p>\n<p>En el pa\u00eds hay una gran atenci\u00f3n con nuestra Audris Rijo, ya que ella tiene la gran oportunidad de darnos la primera corona para la Rep\u00fablica Dominicana en esta s\u00e9ptima edici\u00f3n del reality.<\/p>\n<p>Audris ha sido una de las participantes con mejor desempe\u00f1o y su carisma se demuestra en la aceptaci\u00f3n y ovaci\u00f3n del p\u00fablico cada vez que act\u00faa o aparece en el escenario. Pero su mayor logro es el equilibrio entre humildad y liderazgo, junto a la seguridad y confianza que demuestra y c\u00f3mo se maneja frente a las c\u00e1maras.<\/p>\n<p>Adem\u00e1s de los televidentes que siguen el reality a trav\u00e9s de Con Jatnna, la familia de Audris est\u00e1 muy atenta el desarrollo del show y el domingo pasado aprovecharon para enviar mensajes de motivaci\u00f3n a la joven participante, manifestarle su apoyo y hablar de c\u00f3mo ha sido para ellos toda esta bonita experiencia.<\/p>\n<p><iframe loading=\"lazy\" width=\"498\" height=\"374\" src=\"http:\/\/www.youtube.com\/embed\/olpKEWQIM-Y?rel=0\" frameborder=\"0\" allowfullscreen=\"\"><\/iframe><\/p>\n<p>La gran final de Nuestra belleza Latina ser\u00e1 transmitida en horario especial de las 9:00pm por Color Visi\u00f3n.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La competencia en el Reality Show, Nuestra Belleza Latina, llega a su final el pr\u00f3ximo domingo 19 de mayo. Y la dominicana Audris Rijo logr\u00f3 superar, de nuevo esta gran prueba, pasar a la gran final venciendo todos los obst\u00e1culos con elegancia, tal como lo expresara Juli\u00e1n Gil; \u201cT\u00fa tienes la corona puesta ,yo creo que hoy est\u00e1s lista para ser lo que t\u00fa quieras, siempre dije que yo iba a tratar de convertirte en una mejor mujer, en una l\u00edder, y en una chica que se pueda desarrollar en el mundo del entretenimiento y sabes que yo creo que tu hoy est\u00e1s lista para hacer lo que t\u00fa quieras. T\u00fa sabes c\u00f3mo se dice eso en Rep\u00fablica Dominicana PLATANO POWER\u201d.<\/p>\n","protected":false},"author":3,"featured_media":26317,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-26318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26318"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26317"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}