{"id":26452,"date":"2013-05-18T13:31:00","date_gmt":"2013-05-18T17:31:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/buscando-detener-la-delincuencia-el-gobierno-crea-el-consejo-nacional-de-seguridad-ciudadana\/"},"modified":"2013-05-18T13:31:00","modified_gmt":"2013-05-18T17:31:00","slug":"buscando-detener-la-delincuencia-el-gobierno-crea-el-consejo-nacional-de-seguridad-ciudadana","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/buscando-detener-la-delincuencia-el-gobierno-crea-el-consejo-nacional-de-seguridad-ciudadana\/","title":{"rendered":"Buscando detener la delincuencia El Gobierno crea El Consejo Nacional de Seguridad Ciudadana"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-26451\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_709_palacio_nacional.jpg\" width=\"400\" height=\"249\" alt=\"709_palacio_nacional\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_709_palacio_nacional.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_709_palacio_nacional-300x186.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Santo Domingo. El Presidente Danilo Medina cre\u00f3 el Consejo Nacional de Seguridad Ciudadana, con el objetivo de coordinar, de manera directa, las acciones derivadas del Plan Nacional de Seguridad Ciudadana e integrar a las diferentes instituciones que participan de esta iniciativa.<\/p>\n<p>  <!--more-->  <\/p>\n<div><\/div>\n<div>\n<p>Mediante el Decreto No. 119-13, qued\u00f3 constituido el nuevo Consejo encabezado por el primer mandatario, e integrado por los ministros de la Presidencia, de Interior y Polic\u00eda, quien lo coordina, y de las Fuerzas Armadas. Adem\u00e1s, el Procurador General de la Rep\u00fablica, el Jefe de la Polic\u00eda Nacional, el presidente del Consejo Nacional de Drogas, el Director Nacional de Control de Drogas y el Asesor del Poder Ejecutivo para el Programa de Luchas contra el Narcotr\u00e1fico.<\/p>\n<p><strong>El Ministro de la Presidencia, Gustavo Montalvo, record\u00f3 que el objetivo del gobierno es garantizar que todas las acciones incluidas se lleven a cabo en tiempo y forma, y que el Consejo reci\u00e9n creado sirve a ese objetivo, porque garantiza la coordinaci\u00f3n interinstitucional a todos los niveles, al propiciar el di\u00e1logo permanente con la sociedad civil y la medici\u00f3n de resultados.<\/strong><\/p>\n<p>El Consejo Nacional de Seguridad Ciudadana ser\u00e1 el encargado de dirigir el Observatorio de Seguridad Ciudadana. En este sentido, el Ministro Montalvo manifest\u00f3 que \u201ca partir de los datos que se obtengan del observatorio, el Consejo se encargar\u00e1 de planificar, producir, coordinar y evaluar las acciones necesarias para el combate a la criminalidad y la violencia\u201d.<\/p>\n<p>De acuerdo con el art\u00edculo 3 del decreto, el Consejo Nacional de Seguridad Ciudadana se reunir\u00e1 de manera ordinaria trimestralmente y de forma extraordinaria por convocatoria del Presidente de la Rep\u00fablica.<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo. El Presidente Danilo Medina cre\u00f3 el Consejo Nacional de Seguridad Ciudadana, con el objetivo de coordinar, de manera directa, las acciones derivadas del Plan Nacional de Seguridad Ciudadana e integrar a las diferentes instituciones que participan de esta iniciativa.<\/p>\n","protected":false},"author":3,"featured_media":26451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-26452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26452"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26451"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}