{"id":26701,"date":"2013-05-25T23:09:33","date_gmt":"2013-05-26T03:09:33","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/el-origen-del-microfono-2\/"},"modified":"2013-05-25T23:09:33","modified_gmt":"2013-05-26T03:09:33","slug":"el-origen-del-microfono-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/el-origen-del-microfono-2\/","title":{"rendered":"El origen del micr\u00f3fono"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-26696\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_El-micrfono-origen.jpg\" width=\"255\" height=\"198\" alt=\"El-micrfono-origen\" class=\"caption\" style=\"float: left;\" \/>El micr\u00f3fono es un transductor electroac\u00fastico. Su funci\u00f3n es la de traducir las vibraciones debidas a la presi\u00f3n ac\u00fastica ejercida sobre su c\u00e1psula por las ondas sonoras en energ\u00eda el\u00e9ctrica, lo que permite por ejemplo grabar sonidos de cualquier lugar o elemento.<\/p>\n<p>  <!--more-->  <\/p>\n<p>En 1827,&nbsp;<strong>Charles Wheatstone<\/strong>&nbsp;utiliz\u00f3 por primera vez la palabra \u201cmicr\u00f3fono\u201d para describir un dispositivo ac\u00fastico dise\u00f1ado para amplificar sonidos d\u00e9biles. Procede de los vocablos griegos \u201cmicr\u00f3fono\u201d (peque\u00f1o) y \u201cphon\u201d (sonido)<\/p>\n<p>E<strong>l primer micr\u00f3fono formaba parte del Fon\u00f3grafo, el dispositivo m\u00e1s com\u00fan para reproducir sonido grabado desde la d\u00e9cada de 1870 hasta la d\u00e9cada de 1880<\/strong>&nbsp;y donde precisamente comenz\u00f3 la historia del micr\u00f3fono y las grabaciones de audio. Fue conocido como el primer \u201cmicr\u00f3fono din\u00e1mico\u201d.<\/p>\n<p>En 1876, Alexander Graham Bell, simult\u00e1neamente con Elisha Gray, registraron una patente del \u201ctel\u00e9grafo hablado\u201d (el primer tel\u00e9fono). Por primera vez se incluye el micr\u00f3fono funcional que usa un electroim\u00e1n.<\/p>\n<p>En 1877, David Edward Hughes dise\u00f1\u00f3 una nueva clase de micr\u00f3fono, el micr\u00f3fono de \u201ccontacto suelto\u201d o \u201ccarb\u00f3n\u201d, un dise\u00f1o no magn\u00e9tico basado en part\u00edculas conductoras de carb\u00f3n embalados libremente en una respuesta incluida a la presi\u00f3n que variaba de un diafragma de los sonidos, la resistencia el\u00e9ctrica a trav\u00e9s de los gr\u00e1nulos del carb\u00f3n cambiantes proporcional como las que tienen los tel\u00e9fonos.<\/p>\n<p>El paso importante siguiente en dise\u00f1o del transmisor estaba por Henry Hunnings de Inglaterra. \u00c9l utiliz\u00f3 los gr\u00e1nulos del coque entre el diafragma y un metal detr\u00e1s platee.<\/p>\n<p>En 1878 , es dise\u00f1ado el primer micr\u00f3fono de bobina m\u00f3vil. Este dise\u00f1o fue patentado en 1879.<\/p>\n<p>En 1917, presentan el primer micr\u00f3fono de condensador pr\u00e1ctico y moderno.<\/p>\n<p>En 1920, lleg\u00f3 en la era comercial de la difusi\u00f3n. Algunos de los aficionados y de los cantantes bien informados comenzaron a jugar recursos y a usar los micr\u00f3fonos con sus programas. La estaci\u00f3n de radio temprana utiliz\u00f3 el tel\u00e9fono del candlestick para un micr\u00f3fono.<\/p>\n<p>El paso siguiente era proveer de los actores un micr\u00f3fono que permitir\u00eda que estuvieran parados y que se realizaran. Para este uso el constructor tom\u00f3 el transmisor del tel\u00e9fono del candlestick, substituy\u00f3 la boquilla corta por el meg\u00e1fono y resbal\u00f3 esta combinaci\u00f3n dentro de una manga alineada fieltro de la baquelita cerca de ocho pulgadas de largo y puso pernos de argolla peque\u00f1os en cada extremo para suspenderlo de arriba.<\/p>\n<p>El primer micr\u00f3fono, que hizo para la industria de la pel\u00edcula era el PB17. Era a sandblasted el cilindro de aluminio, 17 pulgadas de largo y el fondo del The de 6 pulgadas de di\u00e1metro fue redondeado con un yugo para llevar a cabo el elemento de la cinta, que ten\u00eda una pantalla perforada protectora. La estructura magn\u00e9tica utiliz\u00f3 un electroim\u00e1n que requer\u00eda seis voltios en un amperio.<\/p>\n<p>En 1931 Western Electric presenta el primer micr\u00f3fono din\u00e1mico: el modelo 600, serie 618. Tambi\u00e9n en 1931, la marca RCA presenta el primer micr\u00f3fono de cinta bidireccional: 44\u00aa de im\u00e1n permanente. En 1947, se funda AKG en Viena.<\/p>\n<p>En 1948, Neumann lanza el micr\u00f3fono a v\u00e1lvulas U47, el primer micr\u00f3fono de condensador con patr\u00f3n conmutable entre cardioide y omnidireccional. Acab\u00f3 convirti\u00e9ndose en todo un cl\u00e1sico para grabar voces desde que se supo que Frank Sinatra se negaba a cantar sin su U47.<\/p>\n<p>Desde 1920 hasta la actualidad se ha ido innovando en tecnolog\u00edas hasta lograr dividir el micr\u00f3fono en 2 tipos, los din\u00e1micos y los condensadores.<\/p>\n<p><a href=\"http:\/\/www.culturizando.com\/2013\/05\/el-origen-de-un-invento-el-microfono.html\" target=\"_blank\">Fuente<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El micr\u00f3fono es un transductor electroac\u00fastico. Su funci\u00f3n es la de traducir las vibraciones debidas a la presi\u00f3n ac\u00fastica ejercida sobre su c\u00e1psula por las ondas sonoras en energ\u00eda el\u00e9ctrica, lo que permite por ejemplo grabar sonidos de cualquier lugar o elemento.<\/p>\n","protected":false},"author":3,"featured_media":26696,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-26701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26701"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26696"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}