{"id":26731,"date":"2013-05-25T16:13:00","date_gmt":"2013-05-25T20:13:00","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/leonel-fernandez-salio-en-coche-fiscalia-tumba-querella-de-corrupcion-en-su-contra-2\/"},"modified":"2013-05-25T16:13:00","modified_gmt":"2013-05-25T20:13:00","slug":"leonel-fernandez-salio-en-coche-fiscalia-tumba-querella-de-corrupcion-en-su-contra-2","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/leonel-fernandez-salio-en-coche-fiscalia-tumba-querella-de-corrupcion-en-su-contra-2\/","title":{"rendered":"Leonel Fern\u00e1ndez \u201csali\u00f3 en coche\u201d Fiscal\u00eda tumba querella de corrupci\u00f3n en su contra"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" alignleft size-full wp-image-26727\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Leonel-Fernndez-sali-el-coche-300x179.jpg\" width=\"300\" height=\"179\" alt=\"Leonel-Fernndez-sali-el-coche-300x179\" class=\"caption\" style=\"float: left;\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Leonel-Fernndez-sali-el-coche-300x179.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/05\/sosua_images_Leonel-Fernndez-sali-el-coche-300x179-500x300.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>La Fiscal\u00eda del Distrito Nacional archiv\u00f3 de manera definitiva la querella presentada por el presidente del Partido Alianza Pa\u00eds, Guillermo Moreno, en contra del expresidente Leonel Fern\u00e1ndez Reyna y la Fundaci\u00f3n Global Democracia y Desarrollo (Funglode), por presuntos actos de corrupci\u00f3n.<\/p>\n<p>  <!--more-->  <\/p>\n<p>De inmediato, Moreno calific\u00f3 de irresponsable la decisi\u00f3n de la fiscal del Distrito Nacional, Yeni Berenice Reynoso, y dijo que recurrir\u00e1 en apelaci\u00f3n la decisi\u00f3n, tras agregar que hay leyes, pero que faltan fiscales para enfrentar la corrupci\u00f3n.<\/p>\n<p>\u201cCon esta decisi\u00f3n se est\u00e1 estimulando la corrupci\u00f3n, y de no haber ley, como dice la fiscal, para castigar la corrupci\u00f3n, entonces el pa\u00eds hay que cerrarlo\u201d, dijo.<\/p>\n<p>En su auto de archivo definitivo, la Fiscal\u00eda se\u00f1al\u00f3 \u201cque la falta de tipificaci\u00f3n de las acciones impide que el ministerio p\u00fablico pueda actuar y hace de las diligencias de investigaci\u00f3n propuestas por el querellante un proyecto fracasado\u201d.<\/p>\n<p>Argumenta que la Fiscal\u00eda del Distrito est\u00e1 convencida, en base a los criterios jur\u00eddicos expresados, que por la deficiencia del sistema legislativo dominicano no es posible imputar determinadas conductas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda del Distrito Nacional archiv\u00f3 de manera definitiva la querella presentada por el presidente del Partido Alianza Pa\u00eds, Guillermo Moreno, en contra del expresidente Leonel Fern\u00e1ndez Reyna y la Fundaci\u00f3n Global Democracia y Desarrollo (Funglode), por presuntos actos de corrupci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":26727,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[76],"tags":[],"class_list":["post-26731","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=26731"}],"version-history":[{"count":0,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/26731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/26727"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=26731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=26731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=26731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}